{"id":47817,"date":"2023-11-20T01:35:54","date_gmt":"2024-03-07T19:28:19","guid":{"rendered":"https:\/\/www.silicloud.com\/zh\/blog\/%e9%80%9a%e8%bf%87%e4%bd%bf%e7%94%a8apollo%e5%92%8cprisma%e6%9d%a5%e5%85%a5%e9%97%a8graphql%e3%80%82\/"},"modified":"2024-05-04T09:54:25","modified_gmt":"2024-05-04T01:54:25","slug":"%e9%80%9a%e8%bf%87%e4%bd%bf%e7%94%a8apollo%e5%92%8cprisma%e6%9d%a5%e5%85%a5%e9%97%a8graphql%e3%80%82","status":"publish","type":"post","link":"https:\/\/www.silicloud.com\/zh\/blog\/%e9%80%9a%e8%bf%87%e4%bd%bf%e7%94%a8apollo%e5%92%8cprisma%e6%9d%a5%e5%85%a5%e9%97%a8graphql%e3%80%82\/","title":{"rendered":"\u901a\u8fc7\u4f7f\u7528Apollo\u548cPrisma\u6765\u5165\u95e8GraphQL"},"content":{"rendered":"<p>\u8fd9\u7bc7\u6587\u7ae0\u662fHamee Advent Calendar 2019\u7b2c21\u5929\u7684\u6587\u7ae0\u3002<\/p>\n<p>\u6700\u8fd1\uff0c\u6211\u5728\u5b9e\u73b0\u67d0\u4e2a\u7ba1\u7406\u754c\u9762\u4e4b\u540e\u610f\u8bc6\u5230\u5e94\u8be5\u4f7f\u7528GraphQL\u8fdb\u884c\u5b9e\u73b0\u3002\u8fd9\u8ba9\u6211\u91cd\u65b0\u5bf9GraphQL\u4ea7\u751f\u4e86\u5174\u8da3\uff0c\u56e0\u6b64\u6211\u51b3\u5b9a\u5c1d\u8bd5\u4e00\u4e0b\u3002\u4e8e\u662f\uff0c\u6211\u771f\u7684\u53bb\u5b9e\u8df5\u4e86\u4e00\u4e0b\u3002<\/p>\n<p>\u672c\u6765\u6211\u8ba1\u5212\u521b\u5efa\u4e00\u4e2a\u7b80\u5355\u7684Todo\u5e94\u7528\uff0c\u4f46\u6700\u7ec8\u53ea\u6574\u7406\u4e86\u4e00\u4e0bGraphQL\u670d\u52a1\u5668\u7684\u63a5\u89e6\u611f\u89c9\u3002<\/p>\n<p>t-yng\/graphql-todo-app\u7684\u4e2d\u6587\u91ca\u4e49\u662f\u4ec0\u4e48\u5462\uff1f<\/p>\n<p>\u53ea\u9700\u8981\u4e00\u4e2a\u7b54\u6848\uff1a<br \/>\nt-yng\/graphql-todo-app \u662f\u4e00\u4e2a\u57fa\u4e8eGraphQL\u7684\u5f85\u529e\u4e8b\u9879\u5e94\u7528\u3002<\/p>\n<h2>\u56fe\u4e66\u9986\u4ecb\u7ecd<\/h2>\n<p>apollographql\/apollo-server: GraphQL\u30b5\u30fc\u30d0\u30fc<\/p>\n<p>\u5b9f\u969b\u306bGraphQL\u306e\u30ea\u30af\u30a8\u30b9\u30c8\u3092\u53d7\u3051\u4ed8\u3051\u3066\u30c7\u30fc\u30bf\u3092\u8fd4\u3059\u30b5\u30fc\u30d0\u30fc<br \/>\n\u3053\u306e\u8a18\u4e8b\u3067\u306f\u30e9\u30c3\u30d7\u3055\u308c\u305f apollo-server-express \u3092\u5229\u7528\u3057\u3066\u3044\u304d\u307e\u3059\u3002<\/p>\n<p>prisma\/prisma: ORM<\/p>\n<p>GraphQL\u30b5\u30fc\u30d0\u30fc\u3068\u30c7\u30fc\u30bf\u30d9\u30fc\u30b9\u3092\u7e4b\u3050ORM<br \/>\nprisma\u81ea\u4f53\u306f\u30e9\u30a4\u30d6\u30e9\u30ea\u3067\u306f\u306a\u304fCLI\u30c4\u30fc\u30eb<\/p>\n<h2>\u9879\u76ee\u7684\u5efa\u7acb<\/h2>\n<pre class=\"post-pre\"><code>$ yarn init -y\r\n$ yarn add typescript\r\n$ yarn add -D ts-node\r\n$ yarn tsc --init\r\n<\/code><\/pre>\n<h2>\u5b89\u88c5 Apollo Server<\/h2>\n<pre class=\"post-pre\"><code>$ yarn add apollo-server-express express @types\/express\r\n<\/code><\/pre>\n<h2>\u4f60\u597d\uff0c\u4e16\u754c\u3002<\/h2>\n<h3>\u5b9e\u65bd<\/h3>\n<pre class=\"post-pre\"><code>$ mkdir src\r\n$ touch src\/index.ts\r\n<\/code><\/pre>\n<pre class=\"post-pre\"><code>\r\n<span class=\"k\">import<\/span> <span class=\"nx\">express<\/span> <span class=\"k\">from<\/span> <span class=\"dl\">'<\/span><span class=\"s1\">express<\/span><span class=\"dl\">'<\/span><span class=\"p\">;<\/span>\r\n<span class=\"k\">import<\/span> <span class=\"p\">{<\/span> <span class=\"nx\">ApolloServer<\/span><span class=\"p\">,<\/span> <span class=\"nx\">gql<\/span> <span class=\"p\">}<\/span> <span class=\"k\">from<\/span> <span class=\"dl\">'<\/span><span class=\"s1\">apollo-server-express<\/span><span class=\"dl\">'<\/span><span class=\"p\">;<\/span>\r\n\r\n<span class=\"kd\">const<\/span> <span class=\"nx\">typeDefs<\/span> <span class=\"o\">=<\/span> <span class=\"nx\">gql<\/span><span class=\"s2\">`\r\n    type Query {\r\n        hello: String\r\n    }\r\n`<\/span><span class=\"p\">;<\/span>\r\n\r\n<span class=\"kd\">const<\/span> <span class=\"nx\">resolvers<\/span> <span class=\"o\">=<\/span> <span class=\"p\">{<\/span>\r\n    <span class=\"na\">Query<\/span><span class=\"p\">:<\/span> <span class=\"p\">{<\/span>\r\n        <span class=\"na\">hello<\/span><span class=\"p\">:<\/span> <span class=\"p\">()<\/span> <span class=\"o\">=&gt;<\/span> <span class=\"dl\">'<\/span><span class=\"s1\">Hello GrapQL!<\/span><span class=\"dl\">'<\/span><span class=\"p\">,<\/span>\r\n    <span class=\"p\">},<\/span>\r\n<span class=\"p\">};<\/span>\r\n\r\n<span class=\"kd\">const<\/span> <span class=\"nx\">server<\/span> <span class=\"o\">=<\/span> <span class=\"k\">new<\/span> <span class=\"nx\">ApolloServer<\/span><span class=\"p\">(<\/span> <span class=\"p\">{<\/span> <span class=\"nx\">typeDefs<\/span><span class=\"p\">,<\/span> <span class=\"nx\">resolvers<\/span> <span class=\"p\">});<\/span>\r\n\r\n<span class=\"kd\">const<\/span> <span class=\"nx\">app<\/span> <span class=\"o\">=<\/span> <span class=\"nx\">express<\/span><span class=\"p\">();<\/span>\r\n<span class=\"nx\">server<\/span><span class=\"p\">.<\/span><span class=\"nx\">applyMiddleware<\/span><span class=\"p\">({<\/span> <span class=\"nx\">app<\/span> <span class=\"p\">});<\/span>\r\n\r\n<span class=\"nx\">app<\/span><span class=\"p\">.<\/span><span class=\"nx\">listen<\/span><span class=\"p\">({<\/span> <span class=\"na\">port<\/span><span class=\"p\">:<\/span> <span class=\"mi\">4000<\/span> <span class=\"p\">},<\/span> <span class=\"p\">()<\/span> <span class=\"o\">=&gt;<\/span> <span class=\"p\">{<\/span>\r\n    <span class=\"nx\">console<\/span><span class=\"p\">.<\/span><span class=\"nx\">log<\/span><span class=\"p\">(<\/span><span class=\"s2\">`? Server ready at http:\/\/localhost:4000<\/span><span class=\"p\">${<\/span><span class=\"nx\">server<\/span><span class=\"p\">.<\/span><span class=\"nx\">graphqlPath<\/span><span class=\"p\">}<\/span><span class=\"s2\">`<\/span><span class=\"p\">);<\/span>\r\n<span class=\"p\">});<\/span>\r\n<\/code><\/pre>\n<h3>\u6267\u884c<\/h3>\n<p>\u5728package.json\u4e2d\u6dfb\u52a0\u6267\u884c\u811a\u672c\u5e76\u6267\u884c\u3002<\/p>\n<pre class=\"post-pre\"><code>  <span class=\"nl\">\"scripts\"<\/span><span class=\"p\">:<\/span> <span class=\"p\">{<\/span>\r\n    <span class=\"nl\">\"dev\"<\/span><span class=\"p\">:<\/span> <span class=\"s2\">\"ts-node src\/index.ts\"<\/span>\r\n  <span class=\"p\">}<\/span>\r\n<\/code><\/pre>\n<pre class=\"post-pre\"><code><span class=\"nv\">$ <\/span>yarn dev\r\n<\/code><\/pre>\n<p>\u5982\u679c\u8bbf\u95ee http:\/\/localhost:4000\/graphql \u5e76\u6267\u884c\u4ee5\u4e0b\u67e5\u8be2\uff0c\u5c06\u8fd4\u56de\u7ed3\u679c\u3002<\/p>\n<pre class=\"post-pre\"><code><span class=\"k\">query<\/span> <span class=\"p\">{<\/span>\r\n  <span class=\"n\">hello<\/span>\r\n<span class=\"p\">}<\/span>\r\n<\/code><\/pre>\n<h2>\u5c1d\u8bd5\u5b9e\u73b0GraphQL\u63a5\u53e3<\/h2>\n<p>\u7136\u540e\uff0c\u6211\u5c06\u5c1d\u8bd5\u81ea\u5df1\u5b9e\u73b0\u4e00\u4e2a\u83b7\u53d6\u7b80\u5355To-do\u7684GraphQL\u67e5\u8be2\u3002<\/p>\n<h3>\u5b9a\u4e49\u6a21\u5f0f<\/h3>\n<p>\u6211\u4f1a\u5199\u4e0bTodo\u5bf9\u8c61\u7684\u7c7b\u578b\u5b9a\u4e49\u4ee5\u53ca\u83b7\u53d6\u5b83\u7684\u67e5\u8be2\u7684\u7c7b\u578b\u5b9a\u4e49\u3002<br \/>\n\u203b \u4e0d\u786e\u5b9a&#8221;\u7c7b\u578b\u5b9a\u4e49&#8221;\u8fd9\u4e2a\u8bf4\u6cd5\u662f\u5426\u6b63\u786e\u3002<\/p>\n<pre class=\"post-pre\"><code><span class=\"kd\">const<\/span> <span class=\"nx\">typeDefs<\/span> <span class=\"o\">=<\/span> <span class=\"nx\">gql<\/span><span class=\"s2\">`\r\n    type Todo {\r\n        id: Int!\r\n        title: String\r\n    }\r\n\r\n    type Query {\r\n        todo(id: Int): Todo\r\n        todoes(title: String): [Todo]\r\n    }\r\n`<\/span><span class=\"p\">;<\/span>\r\n<\/code><\/pre>\n<h3>\u5b9e\u73b0\u89e3\u6790\u5668<\/h3>\n<p>\u89e3\u6790\u5668\u662f\u63a5\u6536\u8bf7\u6c42\u5e76\u6839\u636e\u67b6\u6784\u5b9a\u4e49\u8fd4\u56de\u6570\u636e\u7684\u90e8\u5206\u3002\u5047\u8bbe\u6211\u4eec\u5b9a\u4e49\u4e00\u4e2a\u53d8\u91cf\u5e76\u8fd4\u56de\u503c\u3002<\/p>\n<pre class=\"post-pre\"><code><span class=\"kd\">const<\/span> <span class=\"nx\">todoes<\/span> <span class=\"o\">=<\/span> <span class=\"p\">[<\/span>\r\n    <span class=\"p\">{<\/span>\r\n        <span class=\"na\">id<\/span><span class=\"p\">:<\/span> <span class=\"mi\">1<\/span><span class=\"p\">,<\/span>\r\n        <span class=\"na\">title<\/span><span class=\"p\">:<\/span> <span class=\"dl\">'<\/span><span class=\"s1\">\u7c21\u5358\u306a\u30bf\u30b9\u30af<\/span><span class=\"dl\">'<\/span><span class=\"p\">,<\/span>\r\n    <span class=\"p\">},<\/span>\r\n    <span class=\"p\">{<\/span>\r\n        <span class=\"na\">id<\/span><span class=\"p\">:<\/span> <span class=\"mi\">2<\/span><span class=\"p\">,<\/span>\r\n        <span class=\"na\">title<\/span><span class=\"p\">:<\/span> <span class=\"dl\">'<\/span><span class=\"s1\">\u6c17\u6301\u3061\u7c21\u5358\u306a\u30bf\u30b9\u30af<\/span><span class=\"dl\">'<\/span><span class=\"p\">,<\/span>\r\n    <span class=\"p\">},<\/span>\r\n    <span class=\"p\">{<\/span>\r\n        <span class=\"na\">id<\/span><span class=\"p\">:<\/span> <span class=\"mi\">3<\/span><span class=\"p\">,<\/span>\r\n        <span class=\"na\">title<\/span><span class=\"p\">:<\/span> <span class=\"dl\">'<\/span><span class=\"s1\">\u30e4\u30d0\u3044\u30bf\u30b9\u30af<\/span><span class=\"dl\">'<\/span><span class=\"p\">,<\/span>\r\n    <span class=\"p\">},<\/span>\r\n    <span class=\"p\">{<\/span>\r\n        <span class=\"na\">id<\/span><span class=\"p\">:<\/span> <span class=\"mi\">4<\/span><span class=\"p\">,<\/span>\r\n        <span class=\"na\">title<\/span><span class=\"p\">:<\/span> <span class=\"dl\">'<\/span><span class=\"s1\">\u6c17\u3065\u304b\u306a\u3044\u30d5\u30ea\u3092\u3057\u3066\u3044\u308b\u30bf\u30b9\u30af<\/span><span class=\"dl\">'<\/span><span class=\"p\">,<\/span>\r\n    <span class=\"p\">}<\/span>\r\n<span class=\"p\">]<\/span>\r\n\r\n<span class=\"kd\">const<\/span> <span class=\"nx\">resolvers<\/span> <span class=\"o\">=<\/span> <span class=\"p\">{<\/span>\r\n    <span class=\"na\">Query<\/span><span class=\"p\">:<\/span> <span class=\"p\">{<\/span>\r\n        <span class=\"na\">todo<\/span><span class=\"p\">:<\/span> <span class=\"p\">(<\/span><span class=\"na\">_<\/span><span class=\"p\">:<\/span> <span class=\"kr\">any<\/span><span class=\"p\">,<\/span> <span class=\"p\">{<\/span> <span class=\"nx\">id<\/span> <span class=\"p\">}:<\/span> <span class=\"p\">{<\/span> <span class=\"na\">id<\/span><span class=\"p\">:<\/span> <span class=\"kr\">number<\/span><span class=\"p\">})<\/span> <span class=\"o\">=&gt;<\/span> <span class=\"p\">{<\/span>\r\n            <span class=\"k\">return<\/span> <span class=\"nx\">todoes<\/span><span class=\"p\">.<\/span><span class=\"nx\">find<\/span><span class=\"p\">(<\/span><span class=\"nx\">todo<\/span> <span class=\"o\">=&gt;<\/span> <span class=\"nx\">todo<\/span><span class=\"p\">.<\/span><span class=\"nx\">id<\/span> <span class=\"o\">===<\/span> <span class=\"nx\">id<\/span><span class=\"p\">);<\/span>\r\n        <span class=\"p\">},<\/span>\r\n        <span class=\"na\">todoes<\/span><span class=\"p\">:<\/span> <span class=\"p\">(<\/span><span class=\"na\">_<\/span><span class=\"p\">:<\/span> <span class=\"kr\">any<\/span><span class=\"p\">,<\/span> <span class=\"p\">{<\/span> <span class=\"nx\">title<\/span> <span class=\"p\">}:<\/span> <span class=\"p\">{<\/span> <span class=\"na\">title<\/span><span class=\"p\">:<\/span> <span class=\"kr\">string<\/span> <span class=\"p\">})<\/span> <span class=\"o\">=&gt;<\/span> <span class=\"p\">{<\/span>\r\n            <span class=\"k\">return<\/span> <span class=\"nx\">todoes<\/span><span class=\"p\">.<\/span><span class=\"nx\">filter<\/span><span class=\"p\">(<\/span><span class=\"nx\">todo<\/span> <span class=\"o\">=&gt;<\/span> <span class=\"nx\">todo<\/span><span class=\"p\">.<\/span><span class=\"nx\">title<\/span><span class=\"p\">.<\/span><span class=\"nx\">includes<\/span><span class=\"p\">(<\/span><span class=\"nx\">title<\/span><span class=\"p\">))<\/span>\r\n        <span class=\"p\">},<\/span>\r\n    <span class=\"p\">},<\/span>\r\n<span class=\"p\">};<\/span>\r\n<\/code><\/pre>\n<h3>\u8fdb\u884c<\/h3>\n<p>\u90a3\u4e48\uff0c\u8ba9\u6211\u4eec\u542f\u52a8\u670d\u52a1\u5668\u5e76\u786e\u8ba4\u5230\u76ee\u524d\u4e3a\u6b62\u7684\u66f4\u6539\u3002<\/p>\n<pre class=\"post-pre\"><code><span class=\"nv\">$ <\/span>yarn dev\r\nts-node src\/index.ts\r\n? Server ready at http:\/\/localhost:4000\/graphql\r\n<\/code><\/pre>\n<p>\u54e6\uff01\u7ed3\u679c\u987a\u5229\u83b7\u53d6\u4e86(*\uff9f\u25bd\uff9f\uff89\uff89\uff9e\u2606\uff8a\uff9f\uff81\uff8a\uff9f\uff81<br \/>\n\u8fd9\u771f\u662f\u4e00\u6b21\u4ee4\u4eba\u5174\u594b\u3001\u975e\u5e38\u6709\u8da3\u7684\u65b0\u9c9c\u4f53\u9a8c\uff01<\/p>\n<div><img decoding=\"async\" class=\"post-images\" title=\"\" src=\"https:\/\/cdn.silicloud.com\/blog-img\/blog\/img\/657d80e8913a08637a6abad3\/32-0.png\" alt=\"\u30b9\u30af\u30ea\u30fc\u30f3\u30b7\u30e7\u30c3\u30c8 2019-12-21 1.56.07.png\" \/><\/div>\n<h2>\u4e0eDB\u8fdb\u884c\u5408\u4f5c<\/h2>\n<p>\u53ea\u8981\u53bb\u83b7\u53d6\u53d8\u91cf\u7684\u6570\u636e\u662f\u5f88\u65e0\u804a\u7684\uff0c\u6240\u4ee5\u6700\u597d\u5b9e\u8df5\u6027\u5730\u83b7\u53d6\u5b58\u5728\u4e8e\u6570\u636e\u5e93\u4e2d\u7684\u6570\u636e\u3002<\/p>\n<h3>\u5f15\u5165Prisma<\/h3>\n<p>Prisma\u662f\u4e00\u79cd\u8fde\u63a5GraphQL\u670d\u52a1\u5668\u548c\u6570\u636e\u5e93\u7684ORM\u3002\u53ea\u9700\u7f16\u5199\u6a21\u578b\u5b9a\u4e49\uff0c\u5b83\u4f1a\u81ea\u52a8\u751f\u6210\u7528\u4e8e\u8fdb\u884c\u8868\u8fc1\u79fb\u548c\u8bbf\u95ee\u6570\u636e\u5e93\u7684\u4ee3\u7801\u3002<\/p>\n<p>\u611f\u89c9\u4f7f\u7528TypeORM\u7b49\u5e93\u548c\u6ca1\u6709\u4f7f\u7528\u6ca1\u6709\u592a\u5927\u533a\u522b\uff0c\u5b8c\u5168\u6ca1\u6709\u4eab\u53d7\u5230\u4efb\u4f55\u4f18\u52bf&#8230;<\/p>\n<p>Prisma\u5e76\u975e\u4e00\u4e2a\u5e93\uff0c\u800c\u662f\u4e00\u4e2aCLI\u5de5\u5177\uff0c\u6240\u4ee5\u9700\u8981\u5c06\u5176\u4f5c\u4e3a\u5f00\u53d1\u5305\u8fdb\u884c\u5b89\u88c5\u3002<\/p>\n<pre class=\"post-pre\"><code>$ yarn add -D prisma\r\n<\/code><\/pre>\n<h3>\u6570\u636e\u5e93\u548cPrisma\u7684\u5b89\u88c5\u8bbe\u7f6e<\/h3>\n<p>\u53ea\u8981\u5728\u672c\u5730\u5f00\u53d1\u7684\u8bdd\uff0c\u6267\u884cinit\u547d\u4ee4\u5c31\u80fd\u5e2e\u4f60\u642d\u5efa\u597d\u6570\u636e\u5e93\u7684Docker\u73af\u5883\u3002<\/p>\n<p>\u8fd9\u6b21\u7684\u8bbe\u7f6e\u662f\u9009\u62e9\u4e86\u521b\u5efa\u65b0\u6570\u636e\u5e93\u3001MySQL\u548cPrisma TypeScript Client\u3002<\/p>\n<pre class=\"post-pre\"><code><span class=\"nv\">$ <\/span>yarn prisma init <span class=\"nb\">.<\/span>\r\nyarn run v1.19.1\r\n<span class=\"nv\">$ <\/span>\/Users\/tomohiro\/workspace\/graphql\/graphql-todo-app\/node_modules\/.bin\/prisma init <span class=\"nb\">.<\/span>\r\n? Set up a new Prisma server or deploy to an existing server? Create new database\r\n? What kind of database <span class=\"k\">do <\/span>you want to deploy to? MySQL\r\n? Select the programming language <span class=\"k\">for <\/span>the generated Prisma client Prisma TypeScript Client\r\n\r\nCreated 3 new files:\r\n\r\n  prisma.yml           Prisma service definition\r\n  datamodel.prisma    GraphQL SDL-based datamodel <span class=\"o\">(<\/span>foundation <span class=\"k\">for <\/span>database<span class=\"o\">)<\/span>\r\n  docker-compose.yml   Docker configuration file\r\n\r\nNext steps:\r\n\r\n  1. Open folder: <span class=\"nb\">cd<\/span> <span class=\"nb\">.<\/span>\r\n  2. Start your Prisma server: docker-compose up <span class=\"nt\">-d<\/span>\r\n  3. Deploy your Prisma service: prisma deploy\r\n  4. Read more about Prisma server:\r\n     http:\/\/bit.ly\/prisma-server-overview\r\n\r\nGenerating schema... 17ms\r\nSaving Prisma Client <span class=\"o\">(<\/span>TypeScript<span class=\"o\">)<\/span> at \/Users\/tomohiro\/workspace\/graphql\/graphql-todo-app\/generated\/prisma-client\/\r\n<\/code><\/pre>\n<h3>\u542f\u52a8Docker<\/h3>\n<p>\u4e3a\u4e86\u542f\u52a8Prisma\u670d\u52a1\u5668\uff0c\u4ece\u81ea\u52a8\u751f\u6210\u7684 docker-compose.yml \u6587\u4ef6\u4e2d\u542f\u52a8Docker\u5bb9\u5668\u3002<\/p>\n<p>\u9ed8\u8ba4\u60c5\u51b5\u4e0b\uff0c\u6570\u636e\u5e93\u5bb9\u5668\u7684\u7aef\u53e3\u672a\u7ed1\u5b9a\u5230\u4e3b\u673a\u7aef\u53e3\u4e0a\uff0c\u56e0\u6b64\u8bf7\u5c06\u4ee5\u4e0b\u90e8\u5206\u6ce8\u91ca\u6389\u4ee5\u8bbf\u95ee\u6570\u636e\u5e93\u3002<\/p>\n<pre class=\"post-pre\"><code><span class=\"c1\"># Uncomment the next two lines to connect to your your database from outside the Docker environment, e.g. using a database GUI like Workbench<\/span>\r\n<span class=\"na\">ports<\/span><span class=\"pi\">:<\/span>\r\n<span class=\"pi\">-<\/span> <span class=\"s2\">\"<\/span><span class=\"s\">3306:3306\"<\/span>\r\n<\/code><\/pre>\n<pre class=\"post-pre\"><code><span class=\"nv\">$ <\/span>docker-compose up <span class=\"nt\">-d<\/span>\r\n<\/code><\/pre>\n<h3>\u6570\u636e\u6a21\u578b\u7684\u5b9a\u4e49<\/h3>\n<p>\u6211\u5011\u5c07\u5b9a\u7fa9\u6578\u64da\u6a21\u578b\u3002Prisma\u5c07\u6839\u64da\u9019\u500b\u6a21\u578b\u5b9a\u7fa9\u9032\u884c\u6578\u64da\u5eab\u8868\u7684\u9077\u79fb\u3002<\/p>\n<pre class=\"post-pre\"><code>type Todo {\r\n  id: Int! @id(strategy: AUTO)\r\n  title: String!\r\n}\r\n<\/code><\/pre>\n<h3>\u6267\u884c\u8fc1\u79fb<\/h3>\n<p>\u5728\u6267\u884c\u8fc1\u79fb\u4e4b\u524d\uff0c\u8bf7\u4fee\u6539 prisma.yml \u6587\u4ef6\uff0c\u5e76\u8fdb\u884c\u5ba2\u6237\u7aef\u4ee3\u7801\u751f\u6210\u8def\u5f84\u548c hooks \u7684\u8bbe\u7f6e\u3002<\/p>\n<pre class=\"post-pre\"><code><span class=\"na\">generate<\/span><span class=\"pi\">:<\/span>\r\n  <span class=\"pi\">-<\/span> <span class=\"na\">generator<\/span><span class=\"pi\">:<\/span> <span class=\"s\">typescript-client<\/span>\r\n    <span class=\"na\">output<\/span><span class=\"pi\">:<\/span> <span class=\"s\">.\/src\/generated\/prisma-client\/<\/span> <span class=\"c1\"># \u751f\u6210\u5148\u3092 src\/ \u306b\u5909\u66f4<\/span>\r\n\r\n<span class=\"c1\"># \u30de\u30a4\u30b0\u30ec\u30fc\u30b7\u30e7\u30f3\u5b9f\u884c\u306e\u30bf\u30a4\u30df\u30f3\u30b0\u3067\u30af\u30e9\u30a4\u30a2\u30f3\u30c8\u30b3\u30fc\u30c9\u306e\u751f\u6210\u3082\u5b9f\u884c\u3059\u308b<\/span>\r\n<span class=\"na\">hooks<\/span><span class=\"pi\">:<\/span>\r\n  <span class=\"na\">post-deploy<\/span><span class=\"pi\">:<\/span>\r\n    <span class=\"pi\">-<\/span> <span class=\"s\">prisma generate<\/span>\r\n<\/code><\/pre>\n<p>\u73b0\u5728\u5f00\u59cb\u6267\u884c\u8fc1\u79fb\u64cd\u4f5c\u3002<\/p>\n<pre class=\"post-pre\"><code><span class=\"nv\">$ <\/span>yarn prisma deploy\r\nyarn run v1.19.1\r\n<span class=\"nv\">$ <\/span>\/Users\/tomohiro\/workspace\/graphql\/graphql-todo-app\/node_modules\/.bin\/prisma deploy\r\nCreating stage default <span class=\"k\">for <\/span>service default \u2714\r\nDeploying service <span class=\"sb\">`<\/span>default<span class=\"sb\">`<\/span> to stage <span class=\"sb\">`<\/span>default<span class=\"sb\">`<\/span> to server <span class=\"sb\">`<\/span><span class=\"nb\">local<\/span><span class=\"sb\">`<\/span> 1.3s\r\n\r\nChanges:\r\n\r\n  Todo <span class=\"o\">(<\/span>Type<span class=\"o\">)<\/span>\r\n  + Created <span class=\"nb\">type<\/span> <span class=\"sb\">`<\/span>Todo<span class=\"sb\">`<\/span>\r\n  + Created field <span class=\"sb\">`<\/span><span class=\"nb\">id<\/span><span class=\"sb\">`<\/span> of <span class=\"nb\">type<\/span> <span class=\"sb\">`<\/span>Int!<span class=\"sb\">`<\/span>\r\n  + Created field <span class=\"sb\">`<\/span>title<span class=\"sb\">`<\/span> of <span class=\"nb\">type<\/span> <span class=\"sb\">`<\/span>String!<span class=\"sb\">`<\/span>\r\n\r\n...\r\n<\/code><\/pre>\n<p>\u5982\u679c\u5b9e\u9645\u8fde\u63a5\u5230MySQL\uff0c\u4f60\u53ef\u4ee5\u786e\u8ba4\u751f\u6210\u4e86default@default\/Todo\u6570\u636e\u5e93\u548c\u9009\u9879\u3002<\/p>\n<pre class=\"post-pre\"><code>host: 127.0.0.1\r\nuser: root\r\npassword: prisma\r\n<\/code><\/pre>\n<p>\u6211\u4f1a\u6dfb\u52a0\u4e00\u4e9b\u6570\u636e\u4f5c\u4e3a\u6d4b\u8bd5\u7528\u3002<\/p>\n<pre class=\"post-pre\"><code><span class=\"k\">INSERT<\/span> <span class=\"k\">INTO<\/span> <span class=\"n\">Todo<\/span><span class=\"p\">(<\/span><span class=\"n\">title<\/span><span class=\"p\">)<\/span> <span class=\"k\">values<\/span> \r\n    <span class=\"p\">(<\/span><span class=\"s1\">'\u7c21\u5358\u306a\u30bf\u30b9\u30af'<\/span><span class=\"p\">),<\/span>\r\n    <span class=\"p\">(<\/span><span class=\"s1\">'\u6c17\u6301\u3061\u7c21\u5358\u306a\u30bf\u30b9\u30af'<\/span><span class=\"p\">),<\/span>\r\n    <span class=\"p\">(<\/span><span class=\"s1\">'\u30e4\u30d0\u3044\u30bf\u30b9\u30af'<\/span><span class=\"p\">),<\/span>\r\n    <span class=\"p\">(<\/span><span class=\"s1\">'\u6c17\u3065\u304b\u306a\u3044\u30d5\u30ea\u3092\u3057\u3066\u3044\u308b\u30bf\u30b9\u30af'<\/span><span class=\"p\">);<\/span>\r\n<\/code><\/pre>\n<h3>\u5c06\u8fd4\u56deDB\u6570\u636e\u7684\u5b9e\u73b0\u66f4\u6539\u3002<\/h3>\n<p>\u7531\u4e8e\u5ba2\u6237\u7aef\u5e93\u88ab\u81ea\u52a8\u751f\u6210\u5728 src\/generated\/prisma-client \u4e2d\uff0c\u56e0\u6b64\u6211\u4eec\u5c06\u4f7f\u7528\u5b83\u6765\u8bbf\u95ee\u6570\u636e\u5e93\u3002<\/p>\n<pre class=\"post-pre\"><code><span class=\"k\">import<\/span> <span class=\"p\">{<\/span> <span class=\"nx\">prisma<\/span> <span class=\"p\">}<\/span> <span class=\"k\">from<\/span> <span class=\"dl\">'<\/span><span class=\"s1\">.\/generated\/prisma-client<\/span><span class=\"dl\">'<\/span>\r\n\r\n<span class=\"p\">...<\/span>\r\n\r\n<span class=\"kd\">const<\/span> <span class=\"nx\">resolvers<\/span> <span class=\"o\">=<\/span> <span class=\"p\">{<\/span>\r\n    <span class=\"na\">Query<\/span><span class=\"p\">:<\/span> <span class=\"p\">{<\/span>\r\n        <span class=\"na\">todo<\/span><span class=\"p\">:<\/span> <span class=\"p\">(<\/span><span class=\"na\">_<\/span><span class=\"p\">:<\/span> <span class=\"kr\">any<\/span><span class=\"p\">,<\/span> <span class=\"p\">{<\/span> <span class=\"nx\">id<\/span> <span class=\"p\">}:<\/span> <span class=\"p\">{<\/span> <span class=\"na\">id<\/span><span class=\"p\">:<\/span> <span class=\"kr\">number<\/span><span class=\"p\">})<\/span> <span class=\"o\">=&gt;<\/span> <span class=\"p\">{<\/span>\r\n            <span class=\"k\">return<\/span> <span class=\"nx\">prisma<\/span><span class=\"p\">.<\/span><span class=\"nx\">todo<\/span><span class=\"p\">({<\/span> <span class=\"nx\">id<\/span> <span class=\"p\">});<\/span>\r\n        <span class=\"p\">},<\/span>\r\n        <span class=\"na\">todoes<\/span><span class=\"p\">:<\/span> <span class=\"p\">(<\/span><span class=\"na\">_<\/span><span class=\"p\">:<\/span> <span class=\"kr\">any<\/span><span class=\"p\">,<\/span> <span class=\"p\">{<\/span> <span class=\"nx\">title<\/span> <span class=\"p\">}:<\/span> <span class=\"p\">{<\/span> <span class=\"na\">title<\/span><span class=\"p\">:<\/span> <span class=\"kr\">string<\/span> <span class=\"p\">})<\/span> <span class=\"o\">=&gt;<\/span> <span class=\"p\">{<\/span>\r\n            <span class=\"k\">return<\/span> <span class=\"nx\">prisma<\/span><span class=\"p\">.<\/span><span class=\"nx\">todoes<\/span><span class=\"p\">({<\/span> <span class=\"na\">where<\/span><span class=\"p\">:<\/span> <span class=\"p\">{<\/span> <span class=\"na\">title_contains<\/span><span class=\"p\">:<\/span> <span class=\"nx\">title<\/span> <span class=\"p\">}});<\/span>\r\n        <span class=\"p\">},<\/span>\r\n    <span class=\"p\">},<\/span>\r\n<span class=\"p\">};<\/span>\r\n<\/code><\/pre>\n<div><img decoding=\"async\" class=\"post-images\" title=\"\" src=\"https:\/\/cdn.silicloud.com\/blog-img\/blog\/img\/657d80e8913a08637a6abad3\/64-0.png\" alt=\"\u30b9\u30af\u30ea\u30fc\u30f3\u30b7\u30e7\u30c3\u30c8 2019-12-21 1.56.07.png\" \/><\/div>\n<h2>\u5c06\u6a21\u5f0f\u5b9a\u4e49\u5265\u79bb\u5230\u53e6\u4e00\u4e2a\u6587\u4ef6\u4e2d<\/h2>\n<p>\u7531\u4e8e\u4f7f\u7528\u6a21\u677f\u5b57\u9762\u91cf\u7f16\u5199\u67b6\u6784\u5b9a\u4e49\u4f1a\u5f88\u96be\u9605\u8bfb\u4e14\u7ef4\u62a4\u6027\u5dee\uff0c\u56e0\u6b64\u5c06\u5176\u62c6\u5206\u5230\u53e6\u4e00\u4e2a\u6587\u4ef6\u4e2d\u3002<\/p>\n<h3>\u5b89\u88c5 graphql-import<\/h3>\n<p>Urigo\/graphql-import \u662f\u4e00\u4e2a\u80fd\u591f\u5b9e\u73b0\u5bfc\u5165GraphQL\u6a21\u5f0f\u5b9a\u4e49\u6587\u4ef6\u7684\u5e93\u3002<\/p>\n<pre class=\"post-pre\"><code>$ yarn add graphql-import\r\n<\/code><\/pre>\n<h2>\u5c06\u6a21\u5f0f\u5b9a\u4e49\u62c6\u5206\u4e3a\u591a\u4e2a\u90e8\u5206\u3002<\/h2>\n<p>\u6211\u4f1a\u521b\u5efa\u4e00\u4e2a\u65b0\u76ee\u5f55\u6765\u5b58\u653e\u6a21\u5f0f\u5b9a\u4e49\u3002<\/p>\n<pre class=\"post-pre\"><code>$ mkdir src\/schema\r\n<\/code><\/pre>\n<pre class=\"post-pre\"><code><span class=\"k\">type<\/span> <span class=\"n\">Todo<\/span> <span class=\"p\">{<\/span>\r\n    <span class=\"n\">id<\/span><span class=\"p\">:<\/span> <span class=\"nb\">Int<\/span><span class=\"p\">!<\/span>\r\n    <span class=\"n\">title<\/span><span class=\"p\">:<\/span> <span class=\"nb\">String<\/span>\r\n<span class=\"p\">}<\/span>\r\n<\/code><\/pre>\n<pre class=\"post-pre\"><code><span class=\"c\"># import Todo from \"todoes.graphql\"<\/span>\r\n\r\n<span class=\"k\">type<\/span> <span class=\"n\">Query<\/span> <span class=\"p\">{<\/span>\r\n    <span class=\"n\">todo<\/span><span class=\"p\">(<\/span><span class=\"n\">id<\/span><span class=\"p\">:<\/span> <span class=\"nb\">Int<\/span><span class=\"p\">):<\/span> <span class=\"n\">Todo<\/span>\r\n    <span class=\"n\">todoes<\/span><span class=\"p\">(<\/span><span class=\"n\">title<\/span><span class=\"p\">:<\/span> <span class=\"nb\">String<\/span><span class=\"p\">):<\/span> <span class=\"p\">[<\/span><span class=\"n\">Todo<\/span><span class=\"p\">]<\/span>\r\n<span class=\"p\">}<\/span>\r\n<\/code><\/pre>\n<h2>\u5bfc\u5165\u67b6\u6784\u5b9a\u4e49<\/h2>\n<p>\u6211\u611f\u5230\u975e\u5e38\u6e05\u723d\u3002<\/p>\n<pre class=\"post-pre\"><code><span class=\"k\">import<\/span> <span class=\"nx\">express<\/span> <span class=\"k\">from<\/span> <span class=\"dl\">'<\/span><span class=\"s1\">express<\/span><span class=\"dl\">'<\/span><span class=\"p\">;<\/span>\r\n<span class=\"k\">import<\/span> <span class=\"p\">{<\/span> <span class=\"nx\">ApolloServer<\/span><span class=\"p\">,<\/span> <span class=\"nx\">gql<\/span> <span class=\"p\">}<\/span> <span class=\"k\">from<\/span> <span class=\"dl\">'<\/span><span class=\"s1\">apollo-server-express<\/span><span class=\"dl\">'<\/span><span class=\"p\">;<\/span>\r\n<span class=\"k\">import<\/span> <span class=\"p\">{<\/span> <span class=\"nx\">prisma<\/span> <span class=\"p\">}<\/span> <span class=\"k\">from<\/span> <span class=\"dl\">'<\/span><span class=\"s1\">.\/generated\/prisma-client<\/span><span class=\"dl\">'<\/span><span class=\"p\">;<\/span>\r\n<span class=\"k\">import<\/span> <span class=\"p\">{<\/span> <span class=\"nx\">importSchema<\/span> <span class=\"p\">}<\/span> <span class=\"k\">from<\/span> <span class=\"dl\">'<\/span><span class=\"s1\">graphql-import<\/span><span class=\"dl\">'<\/span><span class=\"p\">;<\/span>\r\n\r\n<span class=\"kd\">const<\/span> <span class=\"nx\">typeDefs<\/span> <span class=\"o\">=<\/span> <span class=\"nx\">importSchema<\/span><span class=\"p\">(<\/span><span class=\"s2\">`<\/span><span class=\"p\">${<\/span><span class=\"nx\">__dirname<\/span><span class=\"p\">}<\/span><span class=\"s2\">\/schema\/schema.graphql`<\/span><span class=\"p\">);<\/span>\r\n\r\n<span class=\"kd\">const<\/span> <span class=\"nx\">resolvers<\/span> <span class=\"o\">=<\/span> <span class=\"p\">{<\/span>\r\n    <span class=\"na\">Query<\/span><span class=\"p\">:<\/span> <span class=\"p\">{<\/span>\r\n        <span class=\"na\">todo<\/span><span class=\"p\">:<\/span> <span class=\"p\">(<\/span><span class=\"na\">_<\/span><span class=\"p\">:<\/span> <span class=\"kr\">any<\/span><span class=\"p\">,<\/span> <span class=\"p\">{<\/span> <span class=\"nx\">id<\/span> <span class=\"p\">}:<\/span> <span class=\"p\">{<\/span> <span class=\"na\">id<\/span><span class=\"p\">:<\/span> <span class=\"kr\">number<\/span><span class=\"p\">})<\/span> <span class=\"o\">=&gt;<\/span> <span class=\"p\">{<\/span>\r\n            <span class=\"k\">return<\/span> <span class=\"nx\">prisma<\/span><span class=\"p\">.<\/span><span class=\"nx\">todo<\/span><span class=\"p\">({<\/span> <span class=\"nx\">id<\/span> <span class=\"p\">});<\/span>\r\n        <span class=\"p\">},<\/span>\r\n        <span class=\"na\">todoes<\/span><span class=\"p\">:<\/span> <span class=\"p\">(<\/span><span class=\"na\">_<\/span><span class=\"p\">:<\/span> <span class=\"kr\">any<\/span><span class=\"p\">,<\/span> <span class=\"p\">{<\/span> <span class=\"nx\">title<\/span> <span class=\"p\">}:<\/span> <span class=\"p\">{<\/span> <span class=\"na\">title<\/span><span class=\"p\">:<\/span> <span class=\"kr\">string<\/span> <span class=\"p\">})<\/span> <span class=\"o\">=&gt;<\/span> <span class=\"p\">{<\/span>\r\n            <span class=\"k\">return<\/span> <span class=\"nx\">prisma<\/span><span class=\"p\">.<\/span><span class=\"nx\">todoes<\/span><span class=\"p\">({<\/span> <span class=\"na\">where<\/span><span class=\"p\">:<\/span> <span class=\"p\">{<\/span> <span class=\"na\">title_contains<\/span><span class=\"p\">:<\/span> <span class=\"nx\">title<\/span> <span class=\"p\">}});<\/span>\r\n        <span class=\"p\">},<\/span>\r\n    <span class=\"p\">},<\/span>\r\n<span class=\"p\">};<\/span>\r\n\r\n<span class=\"kd\">const<\/span> <span class=\"nx\">server<\/span> <span class=\"o\">=<\/span> <span class=\"k\">new<\/span> <span class=\"nx\">ApolloServer<\/span><span class=\"p\">(<\/span> <span class=\"p\">{<\/span> <span class=\"nx\">typeDefs<\/span><span class=\"p\">,<\/span> <span class=\"nx\">resolvers<\/span> <span class=\"p\">});<\/span>\r\n<\/code><\/pre>\n<h2>\u7ed3\u675f<\/h2>\n<p>\u5bf9\u4e8e\u521d\u6b21\u63a5\u89e6\u6765\u8bf4\uff0c\u6574\u4f53\u5b9e\u73b0\u4f3c\u4e4e\u4e0e REST API \u610f\u5916\u5730\u76f8\u4f3c\u3002<br \/>\n\u4e0d\u8fc7\uff0c\u4e00\u65e6\u5f00\u59cb\u5168\u9762\u5730\u5b9e\u65bd\uff0c\u53ef\u80fd\u4f1a\u51fa\u73b0\u5404\u79cd\u91cd\u5927\u5dee\u5f02\u3002<\/p>\n<p>\u6211\u5f88\u9ad8\u5174\u7ec8\u4e8e\u7406\u89e3\u4e86GraphQL\u670d\u52a1\u5668\u5b9e\u73b0\u7684\u6982\u8981\uff0c\u4e4b\u524d\u4e00\u76f4\u5bf9\u6b64\u611f\u5230\u56f0\u60d1\u3002<\/p>\n<p>\u5982\u679c\u4f7f\u7528prisma-labs\/graphqlgen\u5e93\uff0c\u53ef\u4ee5\u4ece\u6a21\u5f0f\u5b9a\u4e49\u81ea\u52a8\u751f\u6210\u89e3\u6790\u5668\uff1f\u56e0\u6b64\uff0c\u671f\u671b\u53ef\u4ee5\u901a\u8fc7\u6b63\u786e\u4f7f\u7528prisma\u6765\u5b9e\u73b0\u4ece\u6a21\u5f0f\u5b9a\u4e49\u4e3a\u57fa\u7840\u7684\u65b0\u5f00\u53d1\u4f53\u9a8c\uff0c\u6240\u4ee5\u60f3\u8981\u5c1d\u8bd5\u66f4\u591a\u3002<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u8fd9\u7bc7\u6587\u7ae0\u662fHamee Advent Calendar 2019\u7b2c21\u5929\u7684\u6587\u7ae0\u3002 \u6700\u8fd1\uff0c\u6211\u5728\u5b9e\u73b0\u67d0\u4e2a\u7ba1\u7406\u754c\u9762\u4e4b\u540e [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-47817","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v21.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u901a\u8fc7\u4f7f\u7528Apollo\u548cPrisma\u6765\u5165\u95e8GraphQL - Blog - Silicon Cloud<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.silicloud.com\/zh\/blog\/\u901a\u8fc7\u4f7f\u7528apollo\u548cprisma\u6765\u5165\u95e8graphql\u3002\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u901a\u8fc7\u4f7f\u7528Apollo\u548cPrisma\u6765\u5165\u95e8GraphQL\" \/>\n<meta property=\"og:description\" content=\"\u8fd9\u7bc7\u6587\u7ae0\u662fHamee Advent Calendar 2019\u7b2c21\u5929\u7684\u6587\u7ae0\u3002 \u6700\u8fd1\uff0c\u6211\u5728\u5b9e\u73b0\u67d0\u4e2a\u7ba1\u7406\u754c\u9762\u4e4b\u540e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.silicloud.com\/zh\/blog\/\u901a\u8fc7\u4f7f\u7528apollo\u548cprisma\u6765\u5165\u95e8graphql\u3002\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog - Silicon Cloud\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-07T19:28:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-04T01:54:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.silicloud.com\/blog-img\/blog\/img\/657d80e8913a08637a6abad3\/32-0.png\" \/>\n<meta name=\"author\" content=\"\u97f5, \u79d1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u97f5, \u79d1\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 \u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.silicloud.com\/zh\/blog\/%e9%80%9a%e8%bf%87%e4%bd%bf%e7%94%a8apollo%e5%92%8cprisma%e6%9d%a5%e5%85%a5%e9%97%a8graphql%e3%80%82\/\",\"url\":\"https:\/\/www.silicloud.com\/zh\/blog\/%e9%80%9a%e8%bf%87%e4%bd%bf%e7%94%a8apollo%e5%92%8cprisma%e6%9d%a5%e5%85%a5%e9%97%a8graphql%e3%80%82\/\",\"name\":\"\u901a\u8fc7\u4f7f\u7528Apollo\u548cPrisma\u6765\u5165\u95e8GraphQL - Blog - Silicon Cloud\",\"isPartOf\":{\"@id\":\"https:\/\/www.silicloud.com\/zh\/blog\/#website\"},\"datePublished\":\"2024-03-07T19:28:19+00:00\",\"dateModified\":\"2024-05-04T01:54:25+00:00\",\"author\":{\"@id\":\"https:\/\/www.silicloud.com\/zh\/blog\/#\/schema\/person\/6530331a63adef3b3443a1fab53a0e6e\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.silicloud.com\/zh\/blog\/%e9%80%9a%e8%bf%87%e4%bd%bf%e7%94%a8apollo%e5%92%8cprisma%e6%9d%a5%e5%85%a5%e9%97%a8graphql%e3%80%82\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.silicloud.com\/zh\/blog\/%e9%80%9a%e8%bf%87%e4%bd%bf%e7%94%a8apollo%e5%92%8cprisma%e6%9d%a5%e5%85%a5%e9%97%a8graphql%e3%80%82\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.silicloud.com\/zh\/blog\/%e9%80%9a%e8%bf%87%e4%bd%bf%e7%94%a8apollo%e5%92%8cprisma%e6%9d%a5%e5%85%a5%e9%97%a8graphql%e3%80%82\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9875\",\"item\":\"https:\/\/www.silicloud.com\/zh\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u901a\u8fc7\u4f7f\u7528Apollo\u548cPrisma\u6765\u5165\u95e8GraphQL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.silicloud.com\/zh\/blog\/#website\",\"url\":\"https:\/\/www.silicloud.com\/zh\/blog\/\",\"name\":\"Blog - Silicon Cloud\",\"description\":\"\",\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.silicloud.com\/zh\/blog\/#\/schema\/person\/6530331a63adef3b3443a1fab53a0e6e\",\"name\":\"\u97f5, \u79d1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\/\/www.silicloud.com\/zh\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/429ccb39b3fff5188bc17986222cfb0936cbadb8cc933cff04ab5ca01bd30a08?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/429ccb39b3fff5188bc17986222cfb0936cbadb8cc933cff04ab5ca01bd30a08?s=96&d=mm&r=g\",\"caption\":\"\u97f5, \u79d1\"},\"url\":\"https:\/\/www.silicloud.com\/zh\/blog\/author\/yunke\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\/\/www.silicloud.com\/zh\/blog\/%e9%80%9a%e8%bf%87%e4%bd%bf%e7%94%a8apollo%e5%92%8cprisma%e6%9d%a5%e5%85%a5%e9%97%a8graphql%e3%80%82\/#local-main-organization-logo\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Blog - Silicon Cloud\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u901a\u8fc7\u4f7f\u7528Apollo\u548cPrisma\u6765\u5165\u95e8GraphQL - Blog - Silicon Cloud","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.silicloud.com\/zh\/blog\/\u901a\u8fc7\u4f7f\u7528apollo\u548cprisma\u6765\u5165\u95e8graphql\u3002\/","og_locale":"zh_CN","og_type":"article","og_title":"\u901a\u8fc7\u4f7f\u7528Apollo\u548cPrisma\u6765\u5165\u95e8GraphQL","og_description":"\u8fd9\u7bc7\u6587\u7ae0\u662fHamee Advent Calendar 2019\u7b2c21\u5929\u7684\u6587\u7ae0\u3002 \u6700\u8fd1\uff0c\u6211\u5728\u5b9e\u73b0\u67d0\u4e2a\u7ba1\u7406\u754c\u9762\u4e4b\u540e [&hellip;]","og_url":"https:\/\/www.silicloud.com\/zh\/blog\/\u901a\u8fc7\u4f7f\u7528apollo\u548cprisma\u6765\u5165\u95e8graphql\u3002\/","og_site_name":"Blog - Silicon Cloud","article_published_time":"2024-03-07T19:28:19+00:00","article_modified_time":"2024-05-04T01:54:25+00:00","og_image":[{"url":"https:\/\/cdn.silicloud.com\/blog-img\/blog\/img\/657d80e8913a08637a6abad3\/32-0.png"}],"author":"\u97f5, \u79d1","twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005":"\u97f5, \u79d1","\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"3 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.silicloud.com\/zh\/blog\/%e9%80%9a%e8%bf%87%e4%bd%bf%e7%94%a8apollo%e5%92%8cprisma%e6%9d%a5%e5%85%a5%e9%97%a8graphql%e3%80%82\/","url":"https:\/\/www.silicloud.com\/zh\/blog\/%e9%80%9a%e8%bf%87%e4%bd%bf%e7%94%a8apollo%e5%92%8cprisma%e6%9d%a5%e5%85%a5%e9%97%a8graphql%e3%80%82\/","name":"\u901a\u8fc7\u4f7f\u7528Apollo\u548cPrisma\u6765\u5165\u95e8GraphQL - Blog - Silicon Cloud","isPartOf":{"@id":"https:\/\/www.silicloud.com\/zh\/blog\/#website"},"datePublished":"2024-03-07T19:28:19+00:00","dateModified":"2024-05-04T01:54:25+00:00","author":{"@id":"https:\/\/www.silicloud.com\/zh\/blog\/#\/schema\/person\/6530331a63adef3b3443a1fab53a0e6e"},"breadcrumb":{"@id":"https:\/\/www.silicloud.com\/zh\/blog\/%e9%80%9a%e8%bf%87%e4%bd%bf%e7%94%a8apollo%e5%92%8cprisma%e6%9d%a5%e5%85%a5%e9%97%a8graphql%e3%80%82\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.silicloud.com\/zh\/blog\/%e9%80%9a%e8%bf%87%e4%bd%bf%e7%94%a8apollo%e5%92%8cprisma%e6%9d%a5%e5%85%a5%e9%97%a8graphql%e3%80%82\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.silicloud.com\/zh\/blog\/%e9%80%9a%e8%bf%87%e4%bd%bf%e7%94%a8apollo%e5%92%8cprisma%e6%9d%a5%e5%85%a5%e9%97%a8graphql%e3%80%82\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/www.silicloud.com\/zh\/blog\/"},{"@type":"ListItem","position":2,"name":"\u901a\u8fc7\u4f7f\u7528Apollo\u548cPrisma\u6765\u5165\u95e8GraphQL"}]},{"@type":"WebSite","@id":"https:\/\/www.silicloud.com\/zh\/blog\/#website","url":"https:\/\/www.silicloud.com\/zh\/blog\/","name":"Blog - Silicon Cloud","description":"","inLanguage":"zh-Hans"},{"@type":"Person","@id":"https:\/\/www.silicloud.com\/zh\/blog\/#\/schema\/person\/6530331a63adef3b3443a1fab53a0e6e","name":"\u97f5, \u79d1","image":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/www.silicloud.com\/zh\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/429ccb39b3fff5188bc17986222cfb0936cbadb8cc933cff04ab5ca01bd30a08?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/429ccb39b3fff5188bc17986222cfb0936cbadb8cc933cff04ab5ca01bd30a08?s=96&d=mm&r=g","caption":"\u97f5, \u79d1"},"url":"https:\/\/www.silicloud.com\/zh\/blog\/author\/yunke\/"},{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/www.silicloud.com\/zh\/blog\/%e9%80%9a%e8%bf%87%e4%bd%bf%e7%94%a8apollo%e5%92%8cprisma%e6%9d%a5%e5%85%a5%e9%97%a8graphql%e3%80%82\/#local-main-organization-logo","url":"","contentUrl":"","caption":"Blog - Silicon Cloud"}]}},"_links":{"self":[{"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/posts\/47817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/comments?post=47817"}],"version-history":[{"count":2,"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/posts\/47817\/revisions"}],"predecessor-version":[{"id":97623,"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/posts\/47817\/revisions\/97623"}],"wp:attachment":[{"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/media?parent=47817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/categories?post=47817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/tags?post=47817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}