{"id":30944,"date":"2023-09-22T22:06:54","date_gmt":"2023-01-28T03:25:57","guid":{"rendered":"https:\/\/www.silicloud.com\/zh\/blog\/php%e7%9a%84%e6%97%a5%e6%9c%9f%e6%a0%bc%e5%bc%8f\/"},"modified":"2025-08-12T21:31:29","modified_gmt":"2025-08-12T13:31:29","slug":"php%e7%9a%84%e6%97%a5%e6%9c%9f%e6%a0%bc%e5%bc%8f","status":"publish","type":"post","link":"https:\/\/www.silicloud.com\/zh\/blog\/php%e7%9a%84%e6%97%a5%e6%9c%9f%e6%a0%bc%e5%bc%8f\/","title":{"rendered":"PHP\u7684\u65e5\u671f\u683c\u5f0f"},"content":{"rendered":"<h1>\u65e5\u671f\u51fd\u6570<\/h1>\n<p>\u4ece\u624b\u518c\u4e2d\u6458\u5f55<\/p>\n<h2>\u4ee3\u7801 m\u01ce)<\/h2>\n<pre class=\"post-pre\"><code><span class=\"cp\">&lt;?php<\/span>\r\n<span class=\"c1\">\/\/ YYYY\/MM\/DD\u5f62\u5f0f<\/span>\r\n<span class=\"k\">echo<\/span> <span class=\"nb\">date<\/span><span class=\"p\">(<\/span><span class=\"s2\">\"Y\/m\/d\"<\/span><span class=\"p\">)<\/span> <span class=\"mf\">.<\/span> <span class=\"s2\">\"<\/span><span class=\"se\">\\n<\/span><span class=\"s2\">\"<\/span><span class=\"p\">;<\/span>\r\n<span class=\"c1\">\/\/ YY\/M\/D\u5f62\u5f0f\uff08\u5148\u982d0\u4ed8\u3051\u306a\u3044\uff09<\/span>\r\n<span class=\"k\">echo<\/span> <span class=\"nb\">date<\/span><span class=\"p\">(<\/span><span class=\"s2\">\"y\/n\/j\"<\/span><span class=\"p\">)<\/span> <span class=\"mf\">.<\/span> <span class=\"s2\">\"<\/span><span class=\"se\">\\n<\/span><span class=\"s2\">\"<\/span><span class=\"p\">;<\/span>\r\n<span class=\"c1\">\/\/ MMM(\u6708\u82f1\u8a9e3\u6587\u5b57)<\/span>\r\n<span class=\"k\">echo<\/span> <span class=\"nb\">date<\/span><span class=\"p\">(<\/span><span class=\"s2\">\"M\"<\/span><span class=\"p\">)<\/span> <span class=\"mf\">.<\/span> <span class=\"s2\">\"<\/span><span class=\"se\">\\n<\/span><span class=\"s2\">\"<\/span><span class=\"p\">;<\/span>\r\n<span class=\"c1\">\/\/ DDD(\u66dc\u65e5\u82f1\u8a9e3\u6587\u5b57)<\/span>\r\n<span class=\"k\">echo<\/span> <span class=\"nb\">date<\/span><span class=\"p\">(<\/span><span class=\"s2\">\"D\"<\/span><span class=\"p\">)<\/span> <span class=\"mf\">.<\/span> <span class=\"s2\">\"<\/span><span class=\"se\">\\n<\/span><span class=\"s2\">\"<\/span><span class=\"p\">;<\/span>\r\n<span class=\"c1\">\/\/ \u66dc\u65e5<\/span>\r\n<span class=\"k\">echo<\/span> <span class=\"nb\">date<\/span><span class=\"p\">(<\/span><span class=\"s2\">\"w\"<\/span><span class=\"p\">)<\/span> <span class=\"mf\">.<\/span> <span class=\"s2\">\"<\/span><span class=\"se\">\\n<\/span><span class=\"s2\">\"<\/span><span class=\"p\">;<\/span>\r\n<span class=\"nv\">$week<\/span> <span class=\"o\">=<\/span> <span class=\"k\">array<\/span><span class=\"p\">(<\/span><span class=\"s2\">\"\u65e5\u66dc\u65e5\"<\/span><span class=\"p\">,<\/span> <span class=\"s2\">\"\u6708\u66dc\u65e5\"<\/span><span class=\"p\">,<\/span> <span class=\"s2\">\"\u706b\u66dc\u65e5\"<\/span><span class=\"p\">,<\/span> <span class=\"s2\">\"\u6c34\u66dc\u65e5\"<\/span><span class=\"p\">,<\/span> <span class=\"s2\">\"\u6728\u66dc\u65e5\"<\/span><span class=\"p\">,<\/span> <span class=\"s2\">\"\u91d1\u66dc\u65e5\"<\/span><span class=\"p\">,<\/span> <span class=\"s2\">\"\u571f\u66dc\u65e5\"<\/span><span class=\"p\">);<\/span>\r\n<span class=\"k\">echo<\/span> <span class=\"nv\">$week<\/span><span class=\"p\">[<\/span><span class=\"nb\">date<\/span><span class=\"p\">(<\/span><span class=\"s2\">\"w\"<\/span><span class=\"p\">)]<\/span> <span class=\"mf\">.<\/span> <span class=\"s2\">\"<\/span><span class=\"se\">\\n<\/span><span class=\"s2\">\"<\/span><span class=\"p\">;<\/span>\r\n<span class=\"c1\">\/\/ HH24:MI:SS\u5f62\u5f0f(24\u6642\u9593\u8868\u8a18)<\/span>\r\n<span class=\"k\">echo<\/span> <span class=\"nb\">date<\/span><span class=\"p\">(<\/span><span class=\"s2\">\"H:i:s\"<\/span><span class=\"p\">)<\/span> <span class=\"mf\">.<\/span> <span class=\"s2\">\"<\/span><span class=\"se\">\\n<\/span><span class=\"s2\">\"<\/span><span class=\"p\">;<\/span>\r\n<span class=\"c1\">\/\/ am|pm HH:MI:SS\u5f62\u5f0f<\/span>\r\n<span class=\"k\">echo<\/span> <span class=\"nb\">date<\/span><span class=\"p\">(<\/span><span class=\"s2\">\"a h:i:s\"<\/span><span class=\"p\">)<\/span> <span class=\"mf\">.<\/span> <span class=\"s2\">\"<\/span><span class=\"se\">\\n<\/span><span class=\"s2\">\"<\/span><span class=\"p\">;<\/span>\r\n<span class=\"c1\">\/\/ AM|PM HH:MI:SS\u5f62\u5f0f<\/span>\r\n<span class=\"k\">echo<\/span> <span class=\"nb\">date<\/span><span class=\"p\">(<\/span><span class=\"s2\">\"A h:i:s\"<\/span><span class=\"p\">)<\/span> <span class=\"mf\">.<\/span> <span class=\"s2\">\"<\/span><span class=\"se\">\\n<\/span><span class=\"s2\">\"<\/span><span class=\"p\">;<\/span>\r\n<\/code><\/pre>\n<h2>\u6267\u884c\u7ed3\u679c<\/h2>\n<pre class=\"post-pre\"><code>2016\/07\/26\r\n16\/7\/26\r\nJul\r\nTue\r\n2\r\n\u706b\u66dc\u65e5\r\n03:02:10\r\nam 03:02:10\r\nAM 03:02:10\r\n<\/code><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>\u65e5\u671f\u51fd\u6570 \u4ece\u624b\u518c\u4e2d\u6458\u5f55 \u4ee3\u7801 m\u01ce) &lt;?php \/\/ YYYY\/MM\/DD\u5f62\u5f0f echo date(&#8221; [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[227],"class_list":["post-30944","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-227"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v21.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PHP\u7684\u65e5\u671f\u683c\u5f0f - Blog - Silicon Cloud<\/title>\n<meta name=\"description\" content=\"\u5173\u4e8ePHP\u7684\u65e5\u671f\u683c\u5f0f\u7684\u6280\u672f\u6587\u7ae0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.silicloud.com\/zh\/blog\/php\u7684\u65e5\u671f\u683c\u5f0f\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PHP\u7684\u65e5\u671f\u683c\u5f0f\" \/>\n<meta property=\"og:description\" content=\"\u5173\u4e8ePHP\u7684\u65e5\u671f\u683c\u5f0f\u7684\u6280\u672f\u6587\u7ae0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.silicloud.com\/zh\/blog\/php\u7684\u65e5\u671f\u683c\u5f0f\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog - Silicon Cloud\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-28T03:25:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-12T13:31:29+00:00\" \/>\n<meta name=\"author\" content=\"\u79d1, \u96c5\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u79d1, \u96c5\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.silicloud.com\/zh\/blog\/php%e7%9a%84%e6%97%a5%e6%9c%9f%e6%a0%bc%e5%bc%8f\/\",\"url\":\"https:\/\/www.silicloud.com\/zh\/blog\/php%e7%9a%84%e6%97%a5%e6%9c%9f%e6%a0%bc%e5%bc%8f\/\",\"name\":\"PHP\u7684\u65e5\u671f\u683c\u5f0f - Blog - Silicon Cloud\",\"isPartOf\":{\"@id\":\"https:\/\/www.silicloud.com\/zh\/blog\/#website\"},\"datePublished\":\"2023-01-28T03:25:57+00:00\",\"dateModified\":\"2025-08-12T13:31:29+00:00\",\"author\":{\"@id\":\"https:\/\/www.silicloud.com\/zh\/blog\/#\/schema\/person\/41e222757cdd2a3365361328bd79970a\"},\"description\":\"\u5173\u4e8ePHP\u7684\u65e5\u671f\u683c\u5f0f\u7684\u6280\u672f\u6587\u7ae0\",\"breadcrumb\":{\"@id\":\"https:\/\/www.silicloud.com\/zh\/blog\/php%e7%9a%84%e6%97%a5%e6%9c%9f%e6%a0%bc%e5%bc%8f\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.silicloud.com\/zh\/blog\/php%e7%9a%84%e6%97%a5%e6%9c%9f%e6%a0%bc%e5%bc%8f\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.silicloud.com\/zh\/blog\/php%e7%9a%84%e6%97%a5%e6%9c%9f%e6%a0%bc%e5%bc%8f\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9875\",\"item\":\"https:\/\/www.silicloud.com\/zh\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PHP\u7684\u65e5\u671f\u683c\u5f0f\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.silicloud.com\/zh\/blog\/#website\",\"url\":\"https:\/\/www.silicloud.com\/zh\/blog\/\",\"name\":\"Blog - Silicon Cloud\",\"description\":\"\",\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.silicloud.com\/zh\/blog\/#\/schema\/person\/41e222757cdd2a3365361328bd79970a\",\"name\":\"\u79d1, \u96c5\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\/\/www.silicloud.com\/zh\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1b2d3e00a7df03689797ebd4af8c5827ba5af936849a71050ec331f4cf902c5d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1b2d3e00a7df03689797ebd4af8c5827ba5af936849a71050ec331f4cf902c5d?s=96&d=mm&r=g\",\"caption\":\"\u79d1, \u96c5\"},\"url\":\"https:\/\/www.silicloud.com\/zh\/blog\/author\/keya\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\/\/www.silicloud.com\/zh\/blog\/php%e7%9a%84%e6%97%a5%e6%9c%9f%e6%a0%bc%e5%bc%8f\/#local-main-organization-logo\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Blog - Silicon Cloud\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"PHP\u7684\u65e5\u671f\u683c\u5f0f - Blog - Silicon Cloud","description":"\u5173\u4e8ePHP\u7684\u65e5\u671f\u683c\u5f0f\u7684\u6280\u672f\u6587\u7ae0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.silicloud.com\/zh\/blog\/php\u7684\u65e5\u671f\u683c\u5f0f\/","og_locale":"zh_CN","og_type":"article","og_title":"PHP\u7684\u65e5\u671f\u683c\u5f0f","og_description":"\u5173\u4e8ePHP\u7684\u65e5\u671f\u683c\u5f0f\u7684\u6280\u672f\u6587\u7ae0","og_url":"https:\/\/www.silicloud.com\/zh\/blog\/php\u7684\u65e5\u671f\u683c\u5f0f\/","og_site_name":"Blog - Silicon Cloud","article_published_time":"2023-01-28T03:25:57+00:00","article_modified_time":"2025-08-12T13:31:29+00:00","author":"\u79d1, \u96c5","twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005":"\u79d1, \u96c5","\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"1 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.silicloud.com\/zh\/blog\/php%e7%9a%84%e6%97%a5%e6%9c%9f%e6%a0%bc%e5%bc%8f\/","url":"https:\/\/www.silicloud.com\/zh\/blog\/php%e7%9a%84%e6%97%a5%e6%9c%9f%e6%a0%bc%e5%bc%8f\/","name":"PHP\u7684\u65e5\u671f\u683c\u5f0f - Blog - Silicon Cloud","isPartOf":{"@id":"https:\/\/www.silicloud.com\/zh\/blog\/#website"},"datePublished":"2023-01-28T03:25:57+00:00","dateModified":"2025-08-12T13:31:29+00:00","author":{"@id":"https:\/\/www.silicloud.com\/zh\/blog\/#\/schema\/person\/41e222757cdd2a3365361328bd79970a"},"description":"\u5173\u4e8ePHP\u7684\u65e5\u671f\u683c\u5f0f\u7684\u6280\u672f\u6587\u7ae0","breadcrumb":{"@id":"https:\/\/www.silicloud.com\/zh\/blog\/php%e7%9a%84%e6%97%a5%e6%9c%9f%e6%a0%bc%e5%bc%8f\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.silicloud.com\/zh\/blog\/php%e7%9a%84%e6%97%a5%e6%9c%9f%e6%a0%bc%e5%bc%8f\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.silicloud.com\/zh\/blog\/php%e7%9a%84%e6%97%a5%e6%9c%9f%e6%a0%bc%e5%bc%8f\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/www.silicloud.com\/zh\/blog\/"},{"@type":"ListItem","position":2,"name":"PHP\u7684\u65e5\u671f\u683c\u5f0f"}]},{"@type":"WebSite","@id":"https:\/\/www.silicloud.com\/zh\/blog\/#website","url":"https:\/\/www.silicloud.com\/zh\/blog\/","name":"Blog - Silicon Cloud","description":"","inLanguage":"zh-Hans"},{"@type":"Person","@id":"https:\/\/www.silicloud.com\/zh\/blog\/#\/schema\/person\/41e222757cdd2a3365361328bd79970a","name":"\u79d1, \u96c5","image":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/www.silicloud.com\/zh\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1b2d3e00a7df03689797ebd4af8c5827ba5af936849a71050ec331f4cf902c5d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1b2d3e00a7df03689797ebd4af8c5827ba5af936849a71050ec331f4cf902c5d?s=96&d=mm&r=g","caption":"\u79d1, \u96c5"},"url":"https:\/\/www.silicloud.com\/zh\/blog\/author\/keya\/"},{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/www.silicloud.com\/zh\/blog\/php%e7%9a%84%e6%97%a5%e6%9c%9f%e6%a0%bc%e5%bc%8f\/#local-main-organization-logo","url":"","contentUrl":"","caption":"Blog - Silicon Cloud"}]}},"_links":{"self":[{"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/posts\/30944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/comments?post=30944"}],"version-history":[{"count":2,"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/posts\/30944\/revisions"}],"predecessor-version":[{"id":95185,"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/posts\/30944\/revisions\/95185"}],"wp:attachment":[{"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/media?parent=30944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/categories?post=30944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/tags?post=30944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}