{"id":30475,"date":"2023-09-29T16:24:44","date_gmt":"2023-05-07T03:51:32","guid":{"rendered":"https:\/\/www.silicloud.com\/zh\/blog\/%e4%bd%bf%e7%94%a8php%e7%bc%96%e5%86%99%e4%b8%80%e4%b8%aaline%e5%85%8b%e9%9a%86%e5%ba%94%e7%94%a8\/"},"modified":"2025-08-12T19:20:44","modified_gmt":"2025-08-12T11:20:44","slug":"%e4%bd%bf%e7%94%a8php%e7%bc%96%e5%86%99%e4%b8%80%e4%b8%aaline%e5%85%8b%e9%9a%86%e5%ba%94%e7%94%a8","status":"publish","type":"post","link":"https:\/\/www.silicloud.com\/zh\/blog\/%e4%bd%bf%e7%94%a8php%e7%bc%96%e5%86%99%e4%b8%80%e4%b8%aaline%e5%85%8b%e9%9a%86%e5%ba%94%e7%94%a8\/","title":{"rendered":"\u4f7f\u7528PHP\u7f16\u5199\u4e00\u4e2aLINE\u514b\u9686\u5e94\u7528"},"content":{"rendered":"<p>\u6211\u5c1d\u8bd5\u521b\u5efa\u4e86\u4e00\u4e2a\u53ef\u4ee5\u53d1\u9001\u548c\u63a5\u6536\u6d88\u606f\u7684\u5e94\u7528\u7a0b\u5e8f\u3002<\/p>\n<div><img decoding=\"async\" class=\"post-images\" title=\"\" src=\"https:\/\/cdn.silicloud.com\/blog-img\/blog\/img\/657d079237434c4406bde6f1\/1-0.gif\" alt=\"ezgif.com-video-to-gif (2).gif\" \/><\/div>\n<h1>\u514b\u9686\u4ee3\u7801\u5e93\u3002<\/h1>\n<pre class=\"post-pre\"><code>git clone https:\/\/github.com\/gong-cha\/line-clone\r\n<\/code><\/pre>\n<p>\u6e90\u4ee3\u7801<\/p>\n<p>&nbsp;<\/p>\n<h1>\u5df2\u7ecf\u6267\u884c\u7684\u529f\u80fd<\/h1>\n<ul class=\"post-ul\">\n<li style=\"list-style-type: none;\">\n<ul class=\"post-ul\">\u65b0\u898f\u767b\u9332<\/ul>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul class=\"post-ul\">\n<li style=\"list-style-type: none;\">\n<ul class=\"post-ul\">\u30ed\u30b0\u30a4\u30f3<\/ul>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul class=\"post-ul\">\n<li style=\"list-style-type: none;\">\n<ul class=\"post-ul\">\u30ed\u30b0\u30a2\u30a6\u30c8<\/ul>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul class=\"post-ul\">\n<li style=\"list-style-type: none;\">\n<ul class=\"post-ul\">\u30a2\u30ab\u30a6\u30f3\u30c8\u524a\u9664<\/ul>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul class=\"post-ul\">\n<li style=\"list-style-type: none;\">\n<ul class=\"post-ul\">\u30ea\u30a2\u30eb\u30bf\u30a4\u30e0\u30e1\u30c3\u30bb\u30fc\u30b8\u53d7\u4fe1<\/ul>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul class=\"post-ul\">\n<li style=\"list-style-type: none;\">\n<ul class=\"post-ul\">\u753b\u50cf\u6295\u7a3f<\/ul>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul class=\"post-ul\">\n<li style=\"list-style-type: none;\">\n<ul class=\"post-ul\">\u30a2\u30a4\u30b3\u30f3\u8868\u793a<\/ul>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul class=\"post-ul\">\n<li style=\"list-style-type: none;\">\n<ul class=\"post-ul\">\u65e2\u8aad\u6a5f\u80fd<\/ul>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul class=\"post-ul\">\u30e6\u30fc\u30b6\u30fc\u4e00\u89a7\u306b\u6700\u65b0\u306e\u30e1\u30c3\u30bb\u30fc\u30b8\u8868\u793a<\/ul>\n<h1>\u6709\u6240\u610f\u8bc6<\/h1>\n<ul class=\"post-ul\">\n<li style=\"list-style-type: none;\">\n<ul class=\"post-ul\">\u30d7\u30ea\u30da\u30a2\u30fc\u30c9\u30b9\u30c6\u30fc\u30c8\u30e1\u30f3\u30c8<\/ul>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul class=\"post-ul\">\n<li style=\"list-style-type: none;\">\n<ul class=\"post-ul\">\u98f2\u3093\u3059\u6a5f\u80fd<\/ul>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul class=\"post-ul\">\u30c7\u30b6\u30a4\u30f3<\/ul>\n<h1>\u5373\u65f6\u6d88\u606f\u65b9\u6cd5\u7684\u8003\u8651<\/h1>\n<p>\u8003\u8651\u5982\u4f55\u5728\u6d4f\u89c8\u5668\u4e2d\u53d1\u9001\u901a\u77e5\u7684\u65b9\u6cd5<\/p>\n<ul class=\"post-ul\">\n<li style=\"list-style-type: none;\">\n<ul class=\"post-ul\">WebSockets<\/ul>\n<\/li>\n<\/ul>\n<p>\u30ec\u30f3\u30bf\u30eb\u30b5\u30fc\u30d0\u30fc\u3067\u306f\u3001push\u3067\u304d\u306a\u3044<\/p>\n<p>Server Sent Events (SSE)<\/p>\n<p>\u3088\u3055\u305d\u3046<\/p>\n<p>Long Polling<\/p>\n<p>Server Sent Events (SSE)\u306e\u65b9\u304c\u30b3\u30cd\u30af\u30b7\u30e7\u30f3\u7bc0\u7d04\u3067\u304d\u305d\u3046<\/p>\n<p>Short Polling<\/p>\n<p>Server Sent Events (SSE)\u306e\u65b9\u304c\u30ea\u30a2\u30eb\u30bf\u30a4\u30e0\u6027\u3042\u308a\u305d\u3046<\/p>\n<p>\u68c0\u6d4b\u5230\u65b0\u6d88\u606f<\/p>\n<ul class=\"post-ul\">\n<li style=\"list-style-type: none;\">\n<ul class=\"post-ul\">inotify<\/ul>\n<\/li>\n<\/ul>\n<p>\u30ec\u30f3\u30bf\u30eb\u30b5\u30fc\u30d0\u30fc\u306bphpize\u3067\u30a4\u30f3\u30b9\u30c8\u30fc\u30eb\u3067\u304d\u306a\u3044\u305f\u3081\u5374\u4e0b (php-devel\u304c\u30a4\u30f3\u30b9\u30c8\u30fc\u30eb\u3067\u304d\u306a\u3044)<\/p>\n<p>pcntl_signal<\/p>\n<p>php cli\u3067\u3057\u304b\u4f7f\u7528\u3067\u304d\u306a\u3044\u305f\u3081\u5374\u4e0b<\/p>\n<p>MySQL Binlog stream https:\/\/github.com\/bullsoft\/php-binlog<\/p>\n<p>\u30ec\u30f3\u30bf\u30eb\u30b5\u30fc\u30d0\u30fc\u306bphpize\u3067\u30a4\u30f3\u30b9\u30c8\u30fc\u30eb\u3067\u304d\u306a\u3044\u305f\u3081\u5374\u4e0b (php-devel\u304c\u30a4\u30f3\u30b9\u30c8\u30fc\u30eb\u3067\u304d\u306a\u3044)<\/p>\n<p>TCP\/UDP Socket<\/p>\n<p>Unix Domain Socket\u306e\u65b9\u304c\u30d7\u30ed\u30bb\u30b9\u9593\u901a\u4fe1\u306e\u52b9\u7387\u3088\u3055\u305d\u3046<\/p>\n<p>Unix Domain Socket (\u62bd\u8c61\u540d\u524d\u7a7a\u9593)<\/p>\n<p>\u3088\u3055\u305d\u3046<\/p>\n<h1>\u53c2\u8003\u7684\u7f51\u7ad9<\/h1>\n<p>\u6211\u8a66\u8457\u88fd\u4f5c\u4e86\u4e00\u500bLINE\u7684\u514b\u9686\u61c9\u7528\u7a0b\u5f0f\u3002<\/p>\n<p>&nbsp;<\/p>\n<p>\u4f7f\u7528React\u521b\u5efa\u4e86\u4e00\u4e2a\u5e94\u7528\u30109\u3011\u3010LINE \u514b\u9686\u3011\u3002<\/p>\n<p>&nbsp;<\/p>\n<p>\u7528React\u548cFirebase\u6559\u7a0b\u521b\u5efaLINE\u514b\u9686\u7684\u65b9\u6cd5-React\u00d7Firebase\u6559\u7a0b<\/p>\n<p>&nbsp;<\/p>\n<p>\u4e00\u4e2a\u6708\u5185\u5f00\u53d1\u51fa\u4e86LINE\u514b\u9686\uff01\u4ecb\u7ecd\u4e00\u4e0bLINE\u7684\u65b0\u5458\u5de5\u5de5\u7a0b\u5e08\u6280\u672f\u57f9\u8bad\u3002<\/p>\n<p>&nbsp;<\/p>\n<h1>\u603b\u7ed3<\/h1>\n<p>\u6211\u8fd8\u6709\u5f88\u591a\u4e0d\u660e\u767d\u7684\u5730\u65b9\uff0c\u4f46\u6211\u4f1a\u8fdb\u884c\u5c31\u4e1a\u6d3b\u52a8\uff0c\u4ee5\u6210\u4e3a\u4e00\u540d\u804c\u4e1a\u7a0b\u5e8f\u5458\u3002<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u6211\u5c1d\u8bd5\u521b\u5efa\u4e86\u4e00\u4e2a\u53ef\u4ee5\u53d1\u9001\u548c\u63a5\u6536\u6d88\u606f\u7684\u5e94\u7528\u7a0b\u5e8f\u3002 \u514b\u9686\u4ee3\u7801\u5e93\u3002 git clone https:\/\/github [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[227],"class_list":["post-30475","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-227"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v21.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u4f7f\u7528PHP\u7f16\u5199\u4e00\u4e2aLINE\u514b\u9686\u5e94\u7528 - Blog - Silicon Cloud<\/title>\n<meta name=\"description\" content=\"\u5173\u4e8e\u4f7f\u7528PHP\u7f16\u5199\u4e00\u4e2aLINE\u514b\u9686\u5e94\u7528\u7684\u6280\u672f\u6587\u7ae0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.silicloud.com\/zh\/blog\/\u4f7f\u7528php\u7f16\u5199\u4e00\u4e2aline\u514b\u9686\u5e94\u7528\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u4f7f\u7528PHP\u7f16\u5199\u4e00\u4e2aLINE\u514b\u9686\u5e94\u7528\" \/>\n<meta property=\"og:description\" content=\"\u5173\u4e8e\u4f7f\u7528PHP\u7f16\u5199\u4e00\u4e2aLINE\u514b\u9686\u5e94\u7528\u7684\u6280\u672f\u6587\u7ae0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.silicloud.com\/zh\/blog\/\u4f7f\u7528php\u7f16\u5199\u4e00\u4e2aline\u514b\u9686\u5e94\u7528\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog - Silicon Cloud\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-07T03:51:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-12T11:20:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.silicloud.com\/blog-img\/blog\/img\/657d079237434c4406bde6f1\/1-0.gif\" \/>\n<meta name=\"author\" content=\"\u79d1, \u96c5\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u79d1, \u96c5\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.silicloud.com\/zh\/blog\/%e4%bd%bf%e7%94%a8php%e7%bc%96%e5%86%99%e4%b8%80%e4%b8%aaline%e5%85%8b%e9%9a%86%e5%ba%94%e7%94%a8\/\",\"url\":\"https:\/\/www.silicloud.com\/zh\/blog\/%e4%bd%bf%e7%94%a8php%e7%bc%96%e5%86%99%e4%b8%80%e4%b8%aaline%e5%85%8b%e9%9a%86%e5%ba%94%e7%94%a8\/\",\"name\":\"\u4f7f\u7528PHP\u7f16\u5199\u4e00\u4e2aLINE\u514b\u9686\u5e94\u7528 - Blog - Silicon Cloud\",\"isPartOf\":{\"@id\":\"https:\/\/www.silicloud.com\/zh\/blog\/#website\"},\"datePublished\":\"2023-05-07T03:51:32+00:00\",\"dateModified\":\"2025-08-12T11:20:44+00:00\",\"author\":{\"@id\":\"https:\/\/www.silicloud.com\/zh\/blog\/#\/schema\/person\/41e222757cdd2a3365361328bd79970a\"},\"description\":\"\u5173\u4e8e\u4f7f\u7528PHP\u7f16\u5199\u4e00\u4e2aLINE\u514b\u9686\u5e94\u7528\u7684\u6280\u672f\u6587\u7ae0\",\"breadcrumb\":{\"@id\":\"https:\/\/www.silicloud.com\/zh\/blog\/%e4%bd%bf%e7%94%a8php%e7%bc%96%e5%86%99%e4%b8%80%e4%b8%aaline%e5%85%8b%e9%9a%86%e5%ba%94%e7%94%a8\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.silicloud.com\/zh\/blog\/%e4%bd%bf%e7%94%a8php%e7%bc%96%e5%86%99%e4%b8%80%e4%b8%aaline%e5%85%8b%e9%9a%86%e5%ba%94%e7%94%a8\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.silicloud.com\/zh\/blog\/%e4%bd%bf%e7%94%a8php%e7%bc%96%e5%86%99%e4%b8%80%e4%b8%aaline%e5%85%8b%e9%9a%86%e5%ba%94%e7%94%a8\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9875\",\"item\":\"https:\/\/www.silicloud.com\/zh\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u4f7f\u7528PHP\u7f16\u5199\u4e00\u4e2aLINE\u514b\u9686\u5e94\u7528\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.silicloud.com\/zh\/blog\/#website\",\"url\":\"https:\/\/www.silicloud.com\/zh\/blog\/\",\"name\":\"Blog - Silicon Cloud\",\"description\":\"\",\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.silicloud.com\/zh\/blog\/#\/schema\/person\/41e222757cdd2a3365361328bd79970a\",\"name\":\"\u79d1, \u96c5\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\/\/www.silicloud.com\/zh\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1b2d3e00a7df03689797ebd4af8c5827ba5af936849a71050ec331f4cf902c5d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1b2d3e00a7df03689797ebd4af8c5827ba5af936849a71050ec331f4cf902c5d?s=96&d=mm&r=g\",\"caption\":\"\u79d1, \u96c5\"},\"url\":\"https:\/\/www.silicloud.com\/zh\/blog\/author\/keya\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\/\/www.silicloud.com\/zh\/blog\/%e4%bd%bf%e7%94%a8php%e7%bc%96%e5%86%99%e4%b8%80%e4%b8%aaline%e5%85%8b%e9%9a%86%e5%ba%94%e7%94%a8\/#local-main-organization-logo\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Blog - Silicon Cloud\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u4f7f\u7528PHP\u7f16\u5199\u4e00\u4e2aLINE\u514b\u9686\u5e94\u7528 - Blog - Silicon Cloud","description":"\u5173\u4e8e\u4f7f\u7528PHP\u7f16\u5199\u4e00\u4e2aLINE\u514b\u9686\u5e94\u7528\u7684\u6280\u672f\u6587\u7ae0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.silicloud.com\/zh\/blog\/\u4f7f\u7528php\u7f16\u5199\u4e00\u4e2aline\u514b\u9686\u5e94\u7528\/","og_locale":"zh_CN","og_type":"article","og_title":"\u4f7f\u7528PHP\u7f16\u5199\u4e00\u4e2aLINE\u514b\u9686\u5e94\u7528","og_description":"\u5173\u4e8e\u4f7f\u7528PHP\u7f16\u5199\u4e00\u4e2aLINE\u514b\u9686\u5e94\u7528\u7684\u6280\u672f\u6587\u7ae0","og_url":"https:\/\/www.silicloud.com\/zh\/blog\/\u4f7f\u7528php\u7f16\u5199\u4e00\u4e2aline\u514b\u9686\u5e94\u7528\/","og_site_name":"Blog - Silicon Cloud","article_published_time":"2023-05-07T03:51:32+00:00","article_modified_time":"2025-08-12T11:20:44+00:00","og_image":[{"url":"https:\/\/cdn.silicloud.com\/blog-img\/blog\/img\/657d079237434c4406bde6f1\/1-0.gif"}],"author":"\u79d1, \u96c5","twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005":"\u79d1, \u96c5","\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"1 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.silicloud.com\/zh\/blog\/%e4%bd%bf%e7%94%a8php%e7%bc%96%e5%86%99%e4%b8%80%e4%b8%aaline%e5%85%8b%e9%9a%86%e5%ba%94%e7%94%a8\/","url":"https:\/\/www.silicloud.com\/zh\/blog\/%e4%bd%bf%e7%94%a8php%e7%bc%96%e5%86%99%e4%b8%80%e4%b8%aaline%e5%85%8b%e9%9a%86%e5%ba%94%e7%94%a8\/","name":"\u4f7f\u7528PHP\u7f16\u5199\u4e00\u4e2aLINE\u514b\u9686\u5e94\u7528 - Blog - Silicon Cloud","isPartOf":{"@id":"https:\/\/www.silicloud.com\/zh\/blog\/#website"},"datePublished":"2023-05-07T03:51:32+00:00","dateModified":"2025-08-12T11:20:44+00:00","author":{"@id":"https:\/\/www.silicloud.com\/zh\/blog\/#\/schema\/person\/41e222757cdd2a3365361328bd79970a"},"description":"\u5173\u4e8e\u4f7f\u7528PHP\u7f16\u5199\u4e00\u4e2aLINE\u514b\u9686\u5e94\u7528\u7684\u6280\u672f\u6587\u7ae0","breadcrumb":{"@id":"https:\/\/www.silicloud.com\/zh\/blog\/%e4%bd%bf%e7%94%a8php%e7%bc%96%e5%86%99%e4%b8%80%e4%b8%aaline%e5%85%8b%e9%9a%86%e5%ba%94%e7%94%a8\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.silicloud.com\/zh\/blog\/%e4%bd%bf%e7%94%a8php%e7%bc%96%e5%86%99%e4%b8%80%e4%b8%aaline%e5%85%8b%e9%9a%86%e5%ba%94%e7%94%a8\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.silicloud.com\/zh\/blog\/%e4%bd%bf%e7%94%a8php%e7%bc%96%e5%86%99%e4%b8%80%e4%b8%aaline%e5%85%8b%e9%9a%86%e5%ba%94%e7%94%a8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/www.silicloud.com\/zh\/blog\/"},{"@type":"ListItem","position":2,"name":"\u4f7f\u7528PHP\u7f16\u5199\u4e00\u4e2aLINE\u514b\u9686\u5e94\u7528"}]},{"@type":"WebSite","@id":"https:\/\/www.silicloud.com\/zh\/blog\/#website","url":"https:\/\/www.silicloud.com\/zh\/blog\/","name":"Blog - Silicon Cloud","description":"","inLanguage":"zh-Hans"},{"@type":"Person","@id":"https:\/\/www.silicloud.com\/zh\/blog\/#\/schema\/person\/41e222757cdd2a3365361328bd79970a","name":"\u79d1, \u96c5","image":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/www.silicloud.com\/zh\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1b2d3e00a7df03689797ebd4af8c5827ba5af936849a71050ec331f4cf902c5d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1b2d3e00a7df03689797ebd4af8c5827ba5af936849a71050ec331f4cf902c5d?s=96&d=mm&r=g","caption":"\u79d1, \u96c5"},"url":"https:\/\/www.silicloud.com\/zh\/blog\/author\/keya\/"},{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/www.silicloud.com\/zh\/blog\/%e4%bd%bf%e7%94%a8php%e7%bc%96%e5%86%99%e4%b8%80%e4%b8%aaline%e5%85%8b%e9%9a%86%e5%ba%94%e7%94%a8\/#local-main-organization-logo","url":"","contentUrl":"","caption":"Blog - Silicon Cloud"}]}},"_links":{"self":[{"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/posts\/30475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/comments?post=30475"}],"version-history":[{"count":2,"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/posts\/30475\/revisions"}],"predecessor-version":[{"id":95456,"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/posts\/30475\/revisions\/95456"}],"wp:attachment":[{"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/media?parent=30475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/categories?post=30475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.silicloud.com\/zh\/blog\/wp-json\/wp\/v2\/tags?post=30475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}