{"id":90787,"date":"2024-03-21T12:59:26","date_gmt":"2024-03-21T03:59:26","guid":{"rendered":"https:\/\/www.silicloud.com\/ja\/blog\/pl-sql%e3%81%a7%e6%96%87%e5%ad%97%e5%88%97%e3%82%92%e6%8a%bd%e5%87%ba%e3%81%99%e3%82%8b%e6%96%b9%e6%b3%95%e3%81%af%ef%bc%9f\/"},"modified":"2024-03-27T09:55:29","modified_gmt":"2024-03-27T00:55:29","slug":"pl-sql%e3%81%a7%e6%96%87%e5%ad%97%e5%88%97%e3%82%92%e6%8a%bd%e5%87%ba%e3%81%99%e3%82%8b%e6%96%b9%e6%b3%95%e3%81%af%ef%bc%9f","status":"publish","type":"post","link":"https:\/\/www.silicloud.com\/ja\/blog\/pl-sql%e3%81%a7%e6%96%87%e5%ad%97%e5%88%97%e3%82%92%e6%8a%bd%e5%87%ba%e3%81%99%e3%82%8b%e6%96%b9%e6%b3%95%e3%81%af%ef%bc%9f\/","title":{"rendered":"PL\/SQL\u3067\u6587\u5b57\u5217\u3092\u62bd\u51fa\u3059\u308b\u65b9\u6cd5\u306f\uff1f"},"content":{"rendered":"<p>PL\/SQL\u3067\u306f\u3001SUBSTR\u95a2\u6570\u3092\u4f7f\u7528\u3057\u3066\u6587\u5b57\u5217\u3092\u62bd\u51fa\u3067\u304d\u307e\u3059\u3002SUBSTR\u95a2\u6570\u306f3\u3064\u306e\u30d1\u30e9\u30e1\u30fc\u30bf\u3092\u53d7\u3051\u53d6\u308a\u307e\u3059\u3002\u62bd\u51fa\u5bfe\u8c61\u306e\u6587\u5b57\u5217\u3001\u958b\u59cb\u4f4d\u7f6e\u3001\u304a\u3088\u3073\u62bd\u51fa\u3059\u308b\u9577\u3055\u3067\u3059\u3002<\/p>\n<p>\u4ee5\u4e0b\u306bSUBSTR\u95a2\u6570\u3092\u4f7f\u3063\u305f\u6587\u5b57\u5217\u306e\u4e00\u90e8\u3092\u53d6\u308a\u51fa\u3059\u4f8b\u3092\u793a\u3057\u307e\u3059\u3002<\/p>\n<pre class=\"post-pre\"><code><span class=\"hljs-keyword\">DECLARE<\/span>\r\n   str VARCHAR2(<span class=\"hljs-number\">100<\/span>) :<span class=\"hljs-operator\">=<\/span> <span class=\"hljs-string\">'Hello World'<\/span>;\r\n   substr_str VARCHAR2(<span class=\"hljs-number\">100<\/span>);\r\n<span class=\"hljs-keyword\">BEGIN<\/span>\r\n   substr_str :<span class=\"hljs-operator\">=<\/span> SUBSTR(str, <span class=\"hljs-number\">7<\/span>, <span class=\"hljs-number\">5<\/span>); <span class=\"hljs-comment\">-- \u4ece\u7b2c7\u4e2a\u4f4d\u7f6e\u5f00\u59cb\u622a\u53d65\u4e2a\u5b57\u7b26<\/span>\r\n   DBMS_OUTPUT.PUT_LINE(substr_str); <span class=\"hljs-comment\">-- \u8f93\u51fa: World<\/span>\r\n<span class=\"hljs-keyword\">END<\/span>;\r\n<span class=\"hljs-operator\">\/<\/span>\r\n<\/code><\/pre>\n<p>\u4e0a\u306e\u4f8b\u3067\u306f\u3001SUBSTR \u95a2\u6570\u306f\u4f4d\u7f6e 7 \u304b\u3089\u9577\u3055 5 \u306e\u90e8\u5206\u6587\u5b57\u5217\u3092\u53d6\u5f97\u3057\u3001\u7d50\u679c\u3092 substr_str \u5909\u6570\u306b\u4ee3\u5165\u3057\u307e\u3059\u3002\u6700\u5f8c\u306b\u3001DBMS_OUTPUT.PUT_LINE \u30b9\u30c6\u30fc\u30c8\u30e1\u30f3\u30c8\u3092\u4f7f\u7528\u3057\u3066\u3001\u53d6\u5f97\u3057\u305f\u6587\u5b57\u5217\u3092\u30b3\u30f3\u30bd\u30fc\u30eb\u306b\u51fa\u529b\u3057\u307e\u3059\u3002<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PL\/SQL\u3067\u306f\u3001SUBSTR\u95a2\u6570\u3092\u4f7f\u7528\u3057\u3066\u6587\u5b57\u5217\u3092\u62bd\u51fa\u3067\u304d\u307e\u3059\u3002SUBSTR\u95a2\u6570\u306f3\u3064\u306e\u30d1\u30e9\u30e1\u30fc\u30bf\u3092\u53d7\u3051\u53d6\u308a\u307e\u3059\u3002\u62bd\u51fa\u5bfe\u8c61\u306e\u6587\u5b57\u5217\u3001\u958b\u59cb\u4f4d\u7f6e\u3001\u304a\u3088\u3073\u62bd\u51fa\u3059\u308b\u9577\u3055\u3067\u3059\u3002 \u4ee5\u4e0b\u306bSUBSTR\u95a2\u6570\u3092\u4f7f\u3063\u305f\u6587\u5b57\u5217\u306e\u4e00\u90e8\u3092\u53d6\u308a\u51fa [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-90787","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v21.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PL\/SQL\u3067\u6587\u5b57\u5217\u3092\u62bd\u51fa\u3059\u308b\u65b9\u6cd5\u306f\uff1f - Blog - Silicon Cloud<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.silicloud.com\/ja\/blog\/pl-sql\u3067\u6587\u5b57\u5217\u3092\u62bd\u51fa\u3059\u308b\u65b9\u6cd5\u306f\uff1f\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PL\/SQL\u3067\u6587\u5b57\u5217\u3092\u62bd\u51fa\u3059\u308b\u65b9\u6cd5\u306f\uff1f\" \/>\n<meta property=\"og:description\" content=\"PL\/SQL\u3067\u306f\u3001SUBSTR\u95a2\u6570\u3092\u4f7f\u7528\u3057\u3066\u6587\u5b57\u5217\u3092\u62bd\u51fa\u3067\u304d\u307e\u3059\u3002SUBSTR\u95a2\u6570\u306f3\u3064\u306e\u30d1\u30e9\u30e1\u30fc\u30bf\u3092\u53d7\u3051\u53d6\u308a\u307e\u3059\u3002\u62bd\u51fa\u5bfe\u8c61\u306e\u6587\u5b57\u5217\u3001\u958b\u59cb\u4f4d\u7f6e\u3001\u304a\u3088\u3073\u62bd\u51fa\u3059\u308b\u9577\u3055\u3067\u3059\u3002 \u4ee5\u4e0b\u306bSUBSTR\u95a2\u6570\u3092\u4f7f\u3063\u305f\u6587\u5b57\u5217\u306e\u4e00\u90e8\u3092\u53d6\u308a\u51fa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.silicloud.com\/ja\/blog\/pl-sql\u3067\u6587\u5b57\u5217\u3092\u62bd\u51fa\u3059\u308b\u65b9\u6cd5\u306f\uff1f\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog - Silicon Cloud\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-21T03:59:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-27T00:55:29+00:00\" \/>\n<meta name=\"author\" content=\"\u82bd\u4f9d, \u96e8\u591c\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u57f7\u7b46\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u82bd\u4f9d, \u96e8\u591c\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/pl-sql%e3%81%a7%e6%96%87%e5%ad%97%e5%88%97%e3%82%92%e6%8a%bd%e5%87%ba%e3%81%99%e3%82%8b%e6%96%b9%e6%b3%95%e3%81%af%ef%bc%9f\/\",\"url\":\"https:\/\/www.silicloud.com\/ja\/blog\/pl-sql%e3%81%a7%e6%96%87%e5%ad%97%e5%88%97%e3%82%92%e6%8a%bd%e5%87%ba%e3%81%99%e3%82%8b%e6%96%b9%e6%b3%95%e3%81%af%ef%bc%9f\/\",\"name\":\"PL\/SQL\u3067\u6587\u5b57\u5217\u3092\u62bd\u51fa\u3059\u308b\u65b9\u6cd5\u306f\uff1f - Blog - Silicon Cloud\",\"isPartOf\":{\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#website\"},\"datePublished\":\"2024-03-21T03:59:26+00:00\",\"dateModified\":\"2024-03-27T00:55:29+00:00\",\"author\":{\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/aeb60a7861f2f002b54c66bd65bc6c27\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/pl-sql%e3%81%a7%e6%96%87%e5%ad%97%e5%88%97%e3%82%92%e6%8a%bd%e5%87%ba%e3%81%99%e3%82%8b%e6%96%b9%e6%b3%95%e3%81%af%ef%bc%9f\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.silicloud.com\/ja\/blog\/pl-sql%e3%81%a7%e6%96%87%e5%ad%97%e5%88%97%e3%82%92%e6%8a%bd%e5%87%ba%e3%81%99%e3%82%8b%e6%96%b9%e6%b3%95%e3%81%af%ef%bc%9f\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/pl-sql%e3%81%a7%e6%96%87%e5%ad%97%e5%88%97%e3%82%92%e6%8a%bd%e5%87%ba%e3%81%99%e3%82%8b%e6%96%b9%e6%b3%95%e3%81%af%ef%bc%9f\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9875\",\"item\":\"https:\/\/www.silicloud.com\/ja\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PL\/SQL\u3067\u6587\u5b57\u5217\u3092\u62bd\u51fa\u3059\u308b\u65b9\u6cd5\u306f\uff1f\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#website\",\"url\":\"https:\/\/www.silicloud.com\/ja\/blog\/\",\"name\":\"Blog - Silicon Cloud\",\"description\":\"\",\"inLanguage\":\"ja\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/aeb60a7861f2f002b54c66bd65bc6c27\",\"name\":\"\u82bd\u4f9d, \u96e8\u591c\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6305fe5cabc2b854c1208975a47fbf3f8cef3f7cd775b94dceedbe59b74a8010?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6305fe5cabc2b854c1208975a47fbf3f8cef3f7cd775b94dceedbe59b74a8010?s=96&d=mm&r=g\",\"caption\":\"\u82bd\u4f9d, \u96e8\u591c\"},\"url\":\"https:\/\/www.silicloud.com\/ja\/blog\/author\/meiamaya\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/pl-sql%e3%81%a7%e6%96%87%e5%ad%97%e5%88%97%e3%82%92%e6%8a%bd%e5%87%ba%e3%81%99%e3%82%8b%e6%96%b9%e6%b3%95%e3%81%af%ef%bc%9f\/#local-main-organization-logo\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Blog - Silicon Cloud\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"PL\/SQL\u3067\u6587\u5b57\u5217\u3092\u62bd\u51fa\u3059\u308b\u65b9\u6cd5\u306f\uff1f - Blog - Silicon Cloud","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.silicloud.com\/ja\/blog\/pl-sql\u3067\u6587\u5b57\u5217\u3092\u62bd\u51fa\u3059\u308b\u65b9\u6cd5\u306f\uff1f\/","og_locale":"ja_JP","og_type":"article","og_title":"PL\/SQL\u3067\u6587\u5b57\u5217\u3092\u62bd\u51fa\u3059\u308b\u65b9\u6cd5\u306f\uff1f","og_description":"PL\/SQL\u3067\u306f\u3001SUBSTR\u95a2\u6570\u3092\u4f7f\u7528\u3057\u3066\u6587\u5b57\u5217\u3092\u62bd\u51fa\u3067\u304d\u307e\u3059\u3002SUBSTR\u95a2\u6570\u306f3\u3064\u306e\u30d1\u30e9\u30e1\u30fc\u30bf\u3092\u53d7\u3051\u53d6\u308a\u307e\u3059\u3002\u62bd\u51fa\u5bfe\u8c61\u306e\u6587\u5b57\u5217\u3001\u958b\u59cb\u4f4d\u7f6e\u3001\u304a\u3088\u3073\u62bd\u51fa\u3059\u308b\u9577\u3055\u3067\u3059\u3002 \u4ee5\u4e0b\u306bSUBSTR\u95a2\u6570\u3092\u4f7f\u3063\u305f\u6587\u5b57\u5217\u306e\u4e00\u90e8\u3092\u53d6\u308a\u51fa [&hellip;]","og_url":"https:\/\/www.silicloud.com\/ja\/blog\/pl-sql\u3067\u6587\u5b57\u5217\u3092\u62bd\u51fa\u3059\u308b\u65b9\u6cd5\u306f\uff1f\/","og_site_name":"Blog - Silicon Cloud","article_published_time":"2024-03-21T03:59:26+00:00","article_modified_time":"2024-03-27T00:55:29+00:00","author":"\u82bd\u4f9d, \u96e8\u591c","twitter_card":"summary_large_image","twitter_misc":{"\u57f7\u7b46\u8005":"\u82bd\u4f9d, \u96e8\u591c"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.silicloud.com\/ja\/blog\/pl-sql%e3%81%a7%e6%96%87%e5%ad%97%e5%88%97%e3%82%92%e6%8a%bd%e5%87%ba%e3%81%99%e3%82%8b%e6%96%b9%e6%b3%95%e3%81%af%ef%bc%9f\/","url":"https:\/\/www.silicloud.com\/ja\/blog\/pl-sql%e3%81%a7%e6%96%87%e5%ad%97%e5%88%97%e3%82%92%e6%8a%bd%e5%87%ba%e3%81%99%e3%82%8b%e6%96%b9%e6%b3%95%e3%81%af%ef%bc%9f\/","name":"PL\/SQL\u3067\u6587\u5b57\u5217\u3092\u62bd\u51fa\u3059\u308b\u65b9\u6cd5\u306f\uff1f - Blog - Silicon Cloud","isPartOf":{"@id":"https:\/\/www.silicloud.com\/ja\/blog\/#website"},"datePublished":"2024-03-21T03:59:26+00:00","dateModified":"2024-03-27T00:55:29+00:00","author":{"@id":"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/aeb60a7861f2f002b54c66bd65bc6c27"},"breadcrumb":{"@id":"https:\/\/www.silicloud.com\/ja\/blog\/pl-sql%e3%81%a7%e6%96%87%e5%ad%97%e5%88%97%e3%82%92%e6%8a%bd%e5%87%ba%e3%81%99%e3%82%8b%e6%96%b9%e6%b3%95%e3%81%af%ef%bc%9f\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.silicloud.com\/ja\/blog\/pl-sql%e3%81%a7%e6%96%87%e5%ad%97%e5%88%97%e3%82%92%e6%8a%bd%e5%87%ba%e3%81%99%e3%82%8b%e6%96%b9%e6%b3%95%e3%81%af%ef%bc%9f\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.silicloud.com\/ja\/blog\/pl-sql%e3%81%a7%e6%96%87%e5%ad%97%e5%88%97%e3%82%92%e6%8a%bd%e5%87%ba%e3%81%99%e3%82%8b%e6%96%b9%e6%b3%95%e3%81%af%ef%bc%9f\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/www.silicloud.com\/ja\/blog\/"},{"@type":"ListItem","position":2,"name":"PL\/SQL\u3067\u6587\u5b57\u5217\u3092\u62bd\u51fa\u3059\u308b\u65b9\u6cd5\u306f\uff1f"}]},{"@type":"WebSite","@id":"https:\/\/www.silicloud.com\/ja\/blog\/#website","url":"https:\/\/www.silicloud.com\/ja\/blog\/","name":"Blog - Silicon Cloud","description":"","inLanguage":"ja"},{"@type":"Person","@id":"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/aeb60a7861f2f002b54c66bd65bc6c27","name":"\u82bd\u4f9d, \u96e8\u591c","image":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6305fe5cabc2b854c1208975a47fbf3f8cef3f7cd775b94dceedbe59b74a8010?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6305fe5cabc2b854c1208975a47fbf3f8cef3f7cd775b94dceedbe59b74a8010?s=96&d=mm&r=g","caption":"\u82bd\u4f9d, \u96e8\u591c"},"url":"https:\/\/www.silicloud.com\/ja\/blog\/author\/meiamaya\/"},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.silicloud.com\/ja\/blog\/pl-sql%e3%81%a7%e6%96%87%e5%ad%97%e5%88%97%e3%82%92%e6%8a%bd%e5%87%ba%e3%81%99%e3%82%8b%e6%96%b9%e6%b3%95%e3%81%af%ef%bc%9f\/#local-main-organization-logo","url":"","contentUrl":"","caption":"Blog - Silicon Cloud"}]}},"_links":{"self":[{"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/posts\/90787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/comments?post=90787"}],"version-history":[{"count":2,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/posts\/90787\/revisions"}],"predecessor-version":[{"id":187288,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/posts\/90787\/revisions\/187288"}],"wp:attachment":[{"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/media?parent=90787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/categories?post=90787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/tags?post=90787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}