{"id":86316,"date":"2024-03-21T06:51:23","date_gmt":"2024-03-20T21:51:23","guid":{"rendered":"https:\/\/www.silicloud.com\/ja\/blog\/nginx%e3%81%a7%e9%9d%99%e7%9a%84%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e5%8f%96%e5%be%97%e3%81%a7%e3%81%8d%e3%81%aa%e3%81%84%e5%a0%b4%e5%90%88%e3%81%ae%e8%a7%a3%e6%b1%ba%e7%ad%96\/"},"modified":"2024-04-04T21:16:58","modified_gmt":"2024-04-04T12:16:58","slug":"nginx%e3%81%a7%e9%9d%99%e7%9a%84%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e5%8f%96%e5%be%97%e3%81%a7%e3%81%8d%e3%81%aa%e3%81%84%e5%a0%b4%e5%90%88%e3%81%ae%e8%a7%a3%e6%b1%ba%e7%ad%96","status":"publish","type":"post","link":"https:\/\/www.silicloud.com\/ja\/blog\/nginx%e3%81%a7%e9%9d%99%e7%9a%84%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e5%8f%96%e5%be%97%e3%81%a7%e3%81%8d%e3%81%aa%e3%81%84%e5%a0%b4%e5%90%88%e3%81%ae%e8%a7%a3%e6%b1%ba%e7%ad%96\/","title":{"rendered":"Nginx\u3067\u9759\u7684\u30d5\u30a1\u30a4\u30eb\u3092\u53d6\u5f97\u3067\u304d\u306a\u3044\u5834\u5408\u306e\u89e3\u6c7a\u7b56"},"content":{"rendered":"<p>Nginx\u3067\u9759\u7684\u30d5\u30a1\u30a4\u30eb\u306e\u53d6\u5f97\u304c\u3067\u304d\u306a\u3044\u5834\u5408\u3001\u4ee5\u4e0b\u306e\u89e3\u6c7a\u7b56\u3092\u8a66\u3057\u3066\u304f\u3060\u3055\u3044\u3002<\/p>\n<ol>\n<li>\u9759\u7684\u30d5\u30a1\u30a4\u30eb\u306e\u30d1\u30b9\u304c\u6b63\u3057\u304f\u8a2d\u5b9a\u3055\u308c\u3066\u3044\u308b\u304b\u78ba\u8a8d\uff1aNginx \u8a2d\u5b9a\u30d5\u30a1\u30a4\u30eb\u306e\u9759\u7684\u30d5\u30a1\u30a4\u30eb\u30d1\u30b9\u304c\u6b63\u3057\u304f\u8a2d\u5b9a\u3055\u308c\u3066\u3044\u308b\u304b\u78ba\u8a8d\u3059\u308b\u3002\u30d5\u30a1\u30a4\u30eb\u30d1\u30b9\u3001\u30d5\u30a1\u30a4\u30eb\u540d\u3001\u30d5\u30a1\u30a4\u30eb\u30bf\u30a4\u30d7\u306e\u7db4\u308a\u3082\u542b\u3080\u3002<\/li>\n<li>\u30d5\u30a1\u30a4\u30eb\u6a29\u9650\u3092\u78ba\u8a8d\u3059\u308b: Nginx\u306b\u9759\u7684\u30d5\u30a1\u30a4\u30eb\u306e\u8aad\u307f\u53d6\u308a\u6a29\u9650\u304c\u3042\u308b\u3053\u3068\u3092\u78ba\u8a8d\u3057\u307e\u3059\u3002\u30d5\u30a1\u30a4\u30eb\u6a29\u9650\u306f\u6b21\u306e\u30b3\u30de\u30f3\u30c9\u3067\u5909\u66f4\u3067\u304d\u307e\u3059:<\/li>\n<li>\u30d5\u30a1\u30a4\u30eb\u3092sudo chmod +r\u3057\u307e\u3059<\/li>\n<li>Nginx\u306e\u8a2d\u5b9a\u30d5\u30a1\u30a4\u30eb\u3092\u78ba\u8a8d\uff1a\u9759\u7684\u306a\u30d5\u30a1\u30a4\u30eb\u3078\u306e\u30a2\u30af\u30bb\u30b9\u304a\u3088\u3073\u30a2\u30af\u30bb\u30b9\u6a29\u306e\u8a2d\u5b9a\u3092\u542b\u3080Nginx\u306e\u8a2d\u5b9a\u30d5\u30a1\u30a4\u30eb\u3092\u691c\u8a3c\u3057\u307e\u3059\u3002<\/li>\n<li>Nginx\u30e6\u30fc\u30b6\u30fc\u3068\u30b0\u30eb\u30fc\u30d7\u306e\u30d1\u30fc\u30df\u30c3\u30b7\u30e7\u30f3\u3092\u78ba\u8a8d\u3059\u308b\uff1aNginx\u3067\u5229\u7528\u3055\u308c\u3066\u3044\u308b\u30e6\u30fc\u30b6\u30fc\u3068\u30b0\u30eb\u30fc\u30d7\u306b\u3001\u9759\u7684\u30d5\u30a1\u30a4\u30eb\u3092\u95b2\u89a7\u3059\u308b\u6a29\u9650\u304c\u3042\u308b\u3053\u3068\u3092\u78ba\u8a8d\u3057\u3066\u304f\u3060\u3055\u3044\u3002Nginx\u8a2d\u5b9a\u30d5\u30a1\u30a4\u30eb\u3067user\u30c7\u30a3\u30ec\u30af\u30c6\u30a3\u30d6\u3092\u8a2d\u5b9a\u3057\u3066\u3001Nginx\u3067\u5229\u7528\u3055\u308c\u308b\u30e6\u30fc\u30b6\u30fc\u3068\u30b0\u30eb\u30fc\u30d7\u3092\u6307\u5b9a\u3067\u304d\u307e\u3059\u3002<\/li>\n<li>Nginx \u306e\u30a2\u30af\u30bb\u30b9\u30ed\u30b0\u30fb\u30a8\u30e9\u30fc\u30ed\u30b0\u3092\u78ba\u8a8d\u3059\u308b: \u9759\u7684\u30d5\u30a1\u30a4\u30eb\u3078\u306e\u30a2\u30af\u30bb\u30b9\u306b\u3064\u3044\u3066\u8a73\u7d30\u3092\u78ba\u8a8d\u3059\u308b\u306b\u306f\u3001Nginx \u306e\u30a2\u30af\u30bb\u30b9\u30ed\u30b0\u304a\u3088\u3073\u30a8\u30e9\u30fc\u30ed\u30b0\u3092\u78ba\u8a8d\u3057\u307e\u3059\u3002\u4e0b\u8a18\u30b3\u30de\u30f3\u30c9\u304b\u3089\u30ed\u30b0\u30d5\u30a1\u30a4\u30eb\u3092\u78ba\u8a8d\u3067\u304d\u307e\u3059:<\/li>\n<li>tail -f \/var\/log\/nginx\/access.log &amp;<br \/>\ntail -f \/var\/log\/nginx\/error.log<\/li>\n<li>\u9759\u7684\u306a\u30d5\u30a1\u30a4\u30eb\u3078\u306e\u30a2\u30af\u30bb\u30b9\u3092\u59a8\u3052\u308b\u4ed6\u306e\u554f\u984c\u304c\u306a\u304f\u3066\u3001Nginx \u30b5\u30fc\u30d3\u30b9\u304c\u78ba\u5b9f\u306b\u52d5\u4f5c\u3057\u3066\u3044\u308b\u3053\u3068\u3092\u78ba\u8a8d\u3057\u3066\u304f\u3060\u3055\u3044\u3002<\/li>\n<\/ol>\n<p>\u305d\u308c\u3067\u3082\u554f\u984c\u304c\u89e3\u6c7a\u3057\u306a\u3044\u5834\u5408\u306f\u3001Nginx \u306e\u518d\u30a4\u30f3\u30b9\u30c8\u30fc\u30eb\u3092\u8a66\u3059\u304b\u3001\u5c02\u9580\u5bb6\u306e\u6280\u8853\u30b5\u30dd\u30fc\u30c8\u3092\u53d7\u3051\u308b\u3053\u3068\u304c\u3067\u304d\u307e\u3059\u3002<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nginx\u3067\u9759\u7684\u30d5\u30a1\u30a4\u30eb\u306e\u53d6\u5f97\u304c\u3067\u304d\u306a\u3044\u5834\u5408\u3001\u4ee5\u4e0b\u306e\u89e3\u6c7a\u7b56\u3092\u8a66\u3057\u3066\u304f\u3060\u3055\u3044\u3002 \u9759\u7684\u30d5\u30a1\u30a4\u30eb\u306e\u30d1\u30b9\u304c\u6b63\u3057\u304f\u8a2d\u5b9a\u3055\u308c\u3066\u3044\u308b\u304b\u78ba\u8a8d\uff1aNginx \u8a2d\u5b9a\u30d5\u30a1\u30a4\u30eb\u306e\u9759\u7684\u30d5\u30a1\u30a4\u30eb\u30d1\u30b9\u304c\u6b63\u3057\u304f\u8a2d\u5b9a\u3055\u308c\u3066\u3044\u308b\u304b\u78ba\u8a8d\u3059\u308b\u3002\u30d5\u30a1\u30a4\u30eb\u30d1\u30b9\u3001\u30d5\u30a1 [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-86316","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v21.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nginx\u3067\u9759\u7684\u30d5\u30a1\u30a4\u30eb\u3092\u53d6\u5f97\u3067\u304d\u306a\u3044\u5834\u5408\u306e\u89e3\u6c7a\u7b56 - Blog - Silicon Cloud<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.silicloud.com\/ja\/blog\/nginx\u3067\u9759\u7684\u30d5\u30a1\u30a4\u30eb\u3092\u53d6\u5f97\u3067\u304d\u306a\u3044\u5834\u5408\u306e\u89e3\u6c7a\u7b56\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nginx\u3067\u9759\u7684\u30d5\u30a1\u30a4\u30eb\u3092\u53d6\u5f97\u3067\u304d\u306a\u3044\u5834\u5408\u306e\u89e3\u6c7a\u7b56\" \/>\n<meta property=\"og:description\" content=\"Nginx\u3067\u9759\u7684\u30d5\u30a1\u30a4\u30eb\u306e\u53d6\u5f97\u304c\u3067\u304d\u306a\u3044\u5834\u5408\u3001\u4ee5\u4e0b\u306e\u89e3\u6c7a\u7b56\u3092\u8a66\u3057\u3066\u304f\u3060\u3055\u3044\u3002 \u9759\u7684\u30d5\u30a1\u30a4\u30eb\u306e\u30d1\u30b9\u304c\u6b63\u3057\u304f\u8a2d\u5b9a\u3055\u308c\u3066\u3044\u308b\u304b\u78ba\u8a8d\uff1aNginx \u8a2d\u5b9a\u30d5\u30a1\u30a4\u30eb\u306e\u9759\u7684\u30d5\u30a1\u30a4\u30eb\u30d1\u30b9\u304c\u6b63\u3057\u304f\u8a2d\u5b9a\u3055\u308c\u3066\u3044\u308b\u304b\u78ba\u8a8d\u3059\u308b\u3002\u30d5\u30a1\u30a4\u30eb\u30d1\u30b9\u3001\u30d5\u30a1 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.silicloud.com\/ja\/blog\/nginx\u3067\u9759\u7684\u30d5\u30a1\u30a4\u30eb\u3092\u53d6\u5f97\u3067\u304d\u306a\u3044\u5834\u5408\u306e\u89e3\u6c7a\u7b56\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog - Silicon Cloud\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-20T21:51:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-04T12:16:58+00:00\" \/>\n<meta name=\"author\" content=\"\u82bd\u4f9d, \u96e8\u591c\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u57f7\u7b46\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u82bd\u4f9d, \u96e8\u591c\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/nginx%e3%81%a7%e9%9d%99%e7%9a%84%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e5%8f%96%e5%be%97%e3%81%a7%e3%81%8d%e3%81%aa%e3%81%84%e5%a0%b4%e5%90%88%e3%81%ae%e8%a7%a3%e6%b1%ba%e7%ad%96\/\",\"url\":\"https:\/\/www.silicloud.com\/ja\/blog\/nginx%e3%81%a7%e9%9d%99%e7%9a%84%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e5%8f%96%e5%be%97%e3%81%a7%e3%81%8d%e3%81%aa%e3%81%84%e5%a0%b4%e5%90%88%e3%81%ae%e8%a7%a3%e6%b1%ba%e7%ad%96\/\",\"name\":\"Nginx\u3067\u9759\u7684\u30d5\u30a1\u30a4\u30eb\u3092\u53d6\u5f97\u3067\u304d\u306a\u3044\u5834\u5408\u306e\u89e3\u6c7a\u7b56 - Blog - Silicon Cloud\",\"isPartOf\":{\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#website\"},\"datePublished\":\"2024-03-20T21:51:23+00:00\",\"dateModified\":\"2024-04-04T12:16:58+00:00\",\"author\":{\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/aeb60a7861f2f002b54c66bd65bc6c27\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/nginx%e3%81%a7%e9%9d%99%e7%9a%84%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e5%8f%96%e5%be%97%e3%81%a7%e3%81%8d%e3%81%aa%e3%81%84%e5%a0%b4%e5%90%88%e3%81%ae%e8%a7%a3%e6%b1%ba%e7%ad%96\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.silicloud.com\/ja\/blog\/nginx%e3%81%a7%e9%9d%99%e7%9a%84%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e5%8f%96%e5%be%97%e3%81%a7%e3%81%8d%e3%81%aa%e3%81%84%e5%a0%b4%e5%90%88%e3%81%ae%e8%a7%a3%e6%b1%ba%e7%ad%96\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/nginx%e3%81%a7%e9%9d%99%e7%9a%84%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e5%8f%96%e5%be%97%e3%81%a7%e3%81%8d%e3%81%aa%e3%81%84%e5%a0%b4%e5%90%88%e3%81%ae%e8%a7%a3%e6%b1%ba%e7%ad%96\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9875\",\"item\":\"https:\/\/www.silicloud.com\/ja\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nginx\u3067\u9759\u7684\u30d5\u30a1\u30a4\u30eb\u3092\u53d6\u5f97\u3067\u304d\u306a\u3044\u5834\u5408\u306e\u89e3\u6c7a\u7b56\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#website\",\"url\":\"https:\/\/www.silicloud.com\/ja\/blog\/\",\"name\":\"Blog - Silicon Cloud\",\"description\":\"\",\"inLanguage\":\"ja\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/aeb60a7861f2f002b54c66bd65bc6c27\",\"name\":\"\u82bd\u4f9d, \u96e8\u591c\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6305fe5cabc2b854c1208975a47fbf3f8cef3f7cd775b94dceedbe59b74a8010?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6305fe5cabc2b854c1208975a47fbf3f8cef3f7cd775b94dceedbe59b74a8010?s=96&d=mm&r=g\",\"caption\":\"\u82bd\u4f9d, \u96e8\u591c\"},\"url\":\"https:\/\/www.silicloud.com\/ja\/blog\/author\/meiamaya\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/nginx%e3%81%a7%e9%9d%99%e7%9a%84%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e5%8f%96%e5%be%97%e3%81%a7%e3%81%8d%e3%81%aa%e3%81%84%e5%a0%b4%e5%90%88%e3%81%ae%e8%a7%a3%e6%b1%ba%e7%ad%96\/#local-main-organization-logo\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Blog - Silicon Cloud\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nginx\u3067\u9759\u7684\u30d5\u30a1\u30a4\u30eb\u3092\u53d6\u5f97\u3067\u304d\u306a\u3044\u5834\u5408\u306e\u89e3\u6c7a\u7b56 - Blog - Silicon Cloud","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.silicloud.com\/ja\/blog\/nginx\u3067\u9759\u7684\u30d5\u30a1\u30a4\u30eb\u3092\u53d6\u5f97\u3067\u304d\u306a\u3044\u5834\u5408\u306e\u89e3\u6c7a\u7b56\/","og_locale":"ja_JP","og_type":"article","og_title":"Nginx\u3067\u9759\u7684\u30d5\u30a1\u30a4\u30eb\u3092\u53d6\u5f97\u3067\u304d\u306a\u3044\u5834\u5408\u306e\u89e3\u6c7a\u7b56","og_description":"Nginx\u3067\u9759\u7684\u30d5\u30a1\u30a4\u30eb\u306e\u53d6\u5f97\u304c\u3067\u304d\u306a\u3044\u5834\u5408\u3001\u4ee5\u4e0b\u306e\u89e3\u6c7a\u7b56\u3092\u8a66\u3057\u3066\u304f\u3060\u3055\u3044\u3002 \u9759\u7684\u30d5\u30a1\u30a4\u30eb\u306e\u30d1\u30b9\u304c\u6b63\u3057\u304f\u8a2d\u5b9a\u3055\u308c\u3066\u3044\u308b\u304b\u78ba\u8a8d\uff1aNginx \u8a2d\u5b9a\u30d5\u30a1\u30a4\u30eb\u306e\u9759\u7684\u30d5\u30a1\u30a4\u30eb\u30d1\u30b9\u304c\u6b63\u3057\u304f\u8a2d\u5b9a\u3055\u308c\u3066\u3044\u308b\u304b\u78ba\u8a8d\u3059\u308b\u3002\u30d5\u30a1\u30a4\u30eb\u30d1\u30b9\u3001\u30d5\u30a1 [&hellip;]","og_url":"https:\/\/www.silicloud.com\/ja\/blog\/nginx\u3067\u9759\u7684\u30d5\u30a1\u30a4\u30eb\u3092\u53d6\u5f97\u3067\u304d\u306a\u3044\u5834\u5408\u306e\u89e3\u6c7a\u7b56\/","og_site_name":"Blog - Silicon Cloud","article_published_time":"2024-03-20T21:51:23+00:00","article_modified_time":"2024-04-04T12:16:58+00:00","author":"\u82bd\u4f9d, \u96e8\u591c","twitter_card":"summary_large_image","twitter_misc":{"\u57f7\u7b46\u8005":"\u82bd\u4f9d, \u96e8\u591c"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.silicloud.com\/ja\/blog\/nginx%e3%81%a7%e9%9d%99%e7%9a%84%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e5%8f%96%e5%be%97%e3%81%a7%e3%81%8d%e3%81%aa%e3%81%84%e5%a0%b4%e5%90%88%e3%81%ae%e8%a7%a3%e6%b1%ba%e7%ad%96\/","url":"https:\/\/www.silicloud.com\/ja\/blog\/nginx%e3%81%a7%e9%9d%99%e7%9a%84%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e5%8f%96%e5%be%97%e3%81%a7%e3%81%8d%e3%81%aa%e3%81%84%e5%a0%b4%e5%90%88%e3%81%ae%e8%a7%a3%e6%b1%ba%e7%ad%96\/","name":"Nginx\u3067\u9759\u7684\u30d5\u30a1\u30a4\u30eb\u3092\u53d6\u5f97\u3067\u304d\u306a\u3044\u5834\u5408\u306e\u89e3\u6c7a\u7b56 - Blog - Silicon Cloud","isPartOf":{"@id":"https:\/\/www.silicloud.com\/ja\/blog\/#website"},"datePublished":"2024-03-20T21:51:23+00:00","dateModified":"2024-04-04T12:16:58+00:00","author":{"@id":"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/aeb60a7861f2f002b54c66bd65bc6c27"},"breadcrumb":{"@id":"https:\/\/www.silicloud.com\/ja\/blog\/nginx%e3%81%a7%e9%9d%99%e7%9a%84%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e5%8f%96%e5%be%97%e3%81%a7%e3%81%8d%e3%81%aa%e3%81%84%e5%a0%b4%e5%90%88%e3%81%ae%e8%a7%a3%e6%b1%ba%e7%ad%96\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.silicloud.com\/ja\/blog\/nginx%e3%81%a7%e9%9d%99%e7%9a%84%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e5%8f%96%e5%be%97%e3%81%a7%e3%81%8d%e3%81%aa%e3%81%84%e5%a0%b4%e5%90%88%e3%81%ae%e8%a7%a3%e6%b1%ba%e7%ad%96\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.silicloud.com\/ja\/blog\/nginx%e3%81%a7%e9%9d%99%e7%9a%84%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e5%8f%96%e5%be%97%e3%81%a7%e3%81%8d%e3%81%aa%e3%81%84%e5%a0%b4%e5%90%88%e3%81%ae%e8%a7%a3%e6%b1%ba%e7%ad%96\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/www.silicloud.com\/ja\/blog\/"},{"@type":"ListItem","position":2,"name":"Nginx\u3067\u9759\u7684\u30d5\u30a1\u30a4\u30eb\u3092\u53d6\u5f97\u3067\u304d\u306a\u3044\u5834\u5408\u306e\u89e3\u6c7a\u7b56"}]},{"@type":"WebSite","@id":"https:\/\/www.silicloud.com\/ja\/blog\/#website","url":"https:\/\/www.silicloud.com\/ja\/blog\/","name":"Blog - Silicon Cloud","description":"","inLanguage":"ja"},{"@type":"Person","@id":"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/aeb60a7861f2f002b54c66bd65bc6c27","name":"\u82bd\u4f9d, \u96e8\u591c","image":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6305fe5cabc2b854c1208975a47fbf3f8cef3f7cd775b94dceedbe59b74a8010?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6305fe5cabc2b854c1208975a47fbf3f8cef3f7cd775b94dceedbe59b74a8010?s=96&d=mm&r=g","caption":"\u82bd\u4f9d, \u96e8\u591c"},"url":"https:\/\/www.silicloud.com\/ja\/blog\/author\/meiamaya\/"},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.silicloud.com\/ja\/blog\/nginx%e3%81%a7%e9%9d%99%e7%9a%84%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e5%8f%96%e5%be%97%e3%81%a7%e3%81%8d%e3%81%aa%e3%81%84%e5%a0%b4%e5%90%88%e3%81%ae%e8%a7%a3%e6%b1%ba%e7%ad%96\/#local-main-organization-logo","url":"","contentUrl":"","caption":"Blog - Silicon Cloud"}]}},"_links":{"self":[{"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/posts\/86316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/comments?post=86316"}],"version-history":[{"count":2,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/posts\/86316\/revisions"}],"predecessor-version":[{"id":293336,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/posts\/86316\/revisions\/293336"}],"wp:attachment":[{"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/media?parent=86316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/categories?post=86316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/tags?post=86316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}