{"id":83476,"date":"2024-03-21T02:55:24","date_gmt":"2024-03-20T17:55:24","guid":{"rendered":"https:\/\/www.silicloud.com\/ja\/blog\/r%e8%a8%80%e8%aa%9e%e3%81%a7xlsx%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e8%aa%ad%e3%81%bf%e8%be%bc%e3%82%80%e6%96%b9%e6%b3%95%e3%81%af\/"},"modified":"2024-04-05T09:09:34","modified_gmt":"2024-04-05T00:09:34","slug":"r%e8%a8%80%e8%aa%9e%e3%81%a7xlsx%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e8%aa%ad%e3%81%bf%e8%be%bc%e3%82%80%e6%96%b9%e6%b3%95%e3%81%af","status":"publish","type":"post","link":"https:\/\/www.silicloud.com\/ja\/blog\/r%e8%a8%80%e8%aa%9e%e3%81%a7xlsx%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e8%aa%ad%e3%81%bf%e8%be%bc%e3%82%80%e6%96%b9%e6%b3%95%e3%81%af\/","title":{"rendered":"R\u8a00\u8a9e\u3067XLSX\u30d5\u30a1\u30a4\u30eb\u3092\u8aad\u307f\u8fbc\u3080\u65b9\u6cd5\u306f?"},"content":{"rendered":"<p>readxl\u30d1\u30c3\u30b1\u30fc\u30b8\u307e\u305f\u306fopenxlsx\u30d1\u30c3\u30b1\u30fc\u30b8\u3092\u4f7f\u7528\u3057\u3066R\u8a00\u8a9e\u3067xlsx\u30d5\u30a1\u30a4\u30eb\u3092\u8aad\u307f\u8fbc\u3080\u3053\u3068\u304c\u3067\u304d\u307e\u3059\u3002\u4f8b\u3068\u3057\u3066readxl\u30d1\u30c3\u30b1\u30fc\u30b8\u3092\u4f7f\u7528\u3057\u307e\u3059\u3002\u4ee5\u4e0b\u306fxlsx\u30d5\u30a1\u30a4\u30eb\u3092\u8aad\u307f\u8fbc\u3080\u624b\u9806\u3067\u3059\u3002<\/p>\n<ol>\n<li>readxl<\/li>\n<\/ol>\n<pre class=\"post-pre\"><code>install.packages<span class=\"hljs-punctuation\">(<\/span><span class=\"hljs-string\">\"readxl\"<\/span><span class=\"hljs-punctuation\">)<\/span>\r\n<\/code><\/pre>\n<ol>\n<li>readxl<\/li>\n<\/ol>\n<pre class=\"post-pre\"><code>library<span class=\"hljs-punctuation\">(<\/span>readxl<span class=\"hljs-punctuation\">)<\/span>\r\n<\/code><\/pre>\n<ol>\n<li>read_excel()<\/li>\n<\/ol>\n<pre class=\"post-pre\"><code>data <span class=\"hljs-operator\">&lt;-<\/span> read_excel<span class=\"hljs-punctuation\">(<\/span><span class=\"hljs-string\">\"\u8def\u5f84\/\u6587\u4ef6\u540d.xlsx\"<\/span><span class=\"hljs-punctuation\">)<\/span>\r\n<\/code><\/pre>\n<p>xlsx\u30d5\u30a1\u30a4\u30eb\u306e\u30d1\u30b9\u53ca\u3073\u30d5\u30a1\u30a4\u30eb\u540d\u306f\u3001\u8aad\u307f\u8fbc\u3080xlsx\u30d5\u30a1\u30a4\u30eb\u306e\u30d1\u30b9\u3068\u30d5\u30a1\u30a4\u30eb\u540d\u3067\u3059\u3002<\/p>\n<ol>\n<li>read_excel()<\/li>\n<li>\u30cd\u30a4\u30c6\u30a3\u30d6\u306a\u65e5\u672c\u8a9e\u3067\u306f\u8a00\u3044\u63db\u3048\u30661\u3064\u306e\u9078\u629e\u80a2\u304c\u5fc5\u8981\u3067\u3059\u304b\uff1f\u308f\u304b\u308a\u307e\u3057\u305f\u3002<\/li>\n<li>\u7bc4\u56f2<\/li>\n<\/ol>\n<pre class=\"post-pre\"><code>data <span class=\"hljs-operator\">&lt;-<\/span> read_excel<span class=\"hljs-punctuation\">(<\/span><span class=\"hljs-string\">\"\u8def\u5f84\/\u6587\u4ef6\u540d.xlsx\"<\/span><span class=\"hljs-punctuation\">,<\/span> sheet <span class=\"hljs-operator\">=<\/span> <span class=\"hljs-string\">\"\u5de5\u4f5c\u8868\u540d\"<\/span><span class=\"hljs-punctuation\">,<\/span> <span class=\"hljs-built_in\">range<\/span> <span class=\"hljs-operator\">=<\/span> <span class=\"hljs-string\">\"A1:B10\"<\/span><span class=\"hljs-punctuation\">)<\/span>\r\n<\/code><\/pre>\n<p>\u306a\u304a\u3001\u30b7\u30fc\u30c8\u540d\u306f\u8aad\u307f\u8fbc\u3080\u30b7\u30fc\u30c8\u306e\u540d\u524d\u3001A1:B10\u306f\u8aad\u307f\u8fbc\u3080\u30bb\u30eb\u306e\u7bc4\u56f2\u3067\u3059\u3002<\/p>\n<ol>\n<li>\u8aad\u307f\u8fbc\u3093\u3060\u30c7\u30fc\u30bf\u3092\u898b\u308b\u65b9\u6cd5\u3068\u3057\u3066\u3001\u4ee5\u4e0b\u306e\u95a2\u6570\u3067\u8aad\u307f\u8fbc\u3093\u3060\u30c7\u30fc\u30bf\u306e\u69cb\u9020\u3084\u5185\u5bb9\u3092\u78ba\u8a8d\u3059\u308b\u3053\u3068\u304c\u3067\u304d\u307e\u3059\u3002<\/li>\n<\/ol>\n<pre class=\"post-pre\"><code>str<span class=\"hljs-punctuation\">(<\/span>data<span class=\"hljs-punctuation\">)<\/span>  <span class=\"hljs-comment\"># \u67e5\u770b\u6570\u636e\u7ed3\u6784<\/span>\r\nhead<span class=\"hljs-punctuation\">(<\/span>data<span class=\"hljs-punctuation\">)<\/span>  <span class=\"hljs-comment\"># \u67e5\u770b\u524d\u51e0\u884c\u6570\u636e<\/span>\r\n<\/code><\/pre>\n<p>xlsx \u30d5\u30a1\u30a4\u30eb\u3092\u8aad\u307f\u8fbc\u3080\u524d\u306b\u3001\u5fc5\u8981\u306a\u30d1\u30c3\u30b1\u30fc\u30b8\u304c\u30a4\u30f3\u30b9\u30c8\u30fc\u30eb\u3055\u308c\u3066\u3044\u3066\u3001\u30d5\u30a1\u30a4\u30eb\u30d1\u30b9\u304c\u6b63\u3057\u3044\u3053\u3068\u3092\u78ba\u8a8d\u3057\u3066\u304f\u3060\u3055\u3044\u3002<\/p>\n","protected":false},"excerpt":{"rendered":"<p>readxl\u30d1\u30c3\u30b1\u30fc\u30b8\u307e\u305f\u306fopenxlsx\u30d1\u30c3\u30b1\u30fc\u30b8\u3092\u4f7f\u7528\u3057\u3066R\u8a00\u8a9e\u3067xlsx\u30d5\u30a1\u30a4\u30eb\u3092\u8aad\u307f\u8fbc\u3080\u3053\u3068\u304c\u3067\u304d\u307e\u3059\u3002\u4f8b\u3068\u3057\u3066readxl\u30d1\u30c3\u30b1\u30fc\u30b8\u3092\u4f7f\u7528\u3057\u307e\u3059\u3002\u4ee5\u4e0b\u306fxlsx\u30d5\u30a1\u30a4\u30eb\u3092\u8aad\u307f\u8fbc\u3080\u624b\u9806\u3067\u3059\u3002 readxl in [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-83476","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v21.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>R\u8a00\u8a9e\u3067XLSX\u30d5\u30a1\u30a4\u30eb\u3092\u8aad\u307f\u8fbc\u3080\u65b9\u6cd5\u306f? - Blog - Silicon Cloud<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.silicloud.com\/ja\/blog\/r\u8a00\u8a9e\u3067xlsx\u30d5\u30a1\u30a4\u30eb\u3092\u8aad\u307f\u8fbc\u3080\u65b9\u6cd5\u306f\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u8a00\u8a9e\u3067XLSX\u30d5\u30a1\u30a4\u30eb\u3092\u8aad\u307f\u8fbc\u3080\u65b9\u6cd5\u306f?\" \/>\n<meta property=\"og:description\" content=\"readxl\u30d1\u30c3\u30b1\u30fc\u30b8\u307e\u305f\u306fopenxlsx\u30d1\u30c3\u30b1\u30fc\u30b8\u3092\u4f7f\u7528\u3057\u3066R\u8a00\u8a9e\u3067xlsx\u30d5\u30a1\u30a4\u30eb\u3092\u8aad\u307f\u8fbc\u3080\u3053\u3068\u304c\u3067\u304d\u307e\u3059\u3002\u4f8b\u3068\u3057\u3066readxl\u30d1\u30c3\u30b1\u30fc\u30b8\u3092\u4f7f\u7528\u3057\u307e\u3059\u3002\u4ee5\u4e0b\u306fxlsx\u30d5\u30a1\u30a4\u30eb\u3092\u8aad\u307f\u8fbc\u3080\u624b\u9806\u3067\u3059\u3002 readxl in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.silicloud.com\/ja\/blog\/r\u8a00\u8a9e\u3067xlsx\u30d5\u30a1\u30a4\u30eb\u3092\u8aad\u307f\u8fbc\u3080\u65b9\u6cd5\u306f\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog - Silicon Cloud\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-20T17:55:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-05T00:09:34+00:00\" \/>\n<meta name=\"author\" content=\"\u82bd\u4f9d, \u96e8\u591c\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u57f7\u7b46\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u82bd\u4f9d, \u96e8\u591c\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/r%e8%a8%80%e8%aa%9e%e3%81%a7xlsx%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e8%aa%ad%e3%81%bf%e8%be%bc%e3%82%80%e6%96%b9%e6%b3%95%e3%81%af\/\",\"url\":\"https:\/\/www.silicloud.com\/ja\/blog\/r%e8%a8%80%e8%aa%9e%e3%81%a7xlsx%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e8%aa%ad%e3%81%bf%e8%be%bc%e3%82%80%e6%96%b9%e6%b3%95%e3%81%af\/\",\"name\":\"R\u8a00\u8a9e\u3067XLSX\u30d5\u30a1\u30a4\u30eb\u3092\u8aad\u307f\u8fbc\u3080\u65b9\u6cd5\u306f? - Blog - Silicon Cloud\",\"isPartOf\":{\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#website\"},\"datePublished\":\"2024-03-20T17:55:24+00:00\",\"dateModified\":\"2024-04-05T00:09:34+00:00\",\"author\":{\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/aeb60a7861f2f002b54c66bd65bc6c27\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/r%e8%a8%80%e8%aa%9e%e3%81%a7xlsx%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e8%aa%ad%e3%81%bf%e8%be%bc%e3%82%80%e6%96%b9%e6%b3%95%e3%81%af\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.silicloud.com\/ja\/blog\/r%e8%a8%80%e8%aa%9e%e3%81%a7xlsx%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e8%aa%ad%e3%81%bf%e8%be%bc%e3%82%80%e6%96%b9%e6%b3%95%e3%81%af\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/r%e8%a8%80%e8%aa%9e%e3%81%a7xlsx%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e8%aa%ad%e3%81%bf%e8%be%bc%e3%82%80%e6%96%b9%e6%b3%95%e3%81%af\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9875\",\"item\":\"https:\/\/www.silicloud.com\/ja\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u8a00\u8a9e\u3067XLSX\u30d5\u30a1\u30a4\u30eb\u3092\u8aad\u307f\u8fbc\u3080\u65b9\u6cd5\u306f?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#website\",\"url\":\"https:\/\/www.silicloud.com\/ja\/blog\/\",\"name\":\"Blog - Silicon Cloud\",\"description\":\"\",\"inLanguage\":\"ja\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/aeb60a7861f2f002b54c66bd65bc6c27\",\"name\":\"\u82bd\u4f9d, \u96e8\u591c\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6305fe5cabc2b854c1208975a47fbf3f8cef3f7cd775b94dceedbe59b74a8010?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6305fe5cabc2b854c1208975a47fbf3f8cef3f7cd775b94dceedbe59b74a8010?s=96&d=mm&r=g\",\"caption\":\"\u82bd\u4f9d, \u96e8\u591c\"},\"url\":\"https:\/\/www.silicloud.com\/ja\/blog\/author\/meiamaya\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/r%e8%a8%80%e8%aa%9e%e3%81%a7xlsx%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e8%aa%ad%e3%81%bf%e8%be%bc%e3%82%80%e6%96%b9%e6%b3%95%e3%81%af\/#local-main-organization-logo\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Blog - Silicon Cloud\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"R\u8a00\u8a9e\u3067XLSX\u30d5\u30a1\u30a4\u30eb\u3092\u8aad\u307f\u8fbc\u3080\u65b9\u6cd5\u306f? - Blog - Silicon Cloud","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.silicloud.com\/ja\/blog\/r\u8a00\u8a9e\u3067xlsx\u30d5\u30a1\u30a4\u30eb\u3092\u8aad\u307f\u8fbc\u3080\u65b9\u6cd5\u306f\/","og_locale":"ja_JP","og_type":"article","og_title":"R\u8a00\u8a9e\u3067XLSX\u30d5\u30a1\u30a4\u30eb\u3092\u8aad\u307f\u8fbc\u3080\u65b9\u6cd5\u306f?","og_description":"readxl\u30d1\u30c3\u30b1\u30fc\u30b8\u307e\u305f\u306fopenxlsx\u30d1\u30c3\u30b1\u30fc\u30b8\u3092\u4f7f\u7528\u3057\u3066R\u8a00\u8a9e\u3067xlsx\u30d5\u30a1\u30a4\u30eb\u3092\u8aad\u307f\u8fbc\u3080\u3053\u3068\u304c\u3067\u304d\u307e\u3059\u3002\u4f8b\u3068\u3057\u3066readxl\u30d1\u30c3\u30b1\u30fc\u30b8\u3092\u4f7f\u7528\u3057\u307e\u3059\u3002\u4ee5\u4e0b\u306fxlsx\u30d5\u30a1\u30a4\u30eb\u3092\u8aad\u307f\u8fbc\u3080\u624b\u9806\u3067\u3059\u3002 readxl in [&hellip;]","og_url":"https:\/\/www.silicloud.com\/ja\/blog\/r\u8a00\u8a9e\u3067xlsx\u30d5\u30a1\u30a4\u30eb\u3092\u8aad\u307f\u8fbc\u3080\u65b9\u6cd5\u306f\/","og_site_name":"Blog - Silicon Cloud","article_published_time":"2024-03-20T17:55:24+00:00","article_modified_time":"2024-04-05T00:09:34+00:00","author":"\u82bd\u4f9d, \u96e8\u591c","twitter_card":"summary_large_image","twitter_misc":{"\u57f7\u7b46\u8005":"\u82bd\u4f9d, \u96e8\u591c"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.silicloud.com\/ja\/blog\/r%e8%a8%80%e8%aa%9e%e3%81%a7xlsx%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e8%aa%ad%e3%81%bf%e8%be%bc%e3%82%80%e6%96%b9%e6%b3%95%e3%81%af\/","url":"https:\/\/www.silicloud.com\/ja\/blog\/r%e8%a8%80%e8%aa%9e%e3%81%a7xlsx%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e8%aa%ad%e3%81%bf%e8%be%bc%e3%82%80%e6%96%b9%e6%b3%95%e3%81%af\/","name":"R\u8a00\u8a9e\u3067XLSX\u30d5\u30a1\u30a4\u30eb\u3092\u8aad\u307f\u8fbc\u3080\u65b9\u6cd5\u306f? - Blog - Silicon Cloud","isPartOf":{"@id":"https:\/\/www.silicloud.com\/ja\/blog\/#website"},"datePublished":"2024-03-20T17:55:24+00:00","dateModified":"2024-04-05T00:09:34+00:00","author":{"@id":"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/aeb60a7861f2f002b54c66bd65bc6c27"},"breadcrumb":{"@id":"https:\/\/www.silicloud.com\/ja\/blog\/r%e8%a8%80%e8%aa%9e%e3%81%a7xlsx%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e8%aa%ad%e3%81%bf%e8%be%bc%e3%82%80%e6%96%b9%e6%b3%95%e3%81%af\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.silicloud.com\/ja\/blog\/r%e8%a8%80%e8%aa%9e%e3%81%a7xlsx%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e8%aa%ad%e3%81%bf%e8%be%bc%e3%82%80%e6%96%b9%e6%b3%95%e3%81%af\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.silicloud.com\/ja\/blog\/r%e8%a8%80%e8%aa%9e%e3%81%a7xlsx%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e8%aa%ad%e3%81%bf%e8%be%bc%e3%82%80%e6%96%b9%e6%b3%95%e3%81%af\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/www.silicloud.com\/ja\/blog\/"},{"@type":"ListItem","position":2,"name":"R\u8a00\u8a9e\u3067XLSX\u30d5\u30a1\u30a4\u30eb\u3092\u8aad\u307f\u8fbc\u3080\u65b9\u6cd5\u306f?"}]},{"@type":"WebSite","@id":"https:\/\/www.silicloud.com\/ja\/blog\/#website","url":"https:\/\/www.silicloud.com\/ja\/blog\/","name":"Blog - Silicon Cloud","description":"","inLanguage":"ja"},{"@type":"Person","@id":"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/aeb60a7861f2f002b54c66bd65bc6c27","name":"\u82bd\u4f9d, \u96e8\u591c","image":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6305fe5cabc2b854c1208975a47fbf3f8cef3f7cd775b94dceedbe59b74a8010?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6305fe5cabc2b854c1208975a47fbf3f8cef3f7cd775b94dceedbe59b74a8010?s=96&d=mm&r=g","caption":"\u82bd\u4f9d, \u96e8\u591c"},"url":"https:\/\/www.silicloud.com\/ja\/blog\/author\/meiamaya\/"},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.silicloud.com\/ja\/blog\/r%e8%a8%80%e8%aa%9e%e3%81%a7xlsx%e3%83%95%e3%82%a1%e3%82%a4%e3%83%ab%e3%82%92%e8%aa%ad%e3%81%bf%e8%be%bc%e3%82%80%e6%96%b9%e6%b3%95%e3%81%af\/#local-main-organization-logo","url":"","contentUrl":"","caption":"Blog - Silicon Cloud"}]}},"_links":{"self":[{"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/posts\/83476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/comments?post=83476"}],"version-history":[{"count":2,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/posts\/83476\/revisions"}],"predecessor-version":[{"id":318238,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/posts\/83476\/revisions\/318238"}],"wp:attachment":[{"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/media?parent=83476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/categories?post=83476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/tags?post=83476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}