{"id":16109,"date":"2024-03-16T03:14:09","date_gmt":"2024-03-15T18:14:09","guid":{"rendered":"https:\/\/www.silicloud.com\/ja\/blog\/setlocale%e9%96%a2%e6%95%b0%e3%81%ae%e4%bd%bf%e3%81%84%e6%96%b9%e3%81%af%e4%bd%95%e3%81%a7%e3%81%99%e3%81%8b%e3%80%82\/"},"modified":"2025-08-06T05:40:17","modified_gmt":"2025-08-05T20:40:17","slug":"setlocale%e9%96%a2%e6%95%b0%e3%81%ae%e4%bd%bf%e3%81%84%e6%96%b9%e3%81%af%e4%bd%95%e3%81%a7%e3%81%99%e3%81%8b%e3%80%82","status":"publish","type":"post","link":"https:\/\/www.silicloud.com\/ja\/blog\/setlocale%e9%96%a2%e6%95%b0%e3%81%ae%e4%bd%bf%e3%81%84%e6%96%b9%e3%81%af%e4%bd%95%e3%81%a7%e3%81%99%e3%81%8b%e3%80%82\/","title":{"rendered":"setlocale\u95a2\u6570\u306e\u4f7f\u3044\u65b9\u306f\u4f55\u3067\u3059\u304b\u3002"},"content":{"rendered":"<p>setlocale\u95a2\u6570\u306f\u3001\u30d7\u30ed\u30b0\u30e9\u30e0\u306e\u30ed\u30fc\u30ab\u30e9\u30a4\u30ba\u74b0\u5883\u3092\u8a2d\u5b9a\u3059\u308b\u305f\u3081\u306b\u4f7f\u7528\u3055\u308c\u307e\u3059\u3002<\/p>\n<p>\u4ee5\u4e0b\u306e\u6587\u3092\u65e5\u672c\u8a9e\u3067\u8a00\u3044\u63db\u3048\u3066\u304f\u3060\u3055\u3044\uff1a<br \/>\n\u3053\u3061\u3089\u306e\u30aa\u30d7\u30b7\u30e7\u30f3\u3092\uff11\u3064\u9078\u3093\u3067\u304f\u3060\u3055\u3044\u3002<\/p>\n<pre class=\"post-pre\"><code><span class=\"hljs-meta\">#<span class=\"hljs-keyword\">include<\/span> <span class=\"hljs-string\">&lt;locale.h&gt;<\/span><\/span>\r\n<span class=\"hljs-function\"><span class=\"hljs-type\">char<\/span>* <span class=\"hljs-title\">setlocale<\/span><span class=\"hljs-params\">(<span class=\"hljs-type\">int<\/span> category, <span class=\"hljs-type\">const<\/span> <span class=\"hljs-type\">char<\/span>* locale)<\/span><\/span>;\r\n<\/code><\/pre>\n<p>\u30d1\u30e9\u30e1\u30fc\u30bf\u30fc\u306b\u3064\u3044\u3066\u8aac\u660e:<\/p>\n<ol>\n<li>\u90e8\u9580\uff1a\u8a2d\u5b9a\u3059\u308b\u30ed\u30fc\u30ab\u30e9\u30a4\u30ba\u74b0\u5883\u306e\u30ab\u30c6\u30b4\u30ea\u3002\u4ee5\u4e0b\u306e\u5b9a\u6570\u306e\u3044\u305a\u308c\u304b\u3092\u6307\u5b9a\u3067\u304d\u307e\u3059\uff1aLC_ALL\uff1a\u3059\u3079\u3066\u306e\u30ab\u30c6\u30b4\u30ea\u3092\u8a2d\u5b9a\u3057\u307e\u3059\u3002<br \/>\nLC_COLLATE\uff1a\u6587\u5b57\u5217\u306e\u6bd4\u8f03\u304a\u3088\u3073\u30bd\u30fc\u30c8\u898f\u5247\u3092\u8a2d\u5b9a\u3057\u307e\u3059\u3002<br \/>\nLC_CTYPE\uff1a\u6587\u5b57\u5206\u985e\u304a\u3088\u3073\u5909\u63db\u898f\u5247\u3092\u8a2d\u5b9a\u3057\u307e\u3059\u3002<br \/>\nLC_MONETARY\uff1a\u901a\u8ca8\u306e\u30d5\u30a9\u30fc\u30de\u30c3\u30c8\u3068\u8a18\u53f7\u3092\u8a2d\u5b9a\u3057\u307e\u3059\u3002<br \/>\nLC_NUMERIC\uff1a\u6570\u5b57\u306e\u30d5\u30a9\u30fc\u30de\u30c3\u30c8\u3092\u8a2d\u5b9a\u3057\u307e\u3059\u3002<br \/>\nLC_TIME\uff1a\u65e5\u4ed8\u3068\u6642\u523b\u306e\u30d5\u30a9\u30fc\u30de\u30c3\u30c8\u3092\u8a2d\u5b9a\u3057\u307e\u3059\u3002<\/li>\n<li>\u30ed\u30b1\u30fc\u30eb\uff1a\u8a2d\u5b9a\u3059\u308b\u30ed\u30fc\u30ab\u30e9\u30a4\u30ba\u74b0\u5883\u306e\u6587\u5b57\u5217\u3067\u3001\u6b21\u306e\u5f62\u5f0f\u306e\u3044\u305a\u308c\u304b\u3092\u4f7f\u7528\u3067\u304d\u307e\u3059\u3002\u7a7a\u306e\u6587\u5b57\u5217(&#8220;&#8221;)\uff1a\u30c7\u30d5\u30a9\u30eb\u30c8\u306e\u30ed\u30fc\u30ab\u30e9\u30a4\u30ba\u74b0\u5883\u3092\u4f7f\u7528\u3057\u307e\u3059\u3002<br \/>\n&#8220;en_US&#8221;\u3001&#8221;zh_CN&#8221;\u306a\u3069\u306e\u30ed\u30fc\u30ab\u30e9\u30a4\u30ba\u74b0\u5883\u306e\u540d\u524d\u3002<br \/>\n&#8220;C&#8221;\uff1aC\u8a00\u8a9e\u306e\u30ed\u30fc\u30ab\u30e9\u30a4\u30ba\u74b0\u5883\u3092\u4f7f\u7528\u3057\u3001\u3064\u307e\u308a\u30ed\u30fc\u30ab\u30e9\u30a4\u30ba\u51e6\u7406\u3092\u884c\u3044\u307e\u305b\u3093\u3002<\/li>\n<\/ol>\n<p>\u8a2d\u5b9a\u304c\u6210\u529f\u3057\u305f\u5834\u5408\u3001\u30ed\u30fc\u30ab\u30e9\u30a4\u30ba\u3055\u308c\u305f\u74b0\u5883\u6587\u5b57\u5217\u304c\u8fd4\u3055\u308c\u3001\u5931\u6557\u3057\u305f\u5834\u5408\u306fNULL\u304c\u8fd4\u3055\u308c\u307e\u3059\u3002<\/p>\n<p>\u4f7f\u7528\u4f8b:<\/p>\n<pre class=\"post-pre\"><code><span class=\"hljs-meta\">#<span class=\"hljs-keyword\">include<\/span> <span class=\"hljs-string\">&lt;iostream&gt;<\/span><\/span>\r\n<span class=\"hljs-meta\">#<span class=\"hljs-keyword\">include<\/span> <span class=\"hljs-string\">&lt;locale.h&gt;<\/span><\/span>\r\n<span class=\"hljs-meta\">#<span class=\"hljs-keyword\">include<\/span> <span class=\"hljs-string\">&lt;ctime&gt;<\/span><\/span>\r\n\r\n<span class=\"hljs-function\"><span class=\"hljs-type\">int<\/span> <span class=\"hljs-title\">main<\/span><span class=\"hljs-params\">()<\/span> <\/span>{\r\n    <span class=\"hljs-built_in\">setlocale<\/span>(LC_ALL, <span class=\"hljs-string\">\"\"<\/span>); <span class=\"hljs-comment\">\/\/ \u4f7f\u7528\u9ed8\u8ba4\u7684\u672c\u5730\u5316\u73af\u5883<\/span>\r\n    \r\n    <span class=\"hljs-type\">time_t<\/span> now = <span class=\"hljs-built_in\">time<\/span>(<span class=\"hljs-literal\">NULL<\/span>);\r\n    <span class=\"hljs-keyword\">struct<\/span> <span class=\"hljs-title class_\">tm<\/span>* timeinfo = <span class=\"hljs-built_in\">localtime<\/span>(&amp;now);\r\n    <span class=\"hljs-type\">char<\/span> buffer[<span class=\"hljs-number\">80<\/span>];\r\n    \r\n    <span class=\"hljs-built_in\">strftime<\/span>(buffer, <span class=\"hljs-built_in\">sizeof<\/span>(buffer), <span class=\"hljs-string\">\"%c\"<\/span>, timeinfo);\r\n    std::cout &lt;&lt; <span class=\"hljs-string\">\"\u5f53\u524d\u65e5\u671f\u548c\u65f6\u95f4\uff1a\"<\/span> &lt;&lt; buffer &lt;&lt; std::endl;\r\n    \r\n    <span class=\"hljs-keyword\">return<\/span> <span class=\"hljs-number\">0<\/span>;\r\n}\r\n<\/code><\/pre>\n<p>\u4e0a\u8a18\u306e\u30b5\u30f3\u30d7\u30eb\u30d7\u30ed\u30b0\u30e9\u30e0\u3067\u306f\u3001\u30c7\u30d5\u30a9\u30eb\u30c8\u306e\u30ed\u30fc\u30ab\u30e9\u30a4\u30ba\u74b0\u5883\u304c\u8a2d\u5b9a\u3055\u308c\u3001strftime\u95a2\u6570\u3092\u4f7f\u7528\u3057\u3066\u73fe\u5728\u306e\u65e5\u4ed8\u3068\u6642\u523b\u3092\u6587\u5b57\u5217\u306b\u30d5\u30a9\u30fc\u30de\u30c3\u30c8\u3057\u3066\u51fa\u529b\u3057\u3066\u3044\u307e\u3059\u3002<\/p>\n","protected":false},"excerpt":{"rendered":"<p>setlocale\u95a2\u6570\u306f\u3001\u30d7\u30ed\u30b0\u30e9\u30e0\u306e\u30ed\u30fc\u30ab\u30e9\u30a4\u30ba\u74b0\u5883\u3092\u8a2d\u5b9a\u3059\u308b\u305f\u3081\u306b\u4f7f\u7528\u3055\u308c\u307e\u3059\u3002 \u4ee5\u4e0b\u306e\u6587\u3092\u65e5\u672c\u8a9e\u3067\u8a00\u3044\u63db\u3048\u3066\u304f\u3060\u3055\u3044\uff1a \u3053\u3061\u3089\u306e\u30aa\u30d7\u30b7\u30e7\u30f3\u3092\uff11\u3064\u9078\u3093\u3067\u304f\u3060\u3055\u3044\u3002 #include &lt;locale.h&gt;  [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[16,26],"class_list":["post-16109","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-16","tag-26"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v21.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>setlocale\u95a2\u6570\u306e\u4f7f\u3044\u65b9\u306f\u4f55\u3067\u3059\u304b\u3002 - Blog - Silicon Cloud<\/title>\n<meta name=\"description\" content=\"setlocale\u95a2\u6570\u306e\u4f7f\u3044\u65b9\u306f\u4f55\u3067\u3059\u304b\u3092\u5206\u304b\u308a\u3084\u3059\u304f\u89e3\u8aac\u3002\u5b9f\u8df5\u7684\u306a\u4f8b\u3068\u30b3\u30fc\u30c9\u3001\u6ce8\u610f\u70b9\u3092\u542b\u3081\u3066\u521d\u5fc3\u8005\u306b\u3082\u7406\u89e3\u3067\u304d\u308b\u3088\u3046\u8aac\u660e\u3057\u307e\u3059\u3002\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.silicloud.com\/ja\/blog\/setlocale\u95a2\u6570\u306e\u4f7f\u3044\u65b9\u306f\u4f55\u3067\u3059\u304b\u3002\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"setlocale\u95a2\u6570\u306e\u4f7f\u3044\u65b9\u306f\u4f55\u3067\u3059\u304b\u3002\" \/>\n<meta property=\"og:description\" content=\"setlocale\u95a2\u6570\u306e\u4f7f\u3044\u65b9\u306f\u4f55\u3067\u3059\u304b\u3092\u5206\u304b\u308a\u3084\u3059\u304f\u89e3\u8aac\u3002\u5b9f\u8df5\u7684\u306a\u4f8b\u3068\u30b3\u30fc\u30c9\u3001\u6ce8\u610f\u70b9\u3092\u542b\u3081\u3066\u521d\u5fc3\u8005\u306b\u3082\u7406\u89e3\u3067\u304d\u308b\u3088\u3046\u8aac\u660e\u3057\u307e\u3059\u3002\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.silicloud.com\/ja\/blog\/setlocale\u95a2\u6570\u306e\u4f7f\u3044\u65b9\u306f\u4f55\u3067\u3059\u304b\u3002\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog - Silicon Cloud\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-15T18:14:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-05T20:40:17+00:00\" \/>\n<meta name=\"author\" content=\"\u7d50\u8863, \u6625\u82b1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u57f7\u7b46\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u7d50\u8863, \u6625\u82b1\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/setlocale%e9%96%a2%e6%95%b0%e3%81%ae%e4%bd%bf%e3%81%84%e6%96%b9%e3%81%af%e4%bd%95%e3%81%a7%e3%81%99%e3%81%8b%e3%80%82\/\",\"url\":\"https:\/\/www.silicloud.com\/ja\/blog\/setlocale%e9%96%a2%e6%95%b0%e3%81%ae%e4%bd%bf%e3%81%84%e6%96%b9%e3%81%af%e4%bd%95%e3%81%a7%e3%81%99%e3%81%8b%e3%80%82\/\",\"name\":\"setlocale\u95a2\u6570\u306e\u4f7f\u3044\u65b9\u306f\u4f55\u3067\u3059\u304b\u3002 - Blog - Silicon Cloud\",\"isPartOf\":{\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#website\"},\"datePublished\":\"2024-03-15T18:14:09+00:00\",\"dateModified\":\"2025-08-05T20:40:17+00:00\",\"author\":{\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/e52a686063ac76fd8cc6f539d41497ac\"},\"description\":\"setlocale\u95a2\u6570\u306e\u4f7f\u3044\u65b9\u306f\u4f55\u3067\u3059\u304b\u3092\u5206\u304b\u308a\u3084\u3059\u304f\u89e3\u8aac\u3002\u5b9f\u8df5\u7684\u306a\u4f8b\u3068\u30b3\u30fc\u30c9\u3001\u6ce8\u610f\u70b9\u3092\u542b\u3081\u3066\u521d\u5fc3\u8005\u306b\u3082\u7406\u89e3\u3067\u304d\u308b\u3088\u3046\u8aac\u660e\u3057\u307e\u3059\u3002\",\"breadcrumb\":{\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/setlocale%e9%96%a2%e6%95%b0%e3%81%ae%e4%bd%bf%e3%81%84%e6%96%b9%e3%81%af%e4%bd%95%e3%81%a7%e3%81%99%e3%81%8b%e3%80%82\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.silicloud.com\/ja\/blog\/setlocale%e9%96%a2%e6%95%b0%e3%81%ae%e4%bd%bf%e3%81%84%e6%96%b9%e3%81%af%e4%bd%95%e3%81%a7%e3%81%99%e3%81%8b%e3%80%82\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/setlocale%e9%96%a2%e6%95%b0%e3%81%ae%e4%bd%bf%e3%81%84%e6%96%b9%e3%81%af%e4%bd%95%e3%81%a7%e3%81%99%e3%81%8b%e3%80%82\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9875\",\"item\":\"https:\/\/www.silicloud.com\/ja\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"setlocale\u95a2\u6570\u306e\u4f7f\u3044\u65b9\u306f\u4f55\u3067\u3059\u304b\u3002\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#website\",\"url\":\"https:\/\/www.silicloud.com\/ja\/blog\/\",\"name\":\"Blog - Silicon Cloud\",\"description\":\"\",\"inLanguage\":\"ja\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/e52a686063ac76fd8cc6f539d41497ac\",\"name\":\"\u7d50\u8863, \u6625\u82b1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c74c6e2eb915a3c8e795b3934aa25a7333e0b38e7f1c7baf52785286ad51105e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c74c6e2eb915a3c8e795b3934aa25a7333e0b38e7f1c7baf52785286ad51105e?s=96&d=mm&r=g\",\"caption\":\"\u7d50\u8863, \u6625\u82b1\"},\"url\":\"https:\/\/www.silicloud.com\/ja\/blog\/author\/yuiharuka\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/setlocale%e9%96%a2%e6%95%b0%e3%81%ae%e4%bd%bf%e3%81%84%e6%96%b9%e3%81%af%e4%bd%95%e3%81%a7%e3%81%99%e3%81%8b%e3%80%82\/#local-main-organization-logo\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Blog - Silicon Cloud\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"setlocale\u95a2\u6570\u306e\u4f7f\u3044\u65b9\u306f\u4f55\u3067\u3059\u304b\u3002 - Blog - Silicon Cloud","description":"setlocale\u95a2\u6570\u306e\u4f7f\u3044\u65b9\u306f\u4f55\u3067\u3059\u304b\u3092\u5206\u304b\u308a\u3084\u3059\u304f\u89e3\u8aac\u3002\u5b9f\u8df5\u7684\u306a\u4f8b\u3068\u30b3\u30fc\u30c9\u3001\u6ce8\u610f\u70b9\u3092\u542b\u3081\u3066\u521d\u5fc3\u8005\u306b\u3082\u7406\u89e3\u3067\u304d\u308b\u3088\u3046\u8aac\u660e\u3057\u307e\u3059\u3002","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.silicloud.com\/ja\/blog\/setlocale\u95a2\u6570\u306e\u4f7f\u3044\u65b9\u306f\u4f55\u3067\u3059\u304b\u3002\/","og_locale":"ja_JP","og_type":"article","og_title":"setlocale\u95a2\u6570\u306e\u4f7f\u3044\u65b9\u306f\u4f55\u3067\u3059\u304b\u3002","og_description":"setlocale\u95a2\u6570\u306e\u4f7f\u3044\u65b9\u306f\u4f55\u3067\u3059\u304b\u3092\u5206\u304b\u308a\u3084\u3059\u304f\u89e3\u8aac\u3002\u5b9f\u8df5\u7684\u306a\u4f8b\u3068\u30b3\u30fc\u30c9\u3001\u6ce8\u610f\u70b9\u3092\u542b\u3081\u3066\u521d\u5fc3\u8005\u306b\u3082\u7406\u89e3\u3067\u304d\u308b\u3088\u3046\u8aac\u660e\u3057\u307e\u3059\u3002","og_url":"https:\/\/www.silicloud.com\/ja\/blog\/setlocale\u95a2\u6570\u306e\u4f7f\u3044\u65b9\u306f\u4f55\u3067\u3059\u304b\u3002\/","og_site_name":"Blog - Silicon Cloud","article_published_time":"2024-03-15T18:14:09+00:00","article_modified_time":"2025-08-05T20:40:17+00:00","author":"\u7d50\u8863, \u6625\u82b1","twitter_card":"summary_large_image","twitter_misc":{"\u57f7\u7b46\u8005":"\u7d50\u8863, \u6625\u82b1","\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593":"3\u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.silicloud.com\/ja\/blog\/setlocale%e9%96%a2%e6%95%b0%e3%81%ae%e4%bd%bf%e3%81%84%e6%96%b9%e3%81%af%e4%bd%95%e3%81%a7%e3%81%99%e3%81%8b%e3%80%82\/","url":"https:\/\/www.silicloud.com\/ja\/blog\/setlocale%e9%96%a2%e6%95%b0%e3%81%ae%e4%bd%bf%e3%81%84%e6%96%b9%e3%81%af%e4%bd%95%e3%81%a7%e3%81%99%e3%81%8b%e3%80%82\/","name":"setlocale\u95a2\u6570\u306e\u4f7f\u3044\u65b9\u306f\u4f55\u3067\u3059\u304b\u3002 - Blog - Silicon Cloud","isPartOf":{"@id":"https:\/\/www.silicloud.com\/ja\/blog\/#website"},"datePublished":"2024-03-15T18:14:09+00:00","dateModified":"2025-08-05T20:40:17+00:00","author":{"@id":"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/e52a686063ac76fd8cc6f539d41497ac"},"description":"setlocale\u95a2\u6570\u306e\u4f7f\u3044\u65b9\u306f\u4f55\u3067\u3059\u304b\u3092\u5206\u304b\u308a\u3084\u3059\u304f\u89e3\u8aac\u3002\u5b9f\u8df5\u7684\u306a\u4f8b\u3068\u30b3\u30fc\u30c9\u3001\u6ce8\u610f\u70b9\u3092\u542b\u3081\u3066\u521d\u5fc3\u8005\u306b\u3082\u7406\u89e3\u3067\u304d\u308b\u3088\u3046\u8aac\u660e\u3057\u307e\u3059\u3002","breadcrumb":{"@id":"https:\/\/www.silicloud.com\/ja\/blog\/setlocale%e9%96%a2%e6%95%b0%e3%81%ae%e4%bd%bf%e3%81%84%e6%96%b9%e3%81%af%e4%bd%95%e3%81%a7%e3%81%99%e3%81%8b%e3%80%82\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.silicloud.com\/ja\/blog\/setlocale%e9%96%a2%e6%95%b0%e3%81%ae%e4%bd%bf%e3%81%84%e6%96%b9%e3%81%af%e4%bd%95%e3%81%a7%e3%81%99%e3%81%8b%e3%80%82\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.silicloud.com\/ja\/blog\/setlocale%e9%96%a2%e6%95%b0%e3%81%ae%e4%bd%bf%e3%81%84%e6%96%b9%e3%81%af%e4%bd%95%e3%81%a7%e3%81%99%e3%81%8b%e3%80%82\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/www.silicloud.com\/ja\/blog\/"},{"@type":"ListItem","position":2,"name":"setlocale\u95a2\u6570\u306e\u4f7f\u3044\u65b9\u306f\u4f55\u3067\u3059\u304b\u3002"}]},{"@type":"WebSite","@id":"https:\/\/www.silicloud.com\/ja\/blog\/#website","url":"https:\/\/www.silicloud.com\/ja\/blog\/","name":"Blog - Silicon Cloud","description":"","inLanguage":"ja"},{"@type":"Person","@id":"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/e52a686063ac76fd8cc6f539d41497ac","name":"\u7d50\u8863, \u6625\u82b1","image":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c74c6e2eb915a3c8e795b3934aa25a7333e0b38e7f1c7baf52785286ad51105e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c74c6e2eb915a3c8e795b3934aa25a7333e0b38e7f1c7baf52785286ad51105e?s=96&d=mm&r=g","caption":"\u7d50\u8863, \u6625\u82b1"},"url":"https:\/\/www.silicloud.com\/ja\/blog\/author\/yuiharuka\/"},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.silicloud.com\/ja\/blog\/setlocale%e9%96%a2%e6%95%b0%e3%81%ae%e4%bd%bf%e3%81%84%e6%96%b9%e3%81%af%e4%bd%95%e3%81%a7%e3%81%99%e3%81%8b%e3%80%82\/#local-main-organization-logo","url":"","contentUrl":"","caption":"Blog - Silicon Cloud"}]}},"_links":{"self":[{"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/posts\/16109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/comments?post=16109"}],"version-history":[{"count":2,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/posts\/16109\/revisions"}],"predecessor-version":[{"id":91266,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/posts\/16109\/revisions\/91266"}],"wp:attachment":[{"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/media?parent=16109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/categories?post=16109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/tags?post=16109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}