{"id":124480,"date":"2024-03-24T15:24:52","date_gmt":"2024-03-24T06:24:52","guid":{"rendered":"https:\/\/www.silicloud.com\/ja\/blog\/spring-%e3%81%ae%e8%aa%ad%e3%81%bf%e8%be%bc%e3%81%bf%e6%96%b9%e6%b3%95\/"},"modified":"2024-04-05T15:50:37","modified_gmt":"2024-04-05T06:50:37","slug":"spring-%e3%81%ae%e8%aa%ad%e3%81%bf%e8%be%bc%e3%81%bf%e6%96%b9%e6%b3%95","status":"publish","type":"post","link":"https:\/\/www.silicloud.com\/ja\/blog\/spring-%e3%81%ae%e8%aa%ad%e3%81%bf%e8%be%bc%e3%81%bf%e6%96%b9%e6%b3%95\/","title":{"rendered":"Spring \u306e\u8aad\u307f\u8fbc\u307f\u65b9\u6cd5"},"content":{"rendered":"<p>Spring \u306e\u8aad\u307f\u8fbc\u307f\u65b9\u6cd5\u306b\u306f\u3001XML \u69cb\u6210\u3092\u4f7f\u3063\u305f\u8aad\u307f\u8fbc\u307f\u3001\u6ce8\u91c8\u3092\u4f7f\u3063\u305f\u8aad\u307f\u8fbc\u307f\u3001Java \u69cb\u6210\u3092\u4f7f\u3063\u305f\u8aad\u307f\u8fbc\u307f\u306e 3 \u7a2e\u985e\u304c\u3042\u308a\u307e\u3059\u3002<\/p>\n<ol>\n<li>XML\u30d9\u30fc\u30b9\u306e\u8a2d\u5b9a\u8aad\u307f\u8fbc\u307f\uff1aSpring\u30b3\u30f3\u30c6\u30ca\u3084Bean\u306b\u95a2\u3059\u308b\u60c5\u5831\u3092\u793a\u3059XML\u30d5\u30a1\u30a4\u30eb\u3092\u4f5c\u6210\u3057\u3001ClassPathXmlApplicationContext\u3084FileSystemXmlApplicationContext\u3068\u3044\u3063\u305f\u30af\u30e9\u30b9\u3092\u4f7f\u7528\u3057\u3066\u3001\u30b3\u30f3\u30d5\u30a3\u30b0\u30d5\u30a1\u30a4\u30eb\u3092\u8aad\u307f\u8fbc\u307f\u3001\u30b3\u30f3\u30c6\u30ca\u3092\u4f5c\u6210\u3057\u307e\u3059\u3002<\/li>\n<li>\u30a2\u30ce\u30c6\u30fc\u30b7\u30e7\u30f3\u30d9\u30fc\u30b9\u306e\u8a2d\u5b9a\u306e\u30ed\u30fc\u30c9\uff1aBean\u3084\u30b3\u30f3\u30c6\u30ca\u95a2\u9023\u60c5\u5831\u3092Java\u30af\u30e9\u30b9\u5185\u3067\u30a2\u30ce\u30c6\u30fc\u30b7\u30e7\u30f3\u3092\u4f7f\u7528\u3057\u3066\u8a2d\u5b9a\u3057\u3001@ComponentScan\u30a2\u30ce\u30c6\u30fc\u30b7\u30e7\u30f3\u3092\u4f7f\u7528\u3057\u3066\u7279\u5b9a\u306e\u30d1\u30c3\u30b1\u30fc\u30b8\u307e\u305f\u306f\u30af\u30e9\u30b9\u3092\u30b9\u30ad\u30e3\u30f3\u3057\u3001@Configuration\u30a2\u30ce\u30c6\u30fc\u30b7\u30e7\u30f3\u3092\u4f7f\u7528\u3057\u3066\u8a2d\u5b9a\u30af\u30e9\u30b9\u3092\u8b58\u5225\u3057\u307e\u3059\u3002<\/li>\n<li>Java\u306b\u3088\u308b\u8a2d\u5b9a\u306e\u8aad\u307f\u8fbc\u307f\uff1aSpring\u30b3\u30f3\u30c6\u30ca\u3001Bean\u306e\u60c5\u5831\u3092Java\u30af\u30e9\u30b9\u3067\u8a2d\u5b9a\u3059\u308b\u65b9\u6cd5\u3067\u3001\u30af\u30e9\u30b9\u306e\u8a2d\u5b9a\u3092\u793a\u3059@Configuration\u6ce8\u91c8\u3068\u3001\u6ce8\u91c8\u306e\u30af\u30e9\u30b9\u3067Bean\u3092\u4f5c\u6210\u3059\u308b@Bean\u6ce8\u91c8\u3092\u4f7f\u7528\u3057\u307e\u3059\u3002 \u8a2d\u5b9a\u306e\u30af\u30e9\u30b9\u306e\u8aad\u307f\u8fbc\u307f\u3001\u30b3\u30f3\u30c6\u30ca\u306e\u4f5c\u6210\u306b\u306f\u3001AnnotationConfigApplicationContext\u30af\u30e9\u30b9\u3092\u4f7f\u7528\u3057\u307e\u3059\u3002<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Spring \u306e\u8aad\u307f\u8fbc\u307f\u65b9\u6cd5\u306b\u306f\u3001XML \u69cb\u6210\u3092\u4f7f\u3063\u305f\u8aad\u307f\u8fbc\u307f\u3001\u6ce8\u91c8\u3092\u4f7f\u3063\u305f\u8aad\u307f\u8fbc\u307f\u3001Java \u69cb\u6210\u3092\u4f7f\u3063\u305f\u8aad\u307f\u8fbc\u307f\u306e 3 \u7a2e\u985e\u304c\u3042\u308a\u307e\u3059\u3002 XML\u30d9\u30fc\u30b9\u306e\u8a2d\u5b9a\u8aad\u307f\u8fbc\u307f\uff1aSpring\u30b3\u30f3\u30c6\u30ca\u3084Bean\u306b\u95a2\u3059\u308b\u60c5\u5831\u3092\u793a\u3059X [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-124480","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v21.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Spring \u306e\u8aad\u307f\u8fbc\u307f\u65b9\u6cd5 - Blog - Silicon Cloud<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.silicloud.com\/ja\/blog\/spring-\u306e\u8aad\u307f\u8fbc\u307f\u65b9\u6cd5\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spring \u306e\u8aad\u307f\u8fbc\u307f\u65b9\u6cd5\" \/>\n<meta property=\"og:description\" content=\"Spring \u306e\u8aad\u307f\u8fbc\u307f\u65b9\u6cd5\u306b\u306f\u3001XML \u69cb\u6210\u3092\u4f7f\u3063\u305f\u8aad\u307f\u8fbc\u307f\u3001\u6ce8\u91c8\u3092\u4f7f\u3063\u305f\u8aad\u307f\u8fbc\u307f\u3001Java \u69cb\u6210\u3092\u4f7f\u3063\u305f\u8aad\u307f\u8fbc\u307f\u306e 3 \u7a2e\u985e\u304c\u3042\u308a\u307e\u3059\u3002 XML\u30d9\u30fc\u30b9\u306e\u8a2d\u5b9a\u8aad\u307f\u8fbc\u307f\uff1aSpring\u30b3\u30f3\u30c6\u30ca\u3084Bean\u306b\u95a2\u3059\u308b\u60c5\u5831\u3092\u793a\u3059X [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.silicloud.com\/ja\/blog\/spring-\u306e\u8aad\u307f\u8fbc\u307f\u65b9\u6cd5\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog - Silicon Cloud\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-24T06:24:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-05T06:50:37+00:00\" \/>\n<meta name=\"author\" content=\"\u7d50\u8863, \u6625\u82b1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u57f7\u7b46\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u7d50\u8863, \u6625\u82b1\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/spring-%e3%81%ae%e8%aa%ad%e3%81%bf%e8%be%bc%e3%81%bf%e6%96%b9%e6%b3%95\/\",\"url\":\"https:\/\/www.silicloud.com\/ja\/blog\/spring-%e3%81%ae%e8%aa%ad%e3%81%bf%e8%be%bc%e3%81%bf%e6%96%b9%e6%b3%95\/\",\"name\":\"Spring \u306e\u8aad\u307f\u8fbc\u307f\u65b9\u6cd5 - Blog - Silicon Cloud\",\"isPartOf\":{\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#website\"},\"datePublished\":\"2024-03-24T06:24:52+00:00\",\"dateModified\":\"2024-04-05T06:50:37+00:00\",\"author\":{\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/e52a686063ac76fd8cc6f539d41497ac\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/spring-%e3%81%ae%e8%aa%ad%e3%81%bf%e8%be%bc%e3%81%bf%e6%96%b9%e6%b3%95\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.silicloud.com\/ja\/blog\/spring-%e3%81%ae%e8%aa%ad%e3%81%bf%e8%be%bc%e3%81%bf%e6%96%b9%e6%b3%95\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/spring-%e3%81%ae%e8%aa%ad%e3%81%bf%e8%be%bc%e3%81%bf%e6%96%b9%e6%b3%95\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9875\",\"item\":\"https:\/\/www.silicloud.com\/ja\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spring \u306e\u8aad\u307f\u8fbc\u307f\u65b9\u6cd5\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#website\",\"url\":\"https:\/\/www.silicloud.com\/ja\/blog\/\",\"name\":\"Blog - Silicon Cloud\",\"description\":\"\",\"inLanguage\":\"ja\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/e52a686063ac76fd8cc6f539d41497ac\",\"name\":\"\u7d50\u8863, \u6625\u82b1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c74c6e2eb915a3c8e795b3934aa25a7333e0b38e7f1c7baf52785286ad51105e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c74c6e2eb915a3c8e795b3934aa25a7333e0b38e7f1c7baf52785286ad51105e?s=96&d=mm&r=g\",\"caption\":\"\u7d50\u8863, \u6625\u82b1\"},\"url\":\"https:\/\/www.silicloud.com\/ja\/blog\/author\/yuiharuka\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/spring-%e3%81%ae%e8%aa%ad%e3%81%bf%e8%be%bc%e3%81%bf%e6%96%b9%e6%b3%95\/#local-main-organization-logo\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Blog - Silicon Cloud\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Spring \u306e\u8aad\u307f\u8fbc\u307f\u65b9\u6cd5 - Blog - Silicon Cloud","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.silicloud.com\/ja\/blog\/spring-\u306e\u8aad\u307f\u8fbc\u307f\u65b9\u6cd5\/","og_locale":"ja_JP","og_type":"article","og_title":"Spring \u306e\u8aad\u307f\u8fbc\u307f\u65b9\u6cd5","og_description":"Spring \u306e\u8aad\u307f\u8fbc\u307f\u65b9\u6cd5\u306b\u306f\u3001XML \u69cb\u6210\u3092\u4f7f\u3063\u305f\u8aad\u307f\u8fbc\u307f\u3001\u6ce8\u91c8\u3092\u4f7f\u3063\u305f\u8aad\u307f\u8fbc\u307f\u3001Java \u69cb\u6210\u3092\u4f7f\u3063\u305f\u8aad\u307f\u8fbc\u307f\u306e 3 \u7a2e\u985e\u304c\u3042\u308a\u307e\u3059\u3002 XML\u30d9\u30fc\u30b9\u306e\u8a2d\u5b9a\u8aad\u307f\u8fbc\u307f\uff1aSpring\u30b3\u30f3\u30c6\u30ca\u3084Bean\u306b\u95a2\u3059\u308b\u60c5\u5831\u3092\u793a\u3059X [&hellip;]","og_url":"https:\/\/www.silicloud.com\/ja\/blog\/spring-\u306e\u8aad\u307f\u8fbc\u307f\u65b9\u6cd5\/","og_site_name":"Blog - Silicon Cloud","article_published_time":"2024-03-24T06:24:52+00:00","article_modified_time":"2024-04-05T06:50:37+00:00","author":"\u7d50\u8863, \u6625\u82b1","twitter_card":"summary_large_image","twitter_misc":{"\u57f7\u7b46\u8005":"\u7d50\u8863, \u6625\u82b1"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.silicloud.com\/ja\/blog\/spring-%e3%81%ae%e8%aa%ad%e3%81%bf%e8%be%bc%e3%81%bf%e6%96%b9%e6%b3%95\/","url":"https:\/\/www.silicloud.com\/ja\/blog\/spring-%e3%81%ae%e8%aa%ad%e3%81%bf%e8%be%bc%e3%81%bf%e6%96%b9%e6%b3%95\/","name":"Spring \u306e\u8aad\u307f\u8fbc\u307f\u65b9\u6cd5 - Blog - Silicon Cloud","isPartOf":{"@id":"https:\/\/www.silicloud.com\/ja\/blog\/#website"},"datePublished":"2024-03-24T06:24:52+00:00","dateModified":"2024-04-05T06:50:37+00:00","author":{"@id":"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/e52a686063ac76fd8cc6f539d41497ac"},"breadcrumb":{"@id":"https:\/\/www.silicloud.com\/ja\/blog\/spring-%e3%81%ae%e8%aa%ad%e3%81%bf%e8%be%bc%e3%81%bf%e6%96%b9%e6%b3%95\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.silicloud.com\/ja\/blog\/spring-%e3%81%ae%e8%aa%ad%e3%81%bf%e8%be%bc%e3%81%bf%e6%96%b9%e6%b3%95\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.silicloud.com\/ja\/blog\/spring-%e3%81%ae%e8%aa%ad%e3%81%bf%e8%be%bc%e3%81%bf%e6%96%b9%e6%b3%95\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/www.silicloud.com\/ja\/blog\/"},{"@type":"ListItem","position":2,"name":"Spring \u306e\u8aad\u307f\u8fbc\u307f\u65b9\u6cd5"}]},{"@type":"WebSite","@id":"https:\/\/www.silicloud.com\/ja\/blog\/#website","url":"https:\/\/www.silicloud.com\/ja\/blog\/","name":"Blog - Silicon Cloud","description":"","inLanguage":"ja"},{"@type":"Person","@id":"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/e52a686063ac76fd8cc6f539d41497ac","name":"\u7d50\u8863, \u6625\u82b1","image":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c74c6e2eb915a3c8e795b3934aa25a7333e0b38e7f1c7baf52785286ad51105e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c74c6e2eb915a3c8e795b3934aa25a7333e0b38e7f1c7baf52785286ad51105e?s=96&d=mm&r=g","caption":"\u7d50\u8863, \u6625\u82b1"},"url":"https:\/\/www.silicloud.com\/ja\/blog\/author\/yuiharuka\/"},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.silicloud.com\/ja\/blog\/spring-%e3%81%ae%e8%aa%ad%e3%81%bf%e8%be%bc%e3%81%bf%e6%96%b9%e6%b3%95\/#local-main-organization-logo","url":"","contentUrl":"","caption":"Blog - Silicon Cloud"}]}},"_links":{"self":[{"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/posts\/124480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/comments?post=124480"}],"version-history":[{"count":2,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/posts\/124480\/revisions"}],"predecessor-version":[{"id":321831,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/posts\/124480\/revisions\/321831"}],"wp:attachment":[{"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/media?parent=124480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/categories?post=124480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/tags?post=124480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}