{"id":123456,"date":"2024-03-24T11:22:29","date_gmt":"2024-03-24T02:22:29","guid":{"rendered":"https:\/\/www.silicloud.com\/ja\/blog\/go%e8%a8%80%e8%aa%9e%e3%81%ab%e3%82%88%e3%82%8b%e9%9d%9e%e5%90%8c%e6%9c%9f%e5%87%a6%e7%90%86%e6%96%b9%e6%b3%95\/"},"modified":"2024-04-05T06:29:53","modified_gmt":"2024-04-04T21:29:53","slug":"go%e8%a8%80%e8%aa%9e%e3%81%ab%e3%82%88%e3%82%8b%e9%9d%9e%e5%90%8c%e6%9c%9f%e5%87%a6%e7%90%86%e6%96%b9%e6%b3%95","status":"publish","type":"post","link":"https:\/\/www.silicloud.com\/ja\/blog\/go%e8%a8%80%e8%aa%9e%e3%81%ab%e3%82%88%e3%82%8b%e9%9d%9e%e5%90%8c%e6%9c%9f%e5%87%a6%e7%90%86%e6%96%b9%e6%b3%95\/","title":{"rendered":"Go\u8a00\u8a9e\u306b\u3088\u308b\u975e\u540c\u671f\u51e6\u7406\u65b9\u6cd5"},"content":{"rendered":"<p>Go\u8a00\u8a9e\u3067\u306f\u3001\u30c1\u30e3\u30cd\u30eb\u306e\u975e\u540c\u671f\u64cd\u4f5c\u3092\u51e6\u7406\u3059\u308b\u305f\u3081\u306bselect\u6587\u3092\u4f7f\u7528\u3067\u304d\u307e\u3059\u3002select\u6587\u306f\u3001\u8907\u6570\u306e\u30c1\u30e3\u30cd\u30eb\u306e\u64cd\u4f5c\u3092\u540c\u6642\u306b\u76e3\u8996\u3057\u3001\u3044\u305a\u308c\u304b\u306e\u30c1\u30e3\u30cd\u30eb\u306e\u6e96\u5099\u304c\u6574\u3044\u6b21\u7b2c\u3001\u5bfe\u5fdc\u3059\u308b\u64cd\u4f5c\u3092\u5b9f\u884c\u3057\u307e\u3059\u3002<\/p>\n<p>\u4ee5\u4e0b\u306b\u3001\u975e\u540c\u671f\u51e6\u7406\u3092\u884c\u3046Select\u6587\u306e\u4f8b\u3092\u793a\u3057\u307e\u3059\u3002<\/p>\n<pre class=\"post-pre\"><code><span class=\"hljs-keyword\">package<\/span> main\r\n<span class=\"hljs-keyword\">import<\/span> (\r\n<span class=\"hljs-string\">\"fmt\"<\/span>\r\n<span class=\"hljs-string\">\"time\"<\/span>\r\n)\r\n<span class=\"hljs-function\"><span class=\"hljs-keyword\">func<\/span> <span class=\"hljs-title\">main<\/span><span class=\"hljs-params\">()<\/span><\/span> {\r\nch1 := <span class=\"hljs-built_in\">make<\/span>(<span class=\"hljs-keyword\">chan<\/span> <span class=\"hljs-type\">string<\/span>)\r\nch2 := <span class=\"hljs-built_in\">make<\/span>(<span class=\"hljs-keyword\">chan<\/span> <span class=\"hljs-type\">string<\/span>)\r\n<span class=\"hljs-keyword\">go<\/span> <span class=\"hljs-function\"><span class=\"hljs-keyword\">func<\/span><span class=\"hljs-params\">()<\/span><\/span> {\r\ntime.Sleep(<span class=\"hljs-number\">2<\/span> * time.Second)\r\nch1 &lt;- <span class=\"hljs-string\">\"Hello\"<\/span>\r\n}()\r\n<span class=\"hljs-keyword\">go<\/span> <span class=\"hljs-function\"><span class=\"hljs-keyword\">func<\/span><span class=\"hljs-params\">()<\/span><\/span> {\r\ntime.Sleep(<span class=\"hljs-number\">1<\/span> * time.Second)\r\nch2 &lt;- <span class=\"hljs-string\">\"World\"<\/span>\r\n}()\r\n<span class=\"hljs-keyword\">select<\/span> {\r\n<span class=\"hljs-keyword\">case<\/span> msg1 := &lt;-ch1:\r\nfmt.Println(msg1)\r\n<span class=\"hljs-keyword\">case<\/span> msg2 := &lt;-ch2:\r\nfmt.Println(msg2)\r\n}\r\n}\r\n<\/code><\/pre>\n<p>\u4e0a\u306e\u4f8b\u3067\u306f\u30012\u3064\u306e\u30c1\u30e3\u30f3\u30cd\u30ebch1\u3068ch2\u3092\u4f5c\u6210\u3057\u30012\u3064\u306egoroutine\u3092\u4f7f\u7528\u3057\u3066\u305d\u308c\u305e\u308c\u306e\u30c1\u30e3\u30f3\u30cd\u30eb\u306b\u30e1\u30c3\u30bb\u30fc\u30b8\u3092\u9001\u4fe1\u3057\u307e\u3059\u3002 select\u6587\u3092\u4f7f\u7528\u3057\u30662\u3064\u306e\u30c1\u30e3\u30f3\u30cd\u30eb\u3092\u76e3\u8996\u3057\u3001\u3069\u3061\u3089\u304b\u306e\u30c1\u30e3\u30f3\u30cd\u30eb\u304c\u6e96\u5099\u3067\u304d\u305f\u3089\u3001\u5bfe\u5fdc\u3059\u308b\u64cd\u4f5c\u3092\u5b9f\u884c\u3057\u307e\u3059\u3002<\/p>\n<p>time.Sleep\u3092\u4f7f\u3063\u3066\u51e6\u7406\u306e\u9045\u5ef6\u3092\u30b7\u30df\u30e5\u30ec\u30fc\u30c8\u3057\u3066\u3044\u307e\u3059\u3002ch2\u306e\u30e1\u30c3\u30bb\u30fc\u30b8\u304c\u5148\u306b\u6e96\u5099\u3067\u304d\u305f\u3089\u300cWorld\u300d\u3068\u30d7\u30ea\u30f3\u30c8\u3055\u308c\u3001ch1\u306e\u30e1\u30c3\u30bb\u30fc\u30b8\u304c\u5148\u306b\u6e96\u5099\u3067\u304d\u305f\u3089\u300cHello\u300d\u3068\u30d7\u30ea\u30f3\u30c8\u3055\u308c\u307e\u3059\u3002<\/p>\n<p>select\u6587\u306f\u30b1\u30fc\u30b9\u5206\u5c90\u306e\u3046\u3061\u4e00\u3064\u3060\u3051\u3092\u5b9f\u884c\u3059\u308b\u3053\u3068\u306b\u6ce8\u610f\u3057\u3066\u304f\u3060\u3055\u3044\u3002\u8907\u6570\u30c1\u30e3\u30cd\u30eb\u304c\u540c\u6642\u306b\u6e96\u5099\u5b8c\u4e86\u3059\u308b\u3068\u3001\u30e9\u30f3\u30c0\u30e0\u306b\u4e00\u3064\u5206\u5c90\u3092\u9078\u629e\u3057\u3066\u5b9f\u884c\u3055\u308c\u307e\u3059\u3002\u3069\u306e\u30c1\u30e3\u30cd\u30eb\u3082\u6e96\u5099\u5b8c\u4e86\u3067\u306a\u3044\u5834\u5408\u3001select\u6587\u306f\u30c1\u30e3\u30cd\u30eb\u304c\u6e96\u5099\u5b8c\u4e86\u3059\u308b\u307e\u3067\u30d6\u30ed\u30c3\u30af\u3057\u3066\u5f85\u6a5f\u3057\u307e\u3059\u3002<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Go\u8a00\u8a9e\u3067\u306f\u3001\u30c1\u30e3\u30cd\u30eb\u306e\u975e\u540c\u671f\u64cd\u4f5c\u3092\u51e6\u7406\u3059\u308b\u305f\u3081\u306bselect\u6587\u3092\u4f7f\u7528\u3067\u304d\u307e\u3059\u3002select\u6587\u306f\u3001\u8907\u6570\u306e\u30c1\u30e3\u30cd\u30eb\u306e\u64cd\u4f5c\u3092\u540c\u6642\u306b\u76e3\u8996\u3057\u3001\u3044\u305a\u308c\u304b\u306e\u30c1\u30e3\u30cd\u30eb\u306e\u6e96\u5099\u304c\u6574\u3044\u6b21\u7b2c\u3001\u5bfe\u5fdc\u3059\u308b\u64cd\u4f5c\u3092\u5b9f\u884c\u3057\u307e\u3059\u3002 \u4ee5\u4e0b\u306b\u3001\u975e\u540c\u671f\u51e6\u7406\u3092\u884c [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-123456","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v21.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Go\u8a00\u8a9e\u306b\u3088\u308b\u975e\u540c\u671f\u51e6\u7406\u65b9\u6cd5 - Blog - Silicon Cloud<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.silicloud.com\/ja\/blog\/go\u8a00\u8a9e\u306b\u3088\u308b\u975e\u540c\u671f\u51e6\u7406\u65b9\u6cd5\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Go\u8a00\u8a9e\u306b\u3088\u308b\u975e\u540c\u671f\u51e6\u7406\u65b9\u6cd5\" \/>\n<meta property=\"og:description\" content=\"Go\u8a00\u8a9e\u3067\u306f\u3001\u30c1\u30e3\u30cd\u30eb\u306e\u975e\u540c\u671f\u64cd\u4f5c\u3092\u51e6\u7406\u3059\u308b\u305f\u3081\u306bselect\u6587\u3092\u4f7f\u7528\u3067\u304d\u307e\u3059\u3002select\u6587\u306f\u3001\u8907\u6570\u306e\u30c1\u30e3\u30cd\u30eb\u306e\u64cd\u4f5c\u3092\u540c\u6642\u306b\u76e3\u8996\u3057\u3001\u3044\u305a\u308c\u304b\u306e\u30c1\u30e3\u30cd\u30eb\u306e\u6e96\u5099\u304c\u6574\u3044\u6b21\u7b2c\u3001\u5bfe\u5fdc\u3059\u308b\u64cd\u4f5c\u3092\u5b9f\u884c\u3057\u307e\u3059\u3002 \u4ee5\u4e0b\u306b\u3001\u975e\u540c\u671f\u51e6\u7406\u3092\u884c [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.silicloud.com\/ja\/blog\/go\u8a00\u8a9e\u306b\u3088\u308b\u975e\u540c\u671f\u51e6\u7406\u65b9\u6cd5\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog - Silicon Cloud\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-24T02:22:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-04T21:29:53+00:00\" \/>\n<meta name=\"author\" content=\"\u967d, \u5411\u5b87\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u57f7\u7b46\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u967d, \u5411\u5b87\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/go%e8%a8%80%e8%aa%9e%e3%81%ab%e3%82%88%e3%82%8b%e9%9d%9e%e5%90%8c%e6%9c%9f%e5%87%a6%e7%90%86%e6%96%b9%e6%b3%95\/\",\"url\":\"https:\/\/www.silicloud.com\/ja\/blog\/go%e8%a8%80%e8%aa%9e%e3%81%ab%e3%82%88%e3%82%8b%e9%9d%9e%e5%90%8c%e6%9c%9f%e5%87%a6%e7%90%86%e6%96%b9%e6%b3%95\/\",\"name\":\"Go\u8a00\u8a9e\u306b\u3088\u308b\u975e\u540c\u671f\u51e6\u7406\u65b9\u6cd5 - Blog - Silicon Cloud\",\"isPartOf\":{\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#website\"},\"datePublished\":\"2024-03-24T02:22:29+00:00\",\"dateModified\":\"2024-04-04T21:29:53+00:00\",\"author\":{\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/4aef6196128551a0f5d66db46c42866c\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/go%e8%a8%80%e8%aa%9e%e3%81%ab%e3%82%88%e3%82%8b%e9%9d%9e%e5%90%8c%e6%9c%9f%e5%87%a6%e7%90%86%e6%96%b9%e6%b3%95\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.silicloud.com\/ja\/blog\/go%e8%a8%80%e8%aa%9e%e3%81%ab%e3%82%88%e3%82%8b%e9%9d%9e%e5%90%8c%e6%9c%9f%e5%87%a6%e7%90%86%e6%96%b9%e6%b3%95\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/go%e8%a8%80%e8%aa%9e%e3%81%ab%e3%82%88%e3%82%8b%e9%9d%9e%e5%90%8c%e6%9c%9f%e5%87%a6%e7%90%86%e6%96%b9%e6%b3%95\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9875\",\"item\":\"https:\/\/www.silicloud.com\/ja\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Go\u8a00\u8a9e\u306b\u3088\u308b\u975e\u540c\u671f\u51e6\u7406\u65b9\u6cd5\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#website\",\"url\":\"https:\/\/www.silicloud.com\/ja\/blog\/\",\"name\":\"Blog - Silicon Cloud\",\"description\":\"\",\"inLanguage\":\"ja\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/4aef6196128551a0f5d66db46c42866c\",\"name\":\"\u967d, \u5411\u5b87\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ad96b120e219751fa368cbd7d2c48ca01b59185e6ed394449bac72614a760bf3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ad96b120e219751fa368cbd7d2c48ca01b59185e6ed394449bac72614a760bf3?s=96&d=mm&r=g\",\"caption\":\"\u967d, \u5411\u5b87\"},\"url\":\"https:\/\/www.silicloud.com\/ja\/blog\/author\/hinatasora\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/www.silicloud.com\/ja\/blog\/go%e8%a8%80%e8%aa%9e%e3%81%ab%e3%82%88%e3%82%8b%e9%9d%9e%e5%90%8c%e6%9c%9f%e5%87%a6%e7%90%86%e6%96%b9%e6%b3%95\/#local-main-organization-logo\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Blog - Silicon Cloud\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Go\u8a00\u8a9e\u306b\u3088\u308b\u975e\u540c\u671f\u51e6\u7406\u65b9\u6cd5 - Blog - Silicon Cloud","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.silicloud.com\/ja\/blog\/go\u8a00\u8a9e\u306b\u3088\u308b\u975e\u540c\u671f\u51e6\u7406\u65b9\u6cd5\/","og_locale":"ja_JP","og_type":"article","og_title":"Go\u8a00\u8a9e\u306b\u3088\u308b\u975e\u540c\u671f\u51e6\u7406\u65b9\u6cd5","og_description":"Go\u8a00\u8a9e\u3067\u306f\u3001\u30c1\u30e3\u30cd\u30eb\u306e\u975e\u540c\u671f\u64cd\u4f5c\u3092\u51e6\u7406\u3059\u308b\u305f\u3081\u306bselect\u6587\u3092\u4f7f\u7528\u3067\u304d\u307e\u3059\u3002select\u6587\u306f\u3001\u8907\u6570\u306e\u30c1\u30e3\u30cd\u30eb\u306e\u64cd\u4f5c\u3092\u540c\u6642\u306b\u76e3\u8996\u3057\u3001\u3044\u305a\u308c\u304b\u306e\u30c1\u30e3\u30cd\u30eb\u306e\u6e96\u5099\u304c\u6574\u3044\u6b21\u7b2c\u3001\u5bfe\u5fdc\u3059\u308b\u64cd\u4f5c\u3092\u5b9f\u884c\u3057\u307e\u3059\u3002 \u4ee5\u4e0b\u306b\u3001\u975e\u540c\u671f\u51e6\u7406\u3092\u884c [&hellip;]","og_url":"https:\/\/www.silicloud.com\/ja\/blog\/go\u8a00\u8a9e\u306b\u3088\u308b\u975e\u540c\u671f\u51e6\u7406\u65b9\u6cd5\/","og_site_name":"Blog - Silicon Cloud","article_published_time":"2024-03-24T02:22:29+00:00","article_modified_time":"2024-04-04T21:29:53+00:00","author":"\u967d, \u5411\u5b87","twitter_card":"summary_large_image","twitter_misc":{"\u57f7\u7b46\u8005":"\u967d, \u5411\u5b87"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.silicloud.com\/ja\/blog\/go%e8%a8%80%e8%aa%9e%e3%81%ab%e3%82%88%e3%82%8b%e9%9d%9e%e5%90%8c%e6%9c%9f%e5%87%a6%e7%90%86%e6%96%b9%e6%b3%95\/","url":"https:\/\/www.silicloud.com\/ja\/blog\/go%e8%a8%80%e8%aa%9e%e3%81%ab%e3%82%88%e3%82%8b%e9%9d%9e%e5%90%8c%e6%9c%9f%e5%87%a6%e7%90%86%e6%96%b9%e6%b3%95\/","name":"Go\u8a00\u8a9e\u306b\u3088\u308b\u975e\u540c\u671f\u51e6\u7406\u65b9\u6cd5 - Blog - Silicon Cloud","isPartOf":{"@id":"https:\/\/www.silicloud.com\/ja\/blog\/#website"},"datePublished":"2024-03-24T02:22:29+00:00","dateModified":"2024-04-04T21:29:53+00:00","author":{"@id":"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/4aef6196128551a0f5d66db46c42866c"},"breadcrumb":{"@id":"https:\/\/www.silicloud.com\/ja\/blog\/go%e8%a8%80%e8%aa%9e%e3%81%ab%e3%82%88%e3%82%8b%e9%9d%9e%e5%90%8c%e6%9c%9f%e5%87%a6%e7%90%86%e6%96%b9%e6%b3%95\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.silicloud.com\/ja\/blog\/go%e8%a8%80%e8%aa%9e%e3%81%ab%e3%82%88%e3%82%8b%e9%9d%9e%e5%90%8c%e6%9c%9f%e5%87%a6%e7%90%86%e6%96%b9%e6%b3%95\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.silicloud.com\/ja\/blog\/go%e8%a8%80%e8%aa%9e%e3%81%ab%e3%82%88%e3%82%8b%e9%9d%9e%e5%90%8c%e6%9c%9f%e5%87%a6%e7%90%86%e6%96%b9%e6%b3%95\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/www.silicloud.com\/ja\/blog\/"},{"@type":"ListItem","position":2,"name":"Go\u8a00\u8a9e\u306b\u3088\u308b\u975e\u540c\u671f\u51e6\u7406\u65b9\u6cd5"}]},{"@type":"WebSite","@id":"https:\/\/www.silicloud.com\/ja\/blog\/#website","url":"https:\/\/www.silicloud.com\/ja\/blog\/","name":"Blog - Silicon Cloud","description":"","inLanguage":"ja"},{"@type":"Person","@id":"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/4aef6196128551a0f5d66db46c42866c","name":"\u967d, \u5411\u5b87","image":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.silicloud.com\/ja\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ad96b120e219751fa368cbd7d2c48ca01b59185e6ed394449bac72614a760bf3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad96b120e219751fa368cbd7d2c48ca01b59185e6ed394449bac72614a760bf3?s=96&d=mm&r=g","caption":"\u967d, \u5411\u5b87"},"url":"https:\/\/www.silicloud.com\/ja\/blog\/author\/hinatasora\/"},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.silicloud.com\/ja\/blog\/go%e8%a8%80%e8%aa%9e%e3%81%ab%e3%82%88%e3%82%8b%e9%9d%9e%e5%90%8c%e6%9c%9f%e5%87%a6%e7%90%86%e6%96%b9%e6%b3%95\/#local-main-organization-logo","url":"","contentUrl":"","caption":"Blog - Silicon Cloud"}]}},"_links":{"self":[{"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/posts\/123456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/comments?post=123456"}],"version-history":[{"count":2,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/posts\/123456\/revisions"}],"predecessor-version":[{"id":312614,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/posts\/123456\/revisions\/312614"}],"wp:attachment":[{"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/media?parent=123456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/categories?post=123456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.silicloud.com\/ja\/blog\/wp-json\/wp\/v2\/tags?post=123456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}